{"id":36665,"date":"2021-10-29T20:56:59","date_gmt":"2021-10-29T18:56:59","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/smart-pool"},"modified":"2026-02-02T14:08:00","modified_gmt":"2026-02-02T13:08:00","slug":"smart-pool","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/ae-en\/smart-pool","title":{"rendered":"Smart pool: easy\u00b7care by Waterair"},"content":{"rendered":"<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column-reverse \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Innovations only make sense if they&#8217;re designed to serve their users, so Waterair Swimming Pools wanted to continue its commitment to its customers by simplifying pool maintenance.<\/p>\n<p>Easy\u00b7care by Waterair is a personalised pool assistant designed to do just that in a very pragmatic way.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"piscine connect\u00e9e\" data-align=\"left\" data-entity-type=\"file\" data-entity-uuid=\"168c18e3-71a7-4de7-9f0f-8c510ae2370a\" height=\"157\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/Trophee-argent-2019-contour-540x540.png\" width=\"157\" \/><\/p>\n<p class=\"notice\">* Trophy awarded by the Federation of Swimming Pool Professionals in the &#8216;Innovations and Equipment&#8217; category.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-12 order-lg-1  \">\n                                <div class=\"content-block__media is-left video-media \">\n                                                                            <button class=\"content-block__button\" data-video='{\"provider\": \"vimeo\", \"id\": \"480665683\", \"poster\": \"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-easycare-1340x1260.png\"}'>\n                                            Watch the video                                            <i class=\"app-icon app-icon-play-fill app-icon--sm\"><\/i>\n                                        <\/button>\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1340\" height=\"1260\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-easycare-1340x1260.png\" class=\"attachment-card_large_2x size-card_large_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-easycare-1340x1260.png 1340w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-easycare-670x630.png 670w\" sizes=\"auto, (max-width: 1340px) 100vw, 1340px\" \/>                                                                                    <\/span>\n                                                                                                                <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                            <title><\/title>\n                                            <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                            <!--<image-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tx=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\ty=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\twidth=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\theight=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\txlink:href=\"--><? \/\/= $media['image']['sizes']['card_large_2x'] \n                                                                                                        ?>\n                                            <!--\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tclip-path=\"url(#content-block__mask---><? \/\/= $blockId \n                                                                                                                                ?>\n                                            <!--)\"-->\n                                            <!--\t\t\t\t\t\t\t\t\/>-->\n                                            <!--\t\t\t\t\t\t\t\t<clipPath id=\"content-block__mask---><? \/\/= $blockId \n                                                                                                                        ?>\n                                            <!--\" class=\"content-block__mask\">-->\n                                            <!--\t\t\t\t\t\t\t\t\t<path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>-->\n                                            <!--\t\t\t\t\t\t\t\t<\/clipPath>-->\n\n                                        <\/svg>\n                                    \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Easy\u00b7care by Waterair: the personalised assistant<\/h2>\n<p>Easy\u00b7care by Waterair is the next step in Waterair Swimming Pools&#8217; 30-year-long commitment to simplifying maintenance.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>It all began in 1990 with the launch of the Easy range, and in particular, the Easy pool, which, thanks to its all-in-one formula, made it possible to limit pool maintenance to a once-a-fortnight treatment.<br \/>\nSimple and effective, its precise dosage saved significant time.<\/p>\n<p>Today, with home automation becoming increasingly common, we needed to come up with a concept that would combine simplicity and automation. The result was easy\u00b7care!<\/p>\n<p><strong>But what is easy\u00b7care?<\/strong><br \/>\nA range of equipment forming an ecosystem that provides personalised assistance. And since this is about your pool, easy\u00b7care will help you monitor the parameters of your water and, where necessary, will give you advice on maintenance requirements.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"495\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-880x495.png\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-880x495.png 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-1440x810.png 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-768x432.png 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-1536x864.png 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-1360x765.png 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-440x248.png 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-1840x1035.png 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo-920x518.png 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easycare-logo.png 1920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>So, how does easy\u00b7care by Waterair work?<\/h2>\n<p><strong>A Waterair modem<\/strong>, linked directly to your home hub, will provide the gateway to a smart world. It will receive information and transmit it to the network. It will then make all these data reports available on your smartphone.<\/p>\n<p><strong>A smart pool control unit<\/strong><span>, directly linked to your pool&#8217;s electrical box, will enable you to manage peripheral equipment<\/span> Coupled with a<strong> pressure sensor<\/strong> that you install on your filtration (optional), it notifies you in the event of an anomaly (water level too low, clogging of the filter, etc.). It also tells you what remedial action you need to take. You can thus preserve your installation and prolong its life.<\/p>\n<p><em>The modem, monitor and smart control unit communicate via the <em>LoRa<\/em> protocol. Better adapted than Bluetooth\u00ae and Wi-Fi, this technology functions everywhere in France.<\/em><\/p>\n<p><strong>A smart monitor<\/strong> floating on the surface of the pool will report your water parameters (temperature, pH, chlorine level). You will be able to consult this data on your smartphone, no matter where you are, using a <strong>mobile application<\/strong>.<\/p>\n<p><em>The modem and smart monitor communicate via the <em>LoRa<\/em> protocol. Better adapted than Bluetooth\u00ae and Wi-Fi, this technology functions everywhere in France.<\/em><\/p>\n<p>In the event of an alert, you will receive a notification from the dedicated mobile application. This personal assistant will then prescribe the correct adjustment to be made, taking into account the volume of your pool, the filtration system and your type of pool cover. So, you will know what product to add and in what quantity to restore the water to a healthy and clear state.<\/p>\n<p><strong>The bonuses?<\/strong> You can order your treatment products online in just a few clicks!<br \/>\nEventually, other smart equipment will be added to the easy\u00b7care range. With the same ultimate objective: to help make life easier for our customers.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">The AC1 smart monitor<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Continuous measurement and analysis of your water data<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-1.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-1.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-1-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">The water parameters are automatically sent to your smartphone<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Notifications inform you of actions to take<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-2.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-2.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-2-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Take corrective action<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>as suggested by the app<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-3.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-3.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-3-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">The bonuses<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Possibility of ordering products via the app<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-4.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-4.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-4-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Smart pool control unit<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Monitor the pool<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-5.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-5.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-5-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Monitor the control unit and automate your filtration<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Via the app on your smartphone<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-6.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-6.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-6-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Remotely control your pool lighting<\/h2>\n                                                                                                                                                                            <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"480\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-7.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-7.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/easy-care-7-440x275.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Easy\u00b7care equipment details<\/h2>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/ae-en\/pools-and-equipment\/equipment\/pool-cleaning-and-maintenance\/waterair-modem\" class=\"item-card is-size-card splide__slide \">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Waterair modem<\/h3>\n\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Box easy care waterair \u00e0 brancher \u00e0 la box internet\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/box-waterair-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/ae-en\/pools-and-equipment\/equipment\/pool-cleaning-and-maintenance\/ac1-smart-monitor\" class=\"item-card is-size-card splide__slide \">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">AC1 smart monitor<\/h3>\n\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Analyseur connect\u00e9 AC1 easy care de Piscines Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/analyseur-connecte-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/ae-en\/pools-and-equipment\/equipment\/pool-cleaning-and-maintenance\/easy-care-app-by-waterair\" class=\"item-card is-size-card splide__slide \">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Easy\u00b7care app by Waterair<\/h3>\n\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Utilisation de l\u2019application easy care waterair pour relever les param\u00e8tres de l\u2019eau de la piscine\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/application-easy-care_0-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/ae-en\/pools-and-equipment\/equipment\/pool-cleaning-and-maintenance\/smart-pool-control-unit\" class=\"item-card is-size-card splide__slide \">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Smart pool control unit<\/h3>\n\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-540x540.jpg\" class=\"attachment-card size-card\" alt=\"BPC Boitier Piscine Connect\u00e9e easy\u00b7care by Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/boitier-piscine-connectee-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/ae-en\/pools-and-equipment\/equipment\/pool-cleaning-and-maintenance\/pressure-sensor\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Pressure sensor<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>The<strong> pressure sensor<\/strong> is a smart device that is part of the easy\u00b7care pack. It enables you to control the pressure of the hydraulic circuit from the smart monitor.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Capteur de pression sur filtration de piscine connect\u00e9e\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-connectee-capteur-pression-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Take the plunge and enjoy a 100% peaceful and pleasurable pool experience!<\/p>\n<p>To get equipped, contact your Waterair dealer.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>Dive in!<\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                        <div class=\"row\">\n                    <div class=\"col-12\">\n                        <div data-wa=\"fade-up\" data-wa-delay=\"100\" class=\"block-mini-form__text text-center c-white\">\n                            <p>Pour commencer votre projet, nous vous invitons \u00e0 plonger dans notre catalogue pour d\u00e9couvrir nos mod\u00e8les de piscines et nos \u00e9quipements.<br \/>Bien saisir vos coordonn\u00e9es, c\u2019est vous assurer que votre catalogue piscines arrivera chez vous, dans votre bo\u00eete aux lettres. Le destin de votre catalogue piscines Waterair ne tient qu&#8217;\u00e0 quelques touches de clavier. Tout commence par le bon choix !<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                        <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"ab46c828fe\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ae-en\/wp-json\/wp\/v2\/pages\/36665\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Surname                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            First name                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Post code                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off529489\"\n                         required='required'                                                                        maxlength=\"\"\n                                                data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Town\/City                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off562228\"\n                         required='required'                                                                        maxlength=\"\"\n                                                data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Number and street                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off240325\"\n                         required='required'                                                                                                maxlength=\"\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"ae-en\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Telephone                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"The telephone number must be at least 6 digits long.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 is-hide\">How would you like to receive your catalogue? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                     checked='checked'                \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>By post to my home<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>By email in digital format<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Address of planned pool<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            The address of my planned pool is the same as my home address        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Yes<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">No<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Post code                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off501489\"\n                                                                                                maxlength=\"\"\n                                                data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Town\/City                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off227563\"\n                                                                                                maxlength=\"\"\n                                                data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Number and street                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off565124\"\n                                                                                                                        maxlength=\"\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"ae-en\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"EMIRATS ARABES UNIS\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Surname                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            First name                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Postcode                    <\/label>\n        <input\n            autocomplete=\"off499315\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off806748\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Number and street                    <\/label>\n        <input\n            autocomplete=\"off302957\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off490121\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Town                    <\/label>\n        <input\n            autocomplete=\"off896328\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off583873\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Telephone                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"The telephone number must be at least 6 digits long.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Waterair customer number                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Yes<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">No<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">I authorise Waterair to send me prices, the digital catalogue and special offers :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row js-optin-block optin-block optin-block--email\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">By email<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row js-optin-block optin-block optin-block--sms\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">By SMS text message<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Your contact details will be transferred to our exclusive Piscines Waterair dealer in your country.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">I was sent here by a friend<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"ae-en\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Send request<\/button>\n\t\t\t<\/div>\n\n\t\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<p>All fields marked * are compulsory<br \/>\nWaterair Group collects the data you provide to assist with the processing of your request. For more information, please consult our privacy policy available at the bottom of our website pages<\/p>\n\t\t<\/div>\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-36665","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Smart pool: a customised pool assistant makes maintenance easier | Waterair Swimming Pools<\/title>\n<meta name=\"description\" content=\"Discover easy\u00b7care by Waterair, which monitors your water parameters (pH and chlorine levels and temperature) and provides appropriate advice where necessary. Simplify pool maintenance!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/ae-en\/smart-pool\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Smart pool: easy\u00b7care by Waterair\" \/>\n<meta property=\"og:description\" content=\"Discover easy\u00b7care by Waterair, which monitors your water parameters (pH and chlorine levels and temperature) and provides appropriate advice where necessary. Simplify pool maintenance!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/ae-en\/smart-pool\" \/>\n<meta property=\"og:site_name\" content=\"Waterair Swimming Pools\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T13:08:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/smart-pool\",\"url\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/smart-pool\",\"name\":\"Smart pool: a customised pool assistant makes maintenance easier | Waterair Swimming Pools\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/#website\"},\"datePublished\":\"2021-10-29T18:56:59+00:00\",\"dateModified\":\"2026-02-02T13:08:00+00:00\",\"description\":\"Discover easy\u00b7care by Waterair, which monitors your water parameters (pH and chlorine levels and temperature) and provides appropriate advice where necessary. Simplify pool maintenance!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/smart-pool#breadcrumb\"},\"inLanguage\":\"en-AE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/smart-pool\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/smart-pool#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Smart pool: easy\u00b7care by Waterair\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/#website\",\"url\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/\",\"name\":\"Waterair Swimming Pools\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.waterair.com\\\/ae-en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-AE\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Smart pool: a customised pool assistant makes maintenance easier | Waterair Swimming Pools","description":"Discover easy\u00b7care by Waterair, which monitors your water parameters (pH and chlorine levels and temperature) and provides appropriate advice where necessary. Simplify pool maintenance!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/ae-en\/smart-pool","og_locale":"en_US","og_type":"article","og_title":"Smart pool: easy\u00b7care by Waterair","og_description":"Discover easy\u00b7care by Waterair, which monitors your water parameters (pH and chlorine levels and temperature) and provides appropriate advice where necessary. Simplify pool maintenance!","og_url":"https:\/\/www.waterair.com\/ae-en\/smart-pool","og_site_name":"Waterair Swimming Pools","article_modified_time":"2026-02-02T13:08:00+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/ae-en\/smart-pool","url":"https:\/\/www.waterair.com\/ae-en\/smart-pool","name":"Smart pool: a customised pool assistant makes maintenance easier | Waterair Swimming Pools","isPartOf":{"@id":"https:\/\/www.waterair.com\/ae-en\/#website"},"datePublished":"2021-10-29T18:56:59+00:00","dateModified":"2026-02-02T13:08:00+00:00","description":"Discover easy\u00b7care by Waterair, which monitors your water parameters (pH and chlorine levels and temperature) and provides appropriate advice where necessary. Simplify pool maintenance!","breadcrumb":{"@id":"https:\/\/www.waterair.com\/ae-en\/smart-pool#breadcrumb"},"inLanguage":"en-AE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/ae-en\/smart-pool"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/ae-en\/smart-pool#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.waterair.com\/ae-en"},{"@type":"ListItem","position":2,"name":"Smart pool: easy\u00b7care by Waterair"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/ae-en\/#website","url":"https:\/\/www.waterair.com\/ae-en\/","name":"Waterair Swimming Pools","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/ae-en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-AE"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/pages\/36665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/comments?post=36665"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/pages\/36665\/revisions"}],"predecessor-version":[{"id":598150,"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/pages\/36665\/revisions\/598150"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/ae-en\/wp-json\/wp\/v2\/media?parent=36665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}