{"id":21339,"date":"2021-10-18T17:49:04","date_gmt":"2021-10-18T15:49:04","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/securite\/poolabdeckung"},"modified":"2024-03-12T10:16:45","modified_gmt":"2024-03-12T09:16:45","slug":"poolabdeckung","status":"publish","type":"equipment-security","link":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung","title":{"rendered":"Poolabdeckungen"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Beim Baden im Pool mit der Familie oder Freunden steht die Sicherheit an erster Stelle. Auch gesetzliche Vorschriften verlangen Sicherheitsma\u00dfnahmen bei privaten Swimmingpools. Waterair bietet Ihnen dazu Poolabdeckungen und andere Sicherheitsprodukte.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Warum eine Poolabdeckung ?<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Unsere Poolabdeckungen sind nicht nur f\u00fcr die Sicherheit Ihres Swimmingpools wichtig, sondern sch\u00fctzen ihn auch das gesamte Jahr \u00fcber vor Witterungseinfl\u00fcssen. Zudem sind sie leicht zu bedienen:<\/p>\n<ul>\n<li>Sie sch\u00fctzen Ihren Swimmingpool vor externen Verschmutzungen.<\/li>\n<li>Sie verringern die Wasserverdunstung.<\/li>\n<li>Sie sparen Reinigungsprodukte, da die Photosynthese eingeschr\u00e4nkt wird.<\/li>\n<li>Sie helfen, die Wassertemperatur aufrechtzuerhalten.<\/li>\n<\/ul>\n<p>Dank einer neuen Generation von Multifunktionsabdeckungen wie Solae Waterair\u00ae k\u00f6nnen Sie Ihren Pool kostenlos mit Sonnenenergie heizen.<\/p>\n<h2>Welche Sicherheitsabdeckung ist die beste f\u00fcr Sie?<\/h2>\n<p>Wir bieten verschiedene Sicherheitsabdeckungen an, die alle dem NFP90-308-Standard entsprechen.<br \/>\nLesen Sie unsere Tipps f\u00fcr die richtige Auswahl:<\/p>\n<table>\n<thead>\n<tr>\n<th><\/th>\n<th>Undurchsichtige Winterabdeckung<\/th>\n<th>Watertop<\/th>\n<th>Securiwat<\/th>\n<th>Solae Waterair\u00ae<\/th>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Sicherheit<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<\/tr>\n<tr>\n<td>Schutz<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<\/tr>\n<tr>\n<td>Weniger Wartungsaufwand<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<\/tr>\n<tr>\n<td>H\u00e4lt die Temperatur aufrecht<\/td>\n<td>Verwendung nur im Winter<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<\/tr>\n<tr>\n<td>\u00dcberwinterung<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<td>Ja<\/td>\n<\/tr>\n<tr>\n<td>Solarheizung<\/td>\n<td>Nein<\/td>\n<td>Nein<\/td>\n<td>Nein<\/td>\n<td>Bis zu +9 \u00b0C<\/td>\n<\/tr>\n<tr>\n<td>Befestigung<\/td>\n<td>Gummiband am Rand<\/td>\n<td>Clipse am Rand<\/td>\n<td>Clipse seitlich der Rolle<\/td>\n<td>Clipse seitlich der Rolle<\/td>\n<\/tr>\n<tr>\n<td>Aufrollvorrichtung<\/td>\n<td>Manuell<\/td>\n<td>Kurbel <strong>oder optional:<\/strong> Elektrische Aufrollvorrichtung iScoot 700<\/td>\n<td>Kurbel <strong>oder optional:<\/strong> Elektrische Aufrollvorrichtung iScoot 700<\/td>\n<td>Elektrische Aufrollvorrichtung iScoot 700<\/td>\n<\/tr>\n<tr>\n<td>Ben\u00f6tigte Zeit zum \u00d6ffnen<\/td>\n<td>10 Minuten<\/td>\n<td>10 \u2013 15 Minuten<\/td>\n<td>5 \u2013 7 Minuten<\/td>\n<td>&lt; 3 Minuten mit iScoot 700<\/td>\n<\/tr>\n<tr>\n<td>Ben\u00f6tigte Zeit zum Schlie\u00dfen<\/td>\n<td>20 Minuten mit 2 Personen<\/td>\n<td>20 Minuten<\/td>\n<td>3 \u2013 5 Minuten<\/td>\n<td>5 \u2013 10 Minuten<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Damit Gro\u00df und Klein in Ihrem Garten sicher sind, sollte der Pool stets abgedeckt werden, wenn er nicht genutzt wird.<\/p>\n<h2><strong>Wie rollen Sie Ihre Sicherheitsabdeckung einfach auf?<\/strong><\/h2>\n<p>Wir bieten bequeme L\u00f6sungen an, um Ihnen die Handhabung Ihrer Poolabdeckung zu erleichtern, zum Beispiel iScoot 700, die elektrische Aufrollvorrichtung f\u00fcr Poolabdeckungen:<\/p>\n<ul>\n<li>M\u00fcheloses Aufrollen in weniger als drei Minuten<sup> (1)<\/sup><\/li>\n<li>Leicht und handlich<\/li>\n<li>Fernbedienung mit Kabel<\/li>\n<li>M\u00f6glichkeit, auf der einen oder anderen Seite zu stehen, um die Abdeckung aufzurollen<\/li>\n<li>Automatisches Ladeger\u00e4t mit Ladeanzeige<\/li>\n<\/ul>\n<p>(1) Zeitaufwand f\u00fcr das Aufrollen einer 5 x 12 Meter gro\u00dfen Abdeckung<sup>\u00b2<\/sup>.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Die Wahl Ihrer Sicherheitsabdeckung besprechen wir gerne w\u00e4hrend der&nbsp;<a href=\"https:\/\/www.waterair.com\/de\/installationsstudie\">Umsetzungsplanung<\/a> Ihres Pools. Ihr Waterair Partner ber\u00e4t Sie gerne zu den verschiedenen M\u00f6glichkeiten der Abdeckung.<\/p>\n<\/div><\/div><\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>G\u00f6nnen Sie sich das Vergn\u00fcgen !<\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"a12b41798d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/de\/wp-json\/wp\/v2\/equipment-security\/21339\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Nachname                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Vorname                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    PLZ                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off377376\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ort                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off523031\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c4\u00d6\u00dc\u1e9e\u00e4\u00f6\u00fc\u00df()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Stra\u00dfe\/Nr.                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off139319\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00c4\u00d6\u00dc\u1e9e\u00e4\u00f6\u00fc\u00df()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"DEU\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"de\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Telefon                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Die Telefonnummer muss mindestens 6 Zeichen lang sein\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 \">Wie m\u00f6chten Sie Ihren Katalog erhalten? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Per Post an meinen Wohnort<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>Per E-Mail in digitaler Form<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Projekt-Adresse<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            Die Projekt-Adresse entspricht meiner Wohn-Adresse        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Ja<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Nein<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    PLZ                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off128244\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ort                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off966580\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c4\u00d6\u00dc\u1e9e\u00e4\u00f6\u00fc\u00df()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Stra\u00dfe\/Nr.                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off764049\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00c4\u00d6\u00dc\u1e9e\u00e4\u00f6\u00fc\u00df()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"DEU\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"de\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"ALLEMAGNE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nachname                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Vorname                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            PLZ                    <\/label>\n        <input\n            autocomplete=\"off872001\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off134785\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Stra\u00dfe\/Nr.                    <\/label>\n        <input\n            autocomplete=\"off296782\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off504015\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ort                    <\/label>\n        <input\n            autocomplete=\"off137700\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off844024\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Telefon                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Die Telefonnummer muss mindestens 6 Zeichen lang sein\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Waterair Kundennummer                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 \">W\u00fcnschen Sie ihren Pool selbst bauen? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col pl-0 pr-0 \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Ja<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Nein<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Vielleicht<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 \">Wann planen Sie dieses Projekt? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col pl-0 pr-0 \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Sofort<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">In den n\u00e4chsten 3 Monaten<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">In den 6 n\u00e4chsten Monaten<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Sp\u00e4ter<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Ich genehmige es Waterair, mir Preise, den digitalen Katalog und Sonderangebote zuzusenden : <\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Per E-Mail<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Per SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Ich bin einverstanden, dass meine Daten an den lokalen Waterair-Partner gesendet werden. F\u00fcr die Verarbeitung Ihrer Anfrage werden Ihre Daten an unserem lokalen Exklusiv-H\u00e4ndler gesendet.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Ich wurde von einem Freund geworben<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"de\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Anfrage senden<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">Mit einem * gekennzeichnete Felder m\u00fcssen ausgef\u00fcllt werden<br \/>\r\nIhre Daten werden im Rahmen Ihrer Anfrage von der Waterair Gruppe gespeichert. Weitere Informationen finden Sie in unserer Datenschutzrichtlinie, die Sie unten auf unserer Website finden.<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t<div class=\"container mb-md-8 mb-4\">\n\t\t\t\t<div class=\"row align-items-end\">\n\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 data-wa=\"fade-up\" class=\"content-block__title mb-0\">Weitere Sicherheits-L\u00f6sungen<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung-solae\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Solae Waterair\u00ae<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\">Solae Waterair\u00ae ist eine patentierte Innovation. Die multifunktionale Solarabdeckung ist mit lichtdurchl\u00e4ssigen Paneelen ausgestattet, die die Wassertemperatur durch den Treibhauseffekt um bis zu 9\u00b0C aufheizt. Dar\u00fcber hinaus bietet sie das ganze Jahr \u00fcber Sicherheit und Schutz f\u00fcr Ihren Pool.<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Piscine enterr\u00e9e Sara + couverture de piscine Solae\u00ae Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/alarmsysteme\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Alarmsysteme<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Ein Alarmsystem, das erkennt, wenn ein Gewicht \u00fcber 6 kg ins Wasser f\u00e4llt oder wenn jemand in den Bereich am Poolrand eindringt.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-540x540.png\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-540x540.png 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-1080x1080.png 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-480x480.png 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-240x240.png 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-150x150.png 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-75x75.png 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-780x780.png 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-390x390.png 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-320x320.png 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/default-waterair-160x160.png 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/schutzzaeune\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Schutzz\u00e4une<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Um die Sicherheit um den Pool zu steigern, nutzen Sie flexible oder starre Schutzz\u00e4une. Sie versperren Kleinkindern den Zugang zum Pool.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Barri\u00e8re pour s\u00e9curiser sa piscine\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Beim Baden im Pool mit der Familie oder Freunden steht die Sicherheit an erster Stelle. Auch gesetzliche Vorschriften verlangen Sicherheitsma\u00dfnahmen bei privaten Swimmingpools. Waterair bietet Ihnen dazu Poolabdeckungen und andere Sicherheitsprodukte. Die Wahl Ihrer Sicherheitsabdeckung besprechen wir gerne w\u00e4hrend der&nbsp;Umsetzungsplanung Ihres Pools. Ihr Waterair Partner ber\u00e4t Sie gerne zu den verschiedenen M\u00f6glichkeiten der Abdeckung.<\/p>\n","protected":false},"featured_media":20710,"template":"","class_list":["post-21339","equipment-security","type-equipment-security","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sichere Poolabdeckungen | Waterair Pools<\/title>\n<meta name=\"description\" content=\"Sichere Poolabdeckungen erleichtern die t\u00e4gliche Nutzung Ihres Swimmingpools. Sie sind praktisch und einfach zu bedienen. Lesen Sie mehr \u00fcber die Vorteile!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poolabdeckungen\" \/>\n<meta property=\"og:description\" content=\"Sichere Poolabdeckungen erleichtern die t\u00e4gliche Nutzung Ihres Swimmingpools. Sie sind praktisch und einfach zu bedienen. Lesen Sie mehr \u00fcber die Vorteile!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung\" \/>\n<meta property=\"og:site_name\" content=\"Waterair Pools\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-12T09:16:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung\",\"url\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung\",\"name\":\"Sichere Poolabdeckungen | Waterair Pools\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg\",\"datePublished\":\"2021-10-18T15:49:04+00:00\",\"dateModified\":\"2024-03-12T09:16:45+00:00\",\"description\":\"Sichere Poolabdeckungen erleichtern die t\u00e4gliche Nutzung Ihres Swimmingpools. Sie sind praktisch und einfach zu bedienen. Lesen Sie mehr \u00fcber die Vorteile!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Couverture de piscine coverwat Waterair\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.waterair.com\/de\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sicherheitsl\u00f6sungen\",\"item\":\"https:\/\/www.waterair.com\/de\/securite\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Poolabdeckungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/de\/#website\",\"url\":\"https:\/\/www.waterair.com\/de\/\",\"name\":\"Waterair Pools\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sichere Poolabdeckungen | Waterair Pools","description":"Sichere Poolabdeckungen erleichtern die t\u00e4gliche Nutzung Ihres Swimmingpools. Sie sind praktisch und einfach zu bedienen. Lesen Sie mehr \u00fcber die Vorteile!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung","og_locale":"de_DE","og_type":"article","og_title":"Poolabdeckungen","og_description":"Sichere Poolabdeckungen erleichtern die t\u00e4gliche Nutzung Ihres Swimmingpools. Sie sind praktisch und einfach zu bedienen. Lesen Sie mehr \u00fcber die Vorteile!","og_url":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung","og_site_name":"Waterair Pools","article_modified_time":"2024-03-12T09:16:45+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung","url":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung","name":"Sichere Poolabdeckungen | Waterair Pools","isPartOf":{"@id":"https:\/\/www.waterair.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg","datePublished":"2021-10-18T15:49:04+00:00","dateModified":"2024-03-12T09:16:45+00:00","description":"Sichere Poolabdeckungen erleichtern die t\u00e4gliche Nutzung Ihres Swimmingpools. Sie sind praktisch und einfach zu bedienen. Lesen Sie mehr \u00fcber die Vorteile!","breadcrumb":{"@id":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat.jpg","width":1920,"height":1080,"caption":"Couverture de piscine coverwat Waterair"},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/de\/pools-und-ausstattung\/ausstattung\/sicherheit\/poolabdeckung#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.waterair.com\/de"},{"@type":"ListItem","position":2,"name":"Sicherheitsl\u00f6sungen","item":"https:\/\/www.waterair.com\/de\/securite"},{"@type":"ListItem","position":3,"name":"Poolabdeckungen"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/de\/#website","url":"https:\/\/www.waterair.com\/de\/","name":"Waterair Pools","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/equipment-security\/21339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/equipment-security"}],"about":[{"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/types\/equipment-security"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/equipment-security\/21339\/revisions"}],"predecessor-version":[{"id":391173,"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/equipment-security\/21339\/revisions\/391173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/media\/20710"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/de\/wp-json\/wp\/v2\/media?parent=21339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}