{"id":15712,"date":"2021-12-03T07:40:14","date_gmt":"2021-12-03T06:40:14","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/escaliers\/square-2"},"modified":"2026-01-23T09:16:37","modified_gmt":"2026-01-23T08:16:37","slug":"square-2","status":"publish","type":"equipment-stairs","link":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square","title":{"rendered":"Escalera de piscina Square"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Ancho: 2,60 m<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Descubra nuestra escalera de \u00e1ngulo Square, exclusivamente disponible para la piscina rectangular de acero <a href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/piscinas\/rectangulares\/tina\">Tina<\/a>. Su forma triangular encaja perfectamente con el dise\u00f1o de este modelo, aunando confort y practicidad.<\/p>\n<\/div><\/div><\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Colocada en una de las esquinas de la piscina, har\u00e1 las delicias de toda la familia, manteniendo la longitud de nado y el espacio de juegos.<\/p>\n<p>Espaciosa, le recibir\u00e1 para disfrutar de unas pausas refrescantes. Con dos anchas plazas de asiento situadas en los laterales, esta acogedora escalera es ideal para relajarse. La zona de acceso central se queda libre para entrar y salir de la piscina con comodidad.<\/p>\n<p>Para mejorar el bienestar, se pueden instalar como opci\u00f3n 2 chorros de hidromasaje a cada lado de los asientos, con 2 efectos de masaje:<\/p>\n<ul>\n<li>1 chorro rotativo para un masaje amplio<\/li>\n<li>1 chorro orientable para un masaje dirigido<\/li>\n<\/ul>\n<p>Pr\u00e1ctica, con 4 escalones antideslizantes, le aportar\u00e1 seguridad y facilidad de acceso.<\/p>\n<p>Disponible en dos colores, gris granito o beige granito, combinar\u00e1 con el color de su liner de piscina seg\u00fan sus gustos.<\/p>\n<p>\u00bfQuiere hacer realidad su proyecto? Solicite ya mismo su cat\u00e1logo piscinas Waterair y descubra todas las posibilidades que le ofrecemos.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t<div class=\"container mb-md-8 mb-4\">\n\t\t\t\t<div class=\"row align-items-end\">\n\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 data-wa=\"fade-up\" class=\"content-block__title mb-0\">Otros modelos de escaleras :<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/piano\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Piano<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\">La escalera de piscina Piano facilita la entrada al agua as\u00ed como la cubierta del estanque. Le presentamos en detalle este equipamiento opcional en las piscinas peque\u00f1as Tina y Inaya.<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-gres-cerame-piano-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/paso\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Escalera Paso<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Siendo de poca anchura la escalera de piscina Paso puede integrar f\u00e1cilmente a las distintas configuraciones de piscinas Waterair. El segundo pelda\u00f1o est\u00e1 especialmente pensado para ofrecerle la posibilidad de sentarse c\u00f3modamente.<\/p>\r\n\r\n<p>Esta escalera dise\u00f1ada para las piscinas existe en acabado beige granito o gris granito.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-paso-ambiance-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/enjoy\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Escalera de piscina Enjoy<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Disponible para la l\u00ednea de piscinas modernas Elsa.<\/p>\r\n\r\n<p>La escalera de piscina Enjoy, con su dise\u00f1o elegante e intemporal, se ha pensado especialmente para el modelo Elsa. Sus amplias dimensiones permiten disfrutar de un verdadero espacio de cordialidad muy c\u00f3modo en la piscina, y no por ello disminuye la superficie de nataci\u00f3n.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Escalier de piscine Enjoy\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-piscine-enjoy-1-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/orbis\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Escalera Orbis<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>La escalera de piscina Orbis es el \u00faltimo modelo de la colecci\u00f3n de escaleras de Piscinas Waterair. Gracias a su dise\u00f1o elegante y contempor\u00e1neo se adapta perfectamente a todo tipo de piscinas.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-orbis-beige-2-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/pacio\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Escalera de piscina Pacio<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>La escalera interior Pacio, parte integrante de la piscina, permite ganar espacio alrededor de esta \u00faltima. El modelo de piscina Waterair y la escalera forman un conjunto \u00fanico.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-pacio-margelles-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/welcome\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Escalera Welcome<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p><strong>Ancho: 2,60 m <\/strong><\/p>\r\n\r\n<p>Descubra nuestra escalera de piscina Welcome, un equipo que combina lo cl\u00e1sico y lo moderno. Esta elegante y espaciosa escalera exterior aportar\u00e1 el m\u00e1ximo confort y belleza a su piscina. Esta escalera de piscina puede ubicarse en diversos lugares de forma que mejor se adapte al terreno y a sus necesidades.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-piscine-welcome-beige-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/lobby\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Lobby<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\">Escalier de piscine Lobby<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/escalier-de-piscine-gris-lobby-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>\u00a1L\u00e1ncese a la piscina!<\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"a12b41798d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/equipment-stairs\/15712\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Apellidos                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nombre                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    C\u00f3digo postal                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off148434\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ciudad                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off618956\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    N\u00famero y direcci\u00f3n                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off337905\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"es\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Tel\u00e9fono                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"El n\u00famero de tel\u00e9fono debe tener al menos 6 caracteres.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 \">\u00bfC\u00f3mo le gustar\u00eda recibir su cat\u00e1logo? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Por correo en mi domicilio<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>Por correo electr\u00f3nico en formato digital<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Direcci\u00f3n de instalaci\u00f3n del proyecto<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            La direcci\u00f3n del proyecto es la misma que mi direcci\u00f3n personal        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">S\u00ed<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">No<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    C\u00f3digo postal                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off404691\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ciudad                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off980006\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    N\u00famero y direcci\u00f3n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off435658\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"es\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"ESPAGNE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Apellidos                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nombre                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            C\u00f3digo postal                    <\/label>\n        <input\n            autocomplete=\"off541266\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off708804\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            N\u00famero y direcci\u00f3n                    <\/label>\n        <input\n            autocomplete=\"off643540\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off489748\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ciudad                    <\/label>\n        <input\n            autocomplete=\"off595135\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off353784\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Tel\u00e9fono                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"El n\u00famero de tel\u00e9fono debe tener al menos 6 caracteres.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            N\u00famero de cliente Waterair                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">S\u00ed<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">No<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Autorizo a Waterair a enviarme las tarifas, el cat\u00e1logo digital y las promociones :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Por correo electr\u00f3nico<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Por SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Autorizo a que se compartan mis datos con el distribuidor exclusivo de Piscines Waterair de mi pa\u00eds<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Vengo de parte de un padrino<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"es\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Enviar la solicitud<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">* campos obligatorios<br \/>\r\nWaterair Group recopila sus datos en el marco de su solicitud. Para obtener m\u00e1s informaci\u00f3n, consulte nuestra pol\u00edtica de privacidad disponible en la parte inferior de nuestra p\u00e1gina web.<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ancho: 2,60 m Descubra nuestra escalera de \u00e1ngulo Square, exclusivamente disponible para la piscina rectangular de acero Tina. Su forma triangular encaja perfectamente con el dise\u00f1o de este modelo, aunando confort y practicidad.<\/p>\n","protected":false},"featured_media":14083,"template":"","class_list":["post-15712","equipment-stairs","type-equipment-stairs","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Escalera de \u00e1ngulo Square | Piscinas Waterair<\/title>\n<meta name=\"description\" content=\"La escalera de \u00e1ngulo Square, que combina perfectamente con la piscina rectangular Emilie, mantiene la longitud de nado y le recibir\u00e1 para unas pausas refrescantes. \u00a1No espere m\u00e1s para descubrirla!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escalera de piscina Square\" \/>\n<meta property=\"og:description\" content=\"La escalera de \u00e1ngulo Square, que combina perfectamente con la piscina rectangular Emilie, mantiene la longitud de nado y le recibir\u00e1 para unas pausas refrescantes. \u00a1No espere m\u00e1s para descubrirla!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square\" \/>\n<meta property=\"og:site_name\" content=\"Piscinas Waterair\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T08:16:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square\",\"url\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square\",\"name\":\"Escalera de \u00e1ngulo Square | Piscinas Waterair\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg\",\"datePublished\":\"2021-12-03T06:40:14+00:00\",\"dateModified\":\"2026-01-23T08:16:37+00:00\",\"description\":\"La escalera de \u00e1ngulo Square, que combina perfectamente con la piscina rectangular Emilie, mantiene la longitud de nado y le recibir\u00e1 para unas pausas refrescantes. \u00a1No espere m\u00e1s para descubrirla!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg\",\"width\":1920,\"height\":1200,\"caption\":\"Escalier d\u2019angle pour piscine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.waterair.com\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escaleras\",\"item\":\"https:\/\/www.waterair.com\/es\/escaliers\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Escalera de piscina Square\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/es\/#website\",\"url\":\"https:\/\/www.waterair.com\/es\/\",\"name\":\"Piscinas Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Escalera de \u00e1ngulo Square | Piscinas Waterair","description":"La escalera de \u00e1ngulo Square, que combina perfectamente con la piscina rectangular Emilie, mantiene la longitud de nado y le recibir\u00e1 para unas pausas refrescantes. \u00a1No espere m\u00e1s para descubrirla!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square","og_locale":"es_ES","og_type":"article","og_title":"Escalera de piscina Square","og_description":"La escalera de \u00e1ngulo Square, que combina perfectamente con la piscina rectangular Emilie, mantiene la longitud de nado y le recibir\u00e1 para unas pausas refrescantes. \u00a1No espere m\u00e1s para descubrirla!","og_url":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square","og_site_name":"Piscinas Waterair","article_modified_time":"2026-01-23T08:16:37+00:00","og_image":[{"width":1920,"height":1200,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square","url":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square","name":"Escalera de \u00e1ngulo Square | Piscinas Waterair","isPartOf":{"@id":"https:\/\/www.waterair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg","datePublished":"2021-12-03T06:40:14+00:00","dateModified":"2026-01-23T08:16:37+00:00","description":"La escalera de \u00e1ngulo Square, que combina perfectamente con la piscina rectangular Emilie, mantiene la longitud de nado y le recibir\u00e1 para unas pausas refrescantes. \u00a1No espere m\u00e1s para descubrirla!","breadcrumb":{"@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/escalier-triangle-square.jpg","width":1920,"height":1200,"caption":"Escalier d\u2019angle pour piscine"},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/escaleras\/square#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.waterair.com\/es"},{"@type":"ListItem","position":2,"name":"Escaleras","item":"https:\/\/www.waterair.com\/es\/escaliers"},{"@type":"ListItem","position":3,"name":"Escalera de piscina Square"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/es\/#website","url":"https:\/\/www.waterair.com\/es\/","name":"Piscinas Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/equipment-stairs\/15712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/equipment-stairs"}],"about":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/types\/equipment-stairs"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/equipment-stairs\/15712\/revisions"}],"predecessor-version":[{"id":573923,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/equipment-stairs\/15712\/revisions\/573923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/media\/14083"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/media?parent=15712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}