{"id":52158,"date":"2021-11-02T12:52:13","date_gmt":"2021-11-02T11:52:13","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/filtracion-para-piscina"},"modified":"2022-05-18T16:45:00","modified_gmt":"2022-05-18T14:45:00","slug":"filtracion-para-piscina","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina","title":{"rendered":"Filtraci\u00f3n de la piscina"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Escoja el sistema de filtraci\u00f3n m\u00e1s adaptado a su piscina.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t<div class=\"container mb-md-8 mb-4\">\n\t\t\t\t<div class=\"row align-items-end\">\n\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 data-wa=\"fade-up\" class=\"content-block__title mb-0\">Nuestros modelos<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\/bloque-de-filtracion-filwat-compact-system-eco-r\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Bloque de filtraci\u00f3n Filwat Compact System\u00ae eco\u00b7r <\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Los procesos de gesti\u00f3n y de toma de decisiones de Piscinas Waterair se basan en el respeto por los valores sociales, el medio ambiente y una econom\u00eda racional. En ese sentido hemos desarrollado la piscina eco-responsable by Waterair: a medida, climatizada, cubierta, segura, innovadora y de bajo consumo. Nuestro objetivo es ofrecer una piscina econ\u00f3mica y respetuosa con el medio ambiente.<\/p>\r\n\r\n<p>De este enfoque nace la etiqueta eco\u00b7r, que permite distinguir nuestros productos ecol\u00f3gicos. \u00a1Le presentamos este nuevo sistema de filtraci\u00f3n innovador y de bajo consumo!<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\/plugin-ecor\" class=\"item-card is-size-card splide__slide \">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Filtraci\u00f3n de piscina econ\u00f3mica y eficiente: el plugin Eco\u00b7R<\/h3>\n\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-540x540.jpg\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2022\/03\/variateur-ecor-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\/filwat-compact-system\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Filwat Compact System\u00ae<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>El sistema de filtraci\u00f3n Filwat Compact System\u00ae es el coraz\u00f3n de su piscina. Directamente colocado junto a la piscina, se evita la creaci\u00f3n de un local t\u00e9cnico separado. Su funci\u00f3n es asegurar una perfecta calidad del agua y la facilidad de mantenimiento.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-piscine-integree-fcs-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\/locaroc\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Local de filtraci\u00f3n Locaroc 2<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Locaroc 2 es un local t\u00e9cnico premontado que permite instalar de manera f\u00e1cil y r\u00e1pida el cuarto t\u00e9cnico de su piscina Waterair. Gracias a su dise\u00f1o inspirado en una roca aut\u00e9ntica, Locaroc 2 posee un aspecto muy real y natural que permite integrar el sistema de filtraci\u00f3n de forma armoniosa en su jard\u00edn.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Filtration locaroc 2\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-locaroc-2-1_0-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\/filtracion-de-cartucho\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Filtraci\u00f3n piscina cl\u00e1sica de cartucho<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Piscinas Waterair le propone un sistema de filtraci\u00f3n cl\u00e1sico de cartucho que se instala en un local t\u00e9cnico, cerca de la piscina o en el s\u00f3tano de su casa.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Filtration \u00e0 cartouche des piscines Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration_cartouche-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\/filtracion-de-arena\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Filtraci\u00f3n cl\u00e1sica de arena<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>El sistema de filtraci\u00f3n de arena, como la de cartucho, se instala simplemente en un local t\u00e9cnico cerca de su piscina Waterair o en el s\u00f3tano de su casa.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-540x540.jpg\" class=\"attachment-card size-card\" alt=\"filtre \u00e0 sable pour piscine\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/filtration-piscine-sable-1-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p><span><span><span>El respeto del agua y del medio ambiente es una prioridad para Piscinas Waterair. \u00bfSab\u00eda que una piscina bien mantenida no tiene obligatoriamente necesidad de ser vaciada? Es la raz\u00f3n por la que es importante escoger un buen sistema de filtraci\u00f3n asociado a productos de mantenimiento de buena calidad: estos son los garantes de un agua sana y l\u00edmpida y, sobre todo, de un bajo consumo de agua.<\/span><\/span><\/span><\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div class=\"container block--core-columns\"><div class=\"row\"><div class=\"col-12 \">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\"><span><span><span>Filtraci\u00f3n Locatec\u00ae<\/span><\/span><\/span><\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Local t\u00e9cnico de piscina con ducha<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>El sistema de filtraci\u00f3n Locatec\u00ae, creaci\u00f3n exclusiva de Piscinas WATERAIR, es un local t\u00e9cnico industrializado multifunciones, est\u00e9tico y pr\u00e1ctico, que le garantiza una comodidad de utilizaci\u00f3n \u00f3ptima.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\"><span><span><span>Locatec\u00ae Premium<\/span><\/span><\/span><\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Local t\u00e9cnico de piscina elegante con ducha<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Dise\u00f1ado por Waterair, el local t\u00e9cnico de filtraci\u00f3n para piscina Locatec\u00ae Premium re\u00fane todas las ventajas de Locatec\u00ae, pero dispone de a\u00fan m\u00e1s equipos de comodidad. El plato de ducha recibe as\u00ed una rejilla que a\u00f1ade un toque de elegancia y que parece ser de madera natural tanto en aspecto como al tacto.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>El local t\u00e9cnico Locatec\u00ae Premium para piscinas Waterair est\u00e1 equipado con una conexi\u00f3n de cascada y una preinstalaci\u00f3n para un electrolizador de sal.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\">&nbsp;<\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\">&nbsp;<\/h2>\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\"><span><span><span>Filwat Compact System\u00ae<\/span><\/span><\/span><\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Filwat Compact System\u00ae, creado por Piscinas WATERAIR y certificado por T\u00dcV (N\u00b0R60022656) est\u00e1 destinado a piscinas con una superficie inferior a 35 m2 (excepto piscinas profundas).<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\"><span><span><span>Filtraci\u00f3n cl\u00e1sica de cartucho<\/span><\/span><\/span><\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Piscinas Waterair le propone un sistema de filtraci\u00f3n cl\u00e1sico de cartucho que se instala en un local t\u00e9cnico, cerca de la piscina o en el s\u00f3tano de su casa.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\"><span><span><span>Filtraci\u00f3n cl\u00e1sica de arena<\/span><\/span><\/span><\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>El sistema de filtraci\u00f3n de arena, como la de cartucho, se instala simplemente en un local t\u00e9cnico cerca de su piscina Waterair o en el s\u00f3tano de su casa.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h2 class=\"wp-block-heading\"><span><span><span>Locaroc 2<\/span><\/span><\/span><\/h2>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>La filtraci\u00f3n preensamblada<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><span><span><span>Locaroc 2 es un local t\u00e9cnico inteligente para las piscinas peque\u00f1as y medianas Waterair, preensamblado en la f\u00e1brica. Un sistema de filtraci\u00f3n pr\u00e1ctico y f\u00e1cil de instalar.<\/span><\/span><\/span><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>\u00a1L\u00e1ncese a la piscina!<\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"ffbf03b29e\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/es\/wp-json\/wp\/v2\/pages\/52158\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Apellidos                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nombre                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    C\u00f3digo postal                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off935396\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ciudad                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off390099\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    N\u00famero y direcci\u00f3n                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off557928\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"es\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Tel\u00e9fono                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"El n\u00famero de tel\u00e9fono debe tener al menos 6 caracteres.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 \">\u00bfC\u00f3mo le gustar\u00eda recibir su cat\u00e1logo? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Por correo en mi domicilio<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>Por correo electr\u00f3nico en formato digital<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Direcci\u00f3n de instalaci\u00f3n del proyecto<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            La direcci\u00f3n del proyecto es la misma que mi direcci\u00f3n personal        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">S\u00ed<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">No<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    C\u00f3digo postal                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off144429\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ciudad                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off918482\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    N\u00famero y direcci\u00f3n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off834789\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00d1\u00c1\u00c9\u00cd\u00d3\u00da\u00dc\u00f1\u00e1\u00e9\u00ed\u00f3\u00fa\u00fc()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"es\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"ESPAGNE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Apellidos                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nombre                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            C\u00f3digo postal                    <\/label>\n        <input\n            autocomplete=\"off256081\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off615018\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            N\u00famero y direcci\u00f3n                    <\/label>\n        <input\n            autocomplete=\"off569970\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off462856\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ciudad                    <\/label>\n        <input\n            autocomplete=\"off711850\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off663090\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Tel\u00e9fono                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"El n\u00famero de tel\u00e9fono debe tener al menos 6 caracteres.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            N\u00famero de cliente Waterair                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">S\u00ed<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">No<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Autorizo a Waterair a enviarme las tarifas, el cat\u00e1logo digital y las promociones :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Por correo electr\u00f3nico<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Por SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Autorizo a que se compartan mis datos con el distribuidor exclusivo de Piscines Waterair de mi pa\u00eds<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Vengo de parte de un padrino<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"es\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Enviar la solicitud<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">* campos obligatorios<br \/>\r\nWaterair Group recopila sus datos en el marco de su solicitud. Para obtener m\u00e1s informaci\u00f3n, consulte nuestra pol\u00edtica de privacidad disponible en la parte inferior de nuestra p\u00e1gina web.<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Escoja el sistema de filtraci\u00f3n m\u00e1s adaptado a su piscina. Filtraci\u00f3n Locatec\u00ae Local t\u00e9cnico de piscina con ducha El sistema de filtraci\u00f3n Locatec\u00ae, creaci\u00f3n exclusiva de Piscinas WATERAIR, es un local t\u00e9cnico industrializado multifunciones, est\u00e9tico y pr\u00e1ctico, que le garantiza una comodidad de utilizaci\u00f3n \u00f3ptima. Locatec\u00ae Premium Local t\u00e9cnico de piscina elegante con ducha Dise\u00f1ado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":45046,"parent":101689,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-52158","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Filtraci\u00f3n de la piscina - filtre de forme eficaz el agua de su piscina<\/title>\n<meta name=\"description\" content=\"Consulte nuestra oferta de filtraci\u00f3n de piscinas Asegure un mantenimiento excelente del agua de la piscina y respete el medio ambiente - Piscinas Waterair\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtraci\u00f3n de la piscina\" \/>\n<meta property=\"og:description\" content=\"Consulte nuestra oferta de filtraci\u00f3n de piscinas Asegure un mantenimiento excelente del agua de la piscina y respete el medio ambiente - Piscinas Waterair\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\" \/>\n<meta property=\"og:site_name\" content=\"Piscinas Waterair\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-18T14:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\",\"url\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\",\"name\":\"Filtraci\u00f3n de la piscina - filtre de forme eficaz el agua de su piscina\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg\",\"datePublished\":\"2021-11-02T11:52:13+00:00\",\"dateModified\":\"2022-05-18T14:45:00+00:00\",\"description\":\"Consulte nuestra oferta de filtraci\u00f3n de piscinas Asegure un mantenimiento excelente del agua de la piscina y respete el medio ambiente - Piscinas Waterair\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Eau de piscine limpide\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.waterair.com\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piscinas y equipos\",\"item\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Equipamiento de piscina\",\"item\":\"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Filtraci\u00f3n de la piscina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/es\/#website\",\"url\":\"https:\/\/www.waterair.com\/es\/\",\"name\":\"Piscinas Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Filtraci\u00f3n de la piscina - filtre de forme eficaz el agua de su piscina","description":"Consulte nuestra oferta de filtraci\u00f3n de piscinas Asegure un mantenimiento excelente del agua de la piscina y respete el medio ambiente - Piscinas Waterair","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina","og_locale":"es_ES","og_type":"article","og_title":"Filtraci\u00f3n de la piscina","og_description":"Consulte nuestra oferta de filtraci\u00f3n de piscinas Asegure un mantenimiento excelente del agua de la piscina y respete el medio ambiente - Piscinas Waterair","og_url":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina","og_site_name":"Piscinas Waterair","article_modified_time":"2022-05-18T14:45:00+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina","url":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina","name":"Filtraci\u00f3n de la piscina - filtre de forme eficaz el agua de su piscina","isPartOf":{"@id":"https:\/\/www.waterair.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg","datePublished":"2021-11-02T11:52:13+00:00","dateModified":"2022-05-18T14:45:00+00:00","description":"Consulte nuestra oferta de filtraci\u00f3n de piscinas Asegure un mantenimiento excelente del agua de la piscina y respete el medio ambiente - Piscinas Waterair","breadcrumb":{"@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/eau-limpide.jpg","width":1920,"height":1080,"caption":"Eau de piscine limpide"},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos\/filtracion-para-piscina#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.waterair.com\/es"},{"@type":"ListItem","position":2,"name":"Piscinas y equipos","item":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos"},{"@type":"ListItem","position":3,"name":"Equipamiento de piscina","item":"https:\/\/www.waterair.com\/es\/piscinas-y-equipos\/equipos"},{"@type":"ListItem","position":4,"name":"Filtraci\u00f3n de la piscina"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/es\/#website","url":"https:\/\/www.waterair.com\/es\/","name":"Piscinas Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/pages\/52158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/comments?post=52158"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/pages\/52158\/revisions"}],"predecessor-version":[{"id":164934,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/pages\/52158\/revisions\/164934"}],"up":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/pages\/101689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/media\/45046"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/es\/wp-json\/wp\/v2\/media?parent=52158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}