{"id":31895,"date":"2021-10-29T19:43:39","date_gmt":"2021-10-29T17:43:39","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/ymparistovastuullinen-uima-allas"},"modified":"2026-01-09T15:11:10","modified_gmt":"2026-01-09T14:11:10","slug":"ymparistovastuullinen-uima-allas","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas","title":{"rendered":"Eco-Responsable-uima-allas"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.<\/p>\n<\/div><\/div><\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Jatkuvan innovointimme johtoajatuksena on saada etumatkaa ja pysty\u00e4 siten vastaamaan yhteiskunnalliseen avainkysymykseen: taisteluun ilmaston l\u00e4mpenemist\u00e4 vastaan, ja kuluttajalle kukkaroyst\u00e4v\u00e4llisesti.<\/p>\n<p>T\u00e4st\u00e4 l\u00e4hestymistavasta syntyi eco\u00b7r-tarra, jolla Waterair-uima-allastarjonnasta tunnistaa kaikki ne tuotteet, jotka ovat ekologisesti ja taloudellisesti yhteensopivia tulevien sukupolvien hyv\u00e4ksi.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-3  \">\n                                <div class=\"content-block__media   is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"312\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor.jpg 555w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor-1360x765.jpg 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor-440x247.jpg 440w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Mik\u00e4 on ymp\u00e4rist\u00f6vastuullinen uima-allas?<\/h2>\n                                                                                                                                                                            <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div data-wa=\"fade-up\"  class=\"block-media  content-block\">\n\t\t\t<div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-12 col-md-10 offset-md-1\">\n                                            <div class=\"content-block__media\">\n                                                                                                <button\n                                            class=\"content-block__button\"\n                                            data-video='{\"provider\": \"vimeo\", \"id\": \"470569574\", \"poster\": \"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-eco-r-v2-1340x1260.png\"}'\n                                    >\n                                        Katso video                                        <i class=\"app-icon app-icon-play-fill app-icon--sm\"><\/i>\n                                    <\/button>\n                                \n                                <img decoding=\"async\"\n                                        src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-eco-r-v2-920x518.png\"\n                                        srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/vignette-eco-r-v2-1840x1035.png 2x\"\n                                        alt=\"\"\n                                >\n                                                    <\/div>\n                                    <\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                            \t<\/div>\n\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <ul>\n<li>Ainutlaatuinen ja patentoitu rakenneter\u00e4slevyjen tekniikka on yksi markkinoiden v\u00e4h\u00e4p\u00e4\u00e4st\u00f6isimmist\u00e4 ratkaisuista.<\/li>\n<li>Innovatiivinen, patentoitu alhaisen kulutuksen suodatus, joka takaa moitteettoman vedenlaadun*. Se kuluttaa energiaa <strong>5 kertaa v\u00e4hemm\u00e4n kuin klassinen suodatus<\/strong>. Lis\u00e4ksi se on eritt\u00e4in hiljainen, uima-altaan rakenteeseen integroituvana yksinkertainen toteuttaa ja sopii muotoilultaan kaikentyyppisille kansille. Pumppu on kahden suodatinmateriaalin kanssa yhteensopiva: Easy Bag (sis\u00e4ltyy alkuper\u00e4istoimitukseen) tai patruunasarja (valinnainen) \u2013 jotka kuluttavat v\u00e4hemm\u00e4n vett\u00e4 kuin hiekkasuodatus. <em>*pumpulla 6 vuoden takuu.<\/em><\/li>\n<li>Kaksi aurinkokennoa, jotka auringosta tuottamallaan energialla <strong>kompensoivat pumpun yhden vuoden kulutuksen<\/strong>.<sup>(1)<\/sup><\/li>\n<li><a href=\"https:\/\/www.waterair.com\/fi\/altaat-ja-varusteet\/varusteet\/allas-turvallisuus\/allas-peite-solae\" data-entity-substitution=\"canonical\" data-entity-type=\"node\" data-entity-uuid=\"2834cbb6-cd2d-4e87-9be4-cd2cc71cee87\">Solae Waterair\u00ae<\/a>, nelj\u00e4\u00e4n vuodenaikaan mukautettu uima-altaan l\u00e4mmitt\u00e4miseen, peitt\u00e4miseen ja suojaamiseen suunniteltu peite. T\u00e4m\u00e4 patentoitu peite l\u00e4mmitt\u00e4\u00e4 uima-altaan veden kasvihuonevaikutuksellaan ja aurinkoenergialla ilmaiseksi 9 asteeseen. Se suojaa ulkopuolelta tulevilta ep\u00e4puhtauksilta. Talvella elementtien l\u00e4pikuultamattomuus ehk\u00e4isee fotosynteesi\u00e4 ja pit\u00e4\u00e4 veden puhtaana. S\u00e4\u00e4st\u00e4t <strong>sek\u00e4 tuote- ett\u00e4 energiakuluissa<\/strong>.<\/li>\n<\/ul>\n<p>N\u00e4m\u00e4 innovaatiot merkitt\u00e4viin kokoonpanos\u00e4\u00e4st\u00f6ihin yhdist\u00e4m\u00e4ll\u00e4 Waterair varmistaa, ett\u00e4 ymp\u00e4rist\u00f6vastuullinen uima-allas on mahdollisimman monen saatavilla ja voi tarjota jokaiselle mahdollisuuden nauttia uinnista ymp\u00e4rist\u00f6\u00e4 s\u00e4\u00e4st\u00e4v\u00e4ll\u00e4 tavalla.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Varusteet, joissa on merkint\u00e4 eco\u00b7r<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Kaikissa n\u00e4iss\u00e4 varusteissa on Eco\u00b7R-tarra :<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/fi\/altaat-ja-varusteet\/varusteet\/allas-suodatus\/suodatusyksikko-filwat-compact-system-eco-r\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Suodatusyksikk\u00f6 Filwat Compact System\u00ae eco\u00b7r<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Piscines Waterairin menettelytavat ja p\u00e4\u00e4t\u00f6ksenteko perustuvat sosiaalisten arvojen, ymp\u00e4rist\u00f6n ja harkitun talouden arvojen kunnioittamiseen. Olemmekin kehitt\u00e4neet ymp\u00e4rist\u00f6vastuullisen Waterair-altaan: r\u00e4\u00e4t\u00e4l\u00f6ity asiakkaan mukaan, l\u00e4mmitetty, katettu, turvattu, innovatiivinen ja v\u00e4h\u00e4n energiaa kuluttava. Tavoitteemme on tarjota taloudellinen ja ymp\u00e4rist\u00f6yst\u00e4v\u00e4llinen uima-allas.<\/p>\r\n\r\n<p>T\u00e4st\u00e4 ajattelutavasta on syntynyt eco\u00b7r-merkki, joka kattaa kaikki ekologiset tuotteemme yhden merkin alla. Tutustutaan tarkemmin uuteen innovatiiviseen ja v\u00e4h\u00e4n energiaa kuluttavaan suodatusj\u00e4rjestelm\u00e4\u00e4n!<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-540x540.webp\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-540x540.webp 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-1080x1080.webp 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-480x480.webp 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-240x240.webp 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-150x150.webp 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-75x75.webp 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-780x780.webp 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-390x390.webp 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-320x320.webp 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor-160x160.webp 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/fi\/altaat-ja-varusteet\/varusteet\/allas-turvallisuus\/allas-peite-solae\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Solae Waterair\u00ae -peite<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Solae Waterair\u00ae on Piscines Waterairin ekslusiivinen patentoitu innovaatio!<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Piscine enterr\u00e9e Sara + couverture de piscine Solae\u00ae Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Waterairin ymp\u00e4rist\u00f6vastuullinen uima-allas on ekologinen investointi!<\/p>\n<p>Lis\u00e4tietoja <strong>ymp\u00e4rist\u00f6vastuullisesta uima-altaasta<strong> saat Waterair-uima-altaiden myyntineuvojalta.<\/strong><\/strong><\/p>\n<p>(1) Piscines Waterair ei myy aurinkokennopaneeleita, joten voit valita vapaasti haluamasi materiaalin.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>Pulahda veteen ! <\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"a12b41798d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fi\/wp-json\/wp\/v2\/pages\/31895\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Nimi                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Etunimi                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Postinumero                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off404683\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Postitoimipaikka                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off532795\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c4\u00d6\u00c5\u0160\u017d\u00e4\u00f6\u00e5\u0161\u017e()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Katuosoite                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off151493\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00c4\u00d6\u00c5\u0160\u017d\u00e4\u00f6\u00e5\u0161\u017e()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"fi\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Puhelinnumero                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Puhelinnumeron tulee olla v\u00e4hint\u00e4\u00e4n 6 merkki\u00e4 pitk\u00e4\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 \">Miten haluaisit vastaanottaa kuvastosi? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Postitse kotiosoitteeseeni<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>S\u00e4hk\u00f6postitse digitaalisessa muodossa<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Hankkeen osoite<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            Hankkeen osoite on sama kuin postiosoitteeni        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Kyll\u00e4<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Ei<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Postinumero                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off561540\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Postitoimipaikka                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off587049\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c4\u00d6\u00c5\u0160\u017d\u00e4\u00f6\u00e5\u0161\u017e()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Katuosoite                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off430144\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00c4\u00d6\u00c5\u0160\u017d\u00e4\u00f6\u00e5\u0161\u017e()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"fi\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"FINLANDE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nimi                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Etunimi                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Postinumero                    <\/label>\n        <input\n            autocomplete=\"off411279\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off498917\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Katuosoite                    <\/label>\n        <input\n            autocomplete=\"off183618\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off795380\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Postitoimipaikka                    <\/label>\n        <input\n            autocomplete=\"off290189\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off493611\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Puhelinnumero                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Puhelinnumeron tulee olla v\u00e4hint\u00e4\u00e4n 6 merkki\u00e4 pitk\u00e4\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Waterair-asiakasnumero                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Kyll\u00e4<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Ei<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Sallin Waterairin l\u00e4hett\u00e4\u00e4 minulle hintoja, digitaalisen kuvaston ja tarjouksia :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">S\u00e4hk\u00f6postitse<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Teksiviestin\u00e4<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Yhteystietosi l\u00e4hetet\u00e4\u00e4n oman maasi yksinoikeudella toimivalle Piscines Waterair -j\u00e4lleenmyyj\u00e4lle.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Minulle on suositeltu teit\u00e4<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"fi\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">L\u00e4het\u00e4 pyynt\u00f6<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">*-merkityt kent\u00e4t ovat pakollisia<br \/>\r\nWaterair-konserni ker\u00e4\u00e4 tietojasi pyynt\u00f6si ohessa. L\u00f6yd\u00e4t lis\u00e4tietoja tietosuojak\u00e4yt\u00e4nn\u00f6st\u00e4mme, joka on saatavilla verkkosivustomme alareunassa<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.<\/p>\n","protected":false},"author":1,"featured_media":31855,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-31895","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eco-Responsable-uima-allas | Piscines Waterair-sivuilla<\/title>\n<meta name=\"description\" content=\"Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eco-Responsable-uima-allas\" \/>\n<meta property=\"og:description\" content=\"Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas\" \/>\n<meta property=\"og:site_name\" content=\"Piscines Waterair-sivuilla\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T14:11:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2247\" \/>\n\t<meta property=\"og:image:height\" content=\"1685\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas\",\"url\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas\",\"name\":\"Eco-Responsable-uima-allas | Piscines Waterair-sivuilla\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/fi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg\",\"datePublished\":\"2021-10-29T17:43:39+00:00\",\"dateModified\":\"2026-01-09T14:11:10+00:00\",\"description\":\"Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#breadcrumb\"},\"inLanguage\":\"fi-FI\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi-FI\",\"@id\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg\",\"width\":2247,\"height\":1685,\"caption\":\"ecor\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\/\/www.waterair.com\/fi\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eco-Responsable-uima-allas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/fi\/#website\",\"url\":\"https:\/\/www.waterair.com\/fi\/\",\"name\":\"Piscines Waterair-sivuilla\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/fi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi-FI\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eco-Responsable-uima-allas | Piscines Waterair-sivuilla","description":"Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas","og_locale":"fi_FI","og_type":"article","og_title":"Eco-Responsable-uima-allas","og_description":"Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.","og_url":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas","og_site_name":"Piscines Waterair-sivuilla","article_modified_time":"2026-01-09T14:11:10+00:00","og_image":[{"width":2247,"height":1685,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas","url":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas","name":"Eco-Responsable-uima-allas | Piscines Waterair-sivuilla","isPartOf":{"@id":"https:\/\/www.waterair.com\/fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg","datePublished":"2021-10-29T17:43:39+00:00","dateModified":"2026-01-09T14:11:10+00:00","description":"Waterair-uima-altaat k\u00e4ynnist\u00e4\u00e4 Eco-Responsable-mallin markkinoinnin: asiakaskohtaisesti r\u00e4\u00e4t\u00e4l\u00f6ity, l\u00e4mmitetty, katettu, suojaava, innovatiivinen, v\u00e4h\u00e4n kuluttava uima-allas.","breadcrumb":{"@id":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#breadcrumb"},"inLanguage":"fi-FI","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas"]}]},{"@type":"ImageObject","inLanguage":"fi-FI","@id":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/q_waterair-beige-0314_-_2247x1685.jpg","width":2247,"height":1685,"caption":"ecor"},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/fi\/ymparistovastuullinen-uima-allas#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/www.waterair.com\/fi"},{"@type":"ListItem","position":2,"name":"Eco-Responsable-uima-allas"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/fi\/#website","url":"https:\/\/www.waterair.com\/fi\/","name":"Piscines Waterair-sivuilla","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi-FI"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/pages\/31895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/comments?post=31895"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/pages\/31895\/revisions"}],"predecessor-version":[{"id":575533,"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/pages\/31895\/revisions\/575533"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/media\/31855"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/fi\/wp-json\/wp\/v2\/media?parent=31895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}