{"id":505917,"date":"2025-05-26T08:36:09","date_gmt":"2025-05-26T06:36:09","guid":{"rendered":"https:\/\/www.waterair.com\/?page_id=505917"},"modified":"2026-02-04T15:45:48","modified_gmt":"2026-02-04T14:45:48","slug":"budget","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/fr\/conseils\/budget","title":{"rendered":"Budget"},"content":{"rendered":"    <div  class=\"block-hub content-block mt-4 mt-sm-2\" data-tab-section>\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                                                                                    <\/div>\n            <\/div>\n            <div data-wa=\"fade-up\" class=\"block-hub__pages\">\n                                                            <div  class=\"block-content-media-slider   block-content-media-slider--right content-block\">\n            <div class=\"container \">\n                            <div class=\"row\">\n                    <div class=\"col-12\">\n                                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\" class=\"row flex-column flex-md-row align-items-center\">\n                        <div\n                                class=\"content-block__col col-lg-6 d-flex flex-column order-2 js-slider\"\n                                data-infinite=\"true\"\n                                data-slides-to-show=\"1\"\n                                data-slides-to-scroll=\"1\"\n                                data-fade=\"true\"\n                                data-adaptive-height=\"true\"\n                                data-arrows=\"true\"\n                                data-dots=\"true\"\n                                data-prev-arrow=\".content-block__prev-arrow\"\n                                data-next-arrow=\".content-block__next-arrow\"\n                                data-before-change=\"changeImage\"\n                        >\n                                                            <div\n                                        data-wa=\"fade-up\"\n                                        class=\"block-content-media-slider__text-wrapper\"\n                                        style=\"display: block\"\n                                        data-image=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-liner-marbre-1340x1260.webp\"\n                                >\n                                                                            <h3 class=\"content-block__subtitle h5 c-tertiary-light mt-6 mb-0\">Combien co\u00fbte une piscine enterr\u00e9e ?<\/h3>\n                                                                                                            <a\tdata-wa=\"button\" data-wa-wave=\"secondary\"\n\tclass=\"btn btn--secondary mt-3\"\n\t\t\thref=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\/prix-piscine-enterree\"\n\t\t>\n\t\tEn savoir plus    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                            <div class=\"content-block__col col-lg-6 order-3\">\n                                <div class=\"content-block__media js-swipe-handler \">\n                                                                                                                <button class=\"content-block__prev-arrow\">Previous<\/button>\n                                        <button class=\"content-block__next-arrow\">Next<\/button>\n                                                                        <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                        <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                        <image\n                                                x=\"0\"\n                                                y=\"0\"\n                                                width=\"100%\"\n                                                height=\"100%\"\n                                                xlink:href=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-liner-marbre-1340x1260.webp\"\n                                                clip-path=\"url(#content-block__mask-1398)\"\n                                        \/>\n                                        <clipPath id=\"content-block__mask-1398\" class=\"content-block__mask\">\n                                            <path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>\n                                        <\/clipPath>\n                                    <\/svg>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n\n                                <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<div  class=\"block-content-media-slider   block-content-media-slider--left content-block\">\n            <div class=\"container \">\n                            <div class=\"row\">\n                    <div class=\"col-12\">\n                                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\" class=\"row flex-column flex-md-row align-items-center\">\n                        <div\n                                class=\"content-block__col col-lg-6 d-flex flex-column order-2 js-slider\"\n                                data-infinite=\"true\"\n                                data-slides-to-show=\"1\"\n                                data-slides-to-scroll=\"1\"\n                                data-fade=\"true\"\n                                data-adaptive-height=\"true\"\n                                data-arrows=\"true\"\n                                data-dots=\"true\"\n                                data-prev-arrow=\".content-block__prev-arrow\"\n                                data-next-arrow=\".content-block__next-arrow\"\n                                data-before-change=\"changeImage\"\n                        >\n                                                            <div\n                                        data-wa=\"fade-up\"\n                                        class=\"block-content-media-slider__text-wrapper\"\n                                        style=\"display: block\"\n                                        data-image=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-liner-marbre-1340x1260.webp\"\n                                >\n                                                                            <h3 class=\"content-block__subtitle h5 c-tertiary-light mt-6 mb-0\">Construction d\u2019une piscine : quel prix pr\u00e9voir\u00a0?<\/h3>\n                                                                                                            <a\tdata-wa=\"button\" data-wa-wave=\"secondary\"\n\tclass=\"btn btn--secondary mt-3\"\n\t\t\thref=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\/budget-pour-construire-une-piscine\"\n\t\t>\n\t\tEn savoir plus    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                            <div class=\"content-block__col col-lg-6 order-1\">\n                                <div class=\"content-block__media js-swipe-handler is-left\">\n                                                                                                                <button class=\"content-block__prev-arrow\">Previous<\/button>\n                                        <button class=\"content-block__next-arrow\">Next<\/button>\n                                                                        <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                        <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                        <image\n                                                x=\"0\"\n                                                y=\"0\"\n                                                width=\"100%\"\n                                                height=\"100%\"\n                                                xlink:href=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-liner-marbre-1340x1260.webp\"\n                                                clip-path=\"url(#content-block__mask-5747)\"\n                                        \/>\n                                        <clipPath id=\"content-block__mask-5747\" class=\"content-block__mask\">\n                                            <path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>\n                                        <\/clipPath>\n                                    <\/svg>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n\n                                <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<div  class=\"block-content-media-slider   block-content-media-slider--right content-block\">\n            <div class=\"container \">\n                            <div class=\"row\">\n                    <div class=\"col-12\">\n                                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\" class=\"row flex-column flex-md-row align-items-center\">\n                        <div\n                                class=\"content-block__col col-lg-6 d-flex flex-column order-2 js-slider\"\n                                data-infinite=\"true\"\n                                data-slides-to-show=\"1\"\n                                data-slides-to-scroll=\"1\"\n                                data-fade=\"true\"\n                                data-adaptive-height=\"true\"\n                                data-arrows=\"true\"\n                                data-dots=\"true\"\n                                data-prev-arrow=\".content-block__prev-arrow\"\n                                data-next-arrow=\".content-block__next-arrow\"\n                                data-before-change=\"changeImage\"\n                        >\n                                                            <div\n                                        data-wa=\"fade-up\"\n                                        class=\"block-content-media-slider__text-wrapper\"\n                                        style=\"display: block\"\n                                        data-image=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/romy-mini-piscine-skimmer-e1767966495777-1340x1260.webp\"\n                                >\n                                                                            <h3 class=\"content-block__subtitle h5 c-tertiary-light mt-6 mb-0\">Prix mini piscine : combien co\u00fbte une piscine de moins de 10 m\u00b2 ?<\/h3>\n                                                                                                            <a\tdata-wa=\"button\" data-wa-wave=\"secondary\"\n\tclass=\"btn btn--secondary mt-3\"\n\t\t\thref=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\/prix-mini-piscine\"\n\t\t>\n\t\tEn savoir plus    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                            <div class=\"content-block__col col-lg-6 order-3\">\n                                <div class=\"content-block__media js-swipe-handler \">\n                                                                                                                <button class=\"content-block__prev-arrow\">Previous<\/button>\n                                        <button class=\"content-block__next-arrow\">Next<\/button>\n                                                                        <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                        <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                        <image\n                                                x=\"0\"\n                                                y=\"0\"\n                                                width=\"100%\"\n                                                height=\"100%\"\n                                                xlink:href=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/romy-mini-piscine-skimmer-e1767966495777-1340x1260.webp\"\n                                                clip-path=\"url(#content-block__mask-7153)\"\n                                        \/>\n                                        <clipPath id=\"content-block__mask-7153\" class=\"content-block__mask\">\n                                            <path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>\n                                        <\/clipPath>\n                                    <\/svg>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n\n                                <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<div  class=\"block-content-media-slider   block-content-media-slider--left content-block\">\n            <div class=\"container \">\n                            <div class=\"row\">\n                    <div class=\"col-12\">\n                                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\" class=\"row flex-column flex-md-row align-items-center\">\n                        <div\n                                class=\"content-block__col col-lg-6 d-flex flex-column order-2 js-slider\"\n                                data-infinite=\"true\"\n                                data-slides-to-show=\"1\"\n                                data-slides-to-scroll=\"1\"\n                                data-fade=\"true\"\n                                data-adaptive-height=\"true\"\n                                data-arrows=\"true\"\n                                data-dots=\"true\"\n                                data-prev-arrow=\".content-block__prev-arrow\"\n                                data-next-arrow=\".content-block__next-arrow\"\n                                data-before-change=\"changeImage\"\n                        >\n                                                            <div\n                                        data-wa=\"fade-up\"\n                                        class=\"block-content-media-slider__text-wrapper\"\n                                        style=\"display: block\"\n                                        data-image=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/12\/header-sofia-1340x1260.webp\"\n                                >\n                                                                            <h3 class=\"content-block__subtitle h5 c-tertiary-light mt-6 mb-0\">Quel est le prix d\u2019une piscine en kit ?<\/h3>\n                                                                                                            <a\tdata-wa=\"button\" data-wa-wave=\"secondary\"\n\tclass=\"btn btn--secondary mt-3\"\n\t\t\thref=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\/prix-piscine-kit\"\n\t\t>\n\t\tEn savoir plus    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                            <div class=\"content-block__col col-lg-6 order-1\">\n                                <div class=\"content-block__media js-swipe-handler is-left\">\n                                                                                                                <button class=\"content-block__prev-arrow\">Previous<\/button>\n                                        <button class=\"content-block__next-arrow\">Next<\/button>\n                                                                        <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                        <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                        <image\n                                                x=\"0\"\n                                                y=\"0\"\n                                                width=\"100%\"\n                                                height=\"100%\"\n                                                xlink:href=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/12\/header-sofia-1340x1260.webp\"\n                                                clip-path=\"url(#content-block__mask-2615)\"\n                                        \/>\n                                        <clipPath id=\"content-block__mask-2615\" class=\"content-block__mask\">\n                                            <path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>\n                                        <\/clipPath>\n                                    <\/svg>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n\n                                <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n<div  class=\"block-content-media-slider   block-content-media-slider--right content-block\">\n            <div class=\"container \">\n                            <div class=\"row\">\n                    <div class=\"col-12\">\n                                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\" class=\"row flex-column flex-md-row align-items-center\">\n                        <div\n                                class=\"content-block__col col-lg-6 d-flex flex-column order-2 js-slider\"\n                                data-infinite=\"true\"\n                                data-slides-to-show=\"1\"\n                                data-slides-to-scroll=\"1\"\n                                data-fade=\"true\"\n                                data-adaptive-height=\"true\"\n                                data-arrows=\"true\"\n                                data-dots=\"true\"\n                                data-prev-arrow=\".content-block__prev-arrow\"\n                                data-next-arrow=\".content-block__next-arrow\"\n                                data-before-change=\"changeImage\"\n                        >\n                                                            <div\n                                        data-wa=\"fade-up\"\n                                        class=\"block-content-media-slider__text-wrapper\"\n                                        style=\"display: block\"\n                                        data-image=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/grande-piscine-haricot-plage-bois-1340x1260.webp\"\n                                >\n                                                                            <h3 class=\"content-block__subtitle h5 c-tertiary-light mt-6 mb-0\">Quel est le prix d\u2019une piscine semi-enterr\u00e9e ?<\/h3>\n                                                                                                            <a\tdata-wa=\"button\" data-wa-wave=\"secondary\"\n\tclass=\"btn btn--secondary mt-3\"\n\t\t\thref=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\/prix-piscine-semi-enterree\"\n\t\t>\n\t\tEn savoir plus    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                            <div class=\"content-block__col col-lg-6 order-3\">\n                                <div class=\"content-block__media js-swipe-handler \">\n                                                                                                                <button class=\"content-block__prev-arrow\">Previous<\/button>\n                                        <button class=\"content-block__next-arrow\">Next<\/button>\n                                                                        <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                        <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                        <image\n                                                x=\"0\"\n                                                y=\"0\"\n                                                width=\"100%\"\n                                                height=\"100%\"\n                                                xlink:href=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/11\/grande-piscine-haricot-plage-bois-1340x1260.webp\"\n                                                clip-path=\"url(#content-block__mask-1686)\"\n                                        \/>\n                                        <clipPath id=\"content-block__mask-1686\" class=\"content-block__mask\">\n                                            <path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>\n                                        <\/clipPath>\n                                    <\/svg>\n                                <\/div>\n                            <\/div>\n                                            <\/div>\n\n                                <\/div>\n                <\/div>\n                    <\/div>\n    <\/div>\n                                                <\/div>\n            <div data-wa=\"fade-up\" class=\"row\">\n                <div class=\"col-12 col-lg-10 offset-lg-1\">\n                                    <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":10,"featured_media":0,"parent":33254,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-505917","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v28.1) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Budget | Piscines Waterair<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Budget\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/fr\/conseils\/budget\" \/>\n<meta property=\"og:site_name\" content=\"Piscines Waterair\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T14:45:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/conseils\\\/budget\",\"url\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/conseils\\\/budget\",\"name\":\"Budget | Piscines Waterair\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/#website\"},\"datePublished\":\"2025-05-26T06:36:09+00:00\",\"dateModified\":\"2026-02-04T14:45:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/conseils\\\/budget#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.waterair.com\\\/fr\\\/conseils\\\/budget\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/conseils\\\/budget#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.waterair.com\\\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conseils piscine Waterair\",\"item\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/conseils\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Budget\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/\",\"name\":\"Piscines Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.waterair.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Budget | Piscines Waterair","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/fr\/conseils\/budget","og_locale":"fr_FR","og_type":"article","og_title":"Budget","og_url":"https:\/\/www.waterair.com\/fr\/conseils\/budget","og_site_name":"Piscines Waterair","article_modified_time":"2026-02-04T14:45:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/fr\/conseils\/budget","url":"https:\/\/www.waterair.com\/fr\/conseils\/budget","name":"Budget | Piscines Waterair","isPartOf":{"@id":"https:\/\/www.waterair.com\/fr\/#website"},"datePublished":"2025-05-26T06:36:09+00:00","dateModified":"2026-02-04T14:45:48+00:00","breadcrumb":{"@id":"https:\/\/www.waterair.com\/fr\/conseils\/budget#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/fr\/conseils\/budget"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/fr\/conseils\/budget#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.waterair.com\/fr"},{"@type":"ListItem","position":2,"name":"Conseils piscine Waterair","item":"https:\/\/www.waterair.com\/fr\/conseils"},{"@type":"ListItem","position":3,"name":"Budget"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/fr\/#website","url":"https:\/\/www.waterair.com\/fr\/","name":"Piscines Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"permalink_manager":null,"_links":{"self":[{"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/pages\/505917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/comments?post=505917"}],"version-history":[{"count":3,"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/pages\/505917\/revisions"}],"predecessor-version":[{"id":598924,"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/pages\/505917\/revisions\/598924"}],"up":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/pages\/33254"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/fr\/wp-json\/wp\/v2\/media?parent=505917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}