{"id":18122,"date":"2025-12-06T09:46:04","date_gmt":"2025-12-06T08:46:04","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/filtration\/bloc-filtrant-filwat-compact-systemr-ecor-2"},"modified":"2026-01-21T11:12:58","modified_gmt":"2026-01-21T10:12:58","slug":"bloc-filtrant-filwat-compact-systemr-ecor-2","status":"publish","type":"equipment-filtration","link":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor","title":{"rendered":"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Piscines Waterair inscrit ses d\u00e9marches et prises de d\u00e9cisions dans le respect des valeurs sociales, de l\u2019environnement et d\u2019une \u00e9conomie raisonn\u00e9e. A ce titre, nous avons d\u00e9velopp\u00e9 la piscine \u00e9co-responsable by Waterair : sur-mesure, chauff\u00e9e, couverte, s\u00e9curis\u00e9e, innovante et basse consommation. Notre objectif est de proposer une piscine \u00e9conomique et respectueuse de l\u2019environnement.<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>De cette d\u00e9marche est n\u00e9e le label eco\u00b7r permettant de distinguer l\u2019ensemble de nos produits \u00e9cologiques. Cap sur ce nouveau syst\u00e8me de filtration innovant et basse consommation !<\/p>\n<\/div><\/div><\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Filwat Compact System eco\u00b7r est un bloc filtrant int\u00e9gr\u00e9 \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permettra de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Avantages de la filtration eco\u00b7r<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h3>1. Une pompe 5 x moins \u00e9nergivore<\/h3>\n<p>La technologie exclusive de cette pompe permet d\u2019assurer la filtration de sa piscine pour seulement 5 \u20ac par \/ mois. Pour une \u00e9conomie de 268 \u20ac sur l\u2019ann\u00e9e.<\/p>\n<p><strong>Exemple de consommation \u00e9lectrique annuelle (tarif edf 2018) Prix du Kwh = 0.1579 \u20ac<\/strong><\/p>\n<table>\n<tbody>\n<tr>\n<td>Pompe de filtration eco\u00b7r<\/td>\n<td>57 \u20ac<\/td>\n<\/tr>\n<tr>\n<td>Pompe de filtration classique<\/td>\n<td>325 \u20ac<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>2. Une pompe ultra silencieuse<\/h3>\n<p>Pour votre confort et celui de vos voisins, la nouvelle pompe Filwat Compact System eco\u00b7r est ultra silencieuse. Ce r\u00e9sultat est obtenu gr\u00e2ce \u00e0 une technologie exclusive et brevet\u00e9e de pompe immerg\u00e9e \u00e0 tr\u00e8s basse tension.<\/p>\n<h3>3. Un bloc filtrant esth\u00e9tique<\/h3>\n<p>Le nouveau design de capot offre un rendu design et esth\u00e9tique. Tr\u00e8s discret, le capot recouvrant le bloc filtrant peut se poser \u00e0 plat sur la page. Il existe en deux coloris : gris et blanc cr\u00e8me. La dimension du capot est de 50 x 50 cm. Il est renforc\u00e9 pour supporter une charge de plus de 150 kg.<\/p>\n<h3>4. Utilisable avec deux m\u00e9dias filtrants<\/h3>\n<p>La pompe eco\u00b7r est int\u00e9gr\u00e9e dans un bloc filtrant avec deux types de m\u00e9dia filtrants au choix : Easy Bag ou le kit cartouche (tous les deux tr\u00e8s \u00e9conomes en eau).<\/p>\n<h3>5. Garantie sur la pompe<\/h3>\n<p>La pompe b\u00e9n\u00e9ficie d\u2019une garantie de 6 ans.<\/p>\n<h3>6. Economie<\/h3>\n<p>FCS eco\u00b7r co\u00fbte plus cher qu\u2019un Filwat Compact System traditionnel, toutefois les \u00e9conomies d\u2019\u00e9nergie r\u00e9alis\u00e9es permettent un retour sur investissement au bout d\u2019environ 4 ans.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Caract\u00e9ristiques<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Compatible avec :<\/p>\n<ul>\n<li>Avec toutes les piscines inf\u00e9rieures \u00e0 36 m<sup>3<\/sup><\/li>\n<li>Possibilit\u00e9 de rajouter un \u00e9lectrolyseur<\/li>\n<\/ul>\n<p>Incompatible avec :<\/p>\n<ul>\n<li>Option baln\u00e9o<\/li>\n<li>Double projecteur<\/li>\n<\/ul>\n<p>D\u2019autres \u00e9quipements Piscines Waterair sont labellis\u00e9s Eco\u00b7R et peuvent se combiner \u00e0 l\u2019action du nouveau bloc filtrant :<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Solae Waterair \u00ae<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Solae Waterair\u00ae est une innovation exclusive brevet\u00e9e par Piscines Waterair !<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Piscine enterr\u00e9e Sara + couverture de piscine Solae\u00ae Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Associer ces diff\u00e9rents \u00e9quipements eco\u00b7r avec des \u00e9conomies de montage significatives, c\u2019est la garantie d\u2019une piscine \u00e9cologique et accessible. Un cr\u00e9do ? Bon pour la plan\u00e8te, bon pour le portefeuille !<br>Pour en savoir plus sur la piscine \u00e9co-responsable by Waterair, vous pouvez contacter un conseiller Piscines Waterair et demande une <a href=\"https:\/\/www.waterair.com\/gp\/etude-implantation\">\u00e9tude d\u2019implantation gratuite et personnalis\u00e9e<\/a>.<\/p>\n<\/div><\/div><\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>Jetez-vous \u00e0 l&#8217;eau ! <\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"8b0be60f03\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/gp\/wp-json\/wp\/v2\/equipment-filtration\/18122\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Nom                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Pr\u00e9nom                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Code postal                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off212098\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ville                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off558948\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Num\u00e9ro et rue                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off458807\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"gp\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            T\u00e9l\u00e9phone                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Le num\u00e9ro de t\u00e9l\u00e9phone doit contenir au minimum 6 caract\u00e8res.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 \">Comment souhaitez-vous recevoir votre catalogue ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Par courrier \u00e0 mon domicile<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>Par e-mail en format num\u00e9rique<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Adresse du projet<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            L\u2018adresse de mon projet est identique \u00e0 mon adresse personnelle        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Oui<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Non<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Code postal                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off234873\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ville                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off418309\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Num\u00e9ro et rue                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off835306\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"gp\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"GUADELOUPE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nom                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Pr\u00e9nom                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Code postal                    <\/label>\n        <input\n            autocomplete=\"off484401\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off589812\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Num\u00e9ro et rue                    <\/label>\n        <input\n            autocomplete=\"off776101\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off133966\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ville                    <\/label>\n        <input\n            autocomplete=\"off120308\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off633997\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            T\u00e9l\u00e9phone                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Le num\u00e9ro de t\u00e9l\u00e9phone doit contenir au minimum 6 caract\u00e8res.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Num\u00e9ro de client Waterair                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Oui<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Non<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">J\u2019autorise Waterair \u00e0 me faire parvenir les tarifs, le catalogue num\u00e9rique et les promotions :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Par e-mail<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Par SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Vos coordonn\u00e9es sont transf\u00e9r\u00e9es \u00e0 notre revendeur exclusif Piscines Waterair dans votre pays.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Je viens de la part d&#8217;un parrain<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"gp\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Envoyer la demande<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\tLes champs marqu\u00e9s d&#8217;un * sont obligatoires.<br \/>\r\nVos donn\u00e9es sont collect\u00e9es par Groupe Waterair dans le cadre de votre demande. Pour plus d&#8217;informations, veuillez consulter notre politique de confidentialit\u00e9 disponible en bas de page de notre site internet\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>Piscines Waterair inscrit ses d\u00e9marches et prises de d\u00e9cisions dans le respect des valeurs sociales, de l\u2019environnement et d\u2019une \u00e9conomie raisonn\u00e9e. A ce titre, nous avons d\u00e9velopp\u00e9 la piscine \u00e9co-responsable by Waterair : sur-mesure, chauff\u00e9e, couverte, s\u00e9curis\u00e9e, innovante et basse consommation. Notre objectif est de proposer une piscine \u00e9conomique et respectueuse de l\u2019environnement. De cette [&hellip;]<\/p>\n","protected":false},"featured_media":574484,"template":"","class_list":["post-18122","equipment-filtration","type-equipment-filtration","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r | Piscines Waterair Guadeloupe<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre bloc filtrant eco\u00b7r \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permet de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre bloc filtrant eco\u00b7r \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permet de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor\" \/>\n<meta property=\"og:site_name\" content=\"Piscines Waterair Guadeloupe\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T10:12:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1196\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor\",\"url\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor\",\"name\":\"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r | Piscines Waterair Guadeloupe\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/gp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp\",\"datePublished\":\"2025-12-06T08:46:04+00:00\",\"dateModified\":\"2026-01-21T10:12:58+00:00\",\"description\":\"D\u00e9couvrez notre bloc filtrant eco\u00b7r \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permet de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#breadcrumb\"},\"inLanguage\":\"fr-GP\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-GP\",\"@id\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp\",\"width\":2000,\"height\":1196},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.waterair.com\/gp\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Filtrations\",\"item\":\"https:\/\/www.waterair.com\/gp\/filtration\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/gp\/#website\",\"url\":\"https:\/\/www.waterair.com\/gp\/\",\"name\":\"Piscines Waterair Guadeloupe\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/gp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-GP\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r | Piscines Waterair Guadeloupe","description":"D\u00e9couvrez notre bloc filtrant eco\u00b7r \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permet de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor","og_locale":"fr_FR","og_type":"article","og_title":"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r","og_description":"D\u00e9couvrez notre bloc filtrant eco\u00b7r \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permet de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.","og_url":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor","og_site_name":"Piscines Waterair Guadeloupe","article_modified_time":"2026-01-21T10:12:58+00:00","og_image":[{"width":2000,"height":1196,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor","url":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor","name":"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r | Piscines Waterair Guadeloupe","isPartOf":{"@id":"https:\/\/www.waterair.com\/gp\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp","datePublished":"2025-12-06T08:46:04+00:00","dateModified":"2026-01-21T10:12:58+00:00","description":"D\u00e9couvrez notre bloc filtrant eco\u00b7r \u00e9quip\u00e9 d\u2019une pompe tr\u00e8s peu consommatrice en \u00e9nergie. Cette innovation permet de r\u00e9duire consid\u00e9rablement la d\u00e9pense \u00e9nerg\u00e9tique par rapport \u00e0 une filtration dite classique.","breadcrumb":{"@id":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#breadcrumb"},"inLanguage":"fr-GP","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor"]}]},{"@type":"ImageObject","inLanguage":"fr-GP","@id":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/filtration-filwat-compact-system-ecor.webp","width":2000,"height":1196},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/gp\/piscines-et-equipements\/equipements\/filtration-de-piscine\/bloc-filtrant-filwat-compact-systemr-ecor#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.waterair.com\/gp"},{"@type":"ListItem","position":2,"name":"Filtrations","item":"https:\/\/www.waterair.com\/gp\/filtration"},{"@type":"ListItem","position":3,"name":"Bloc Filtrant Filwat Compact System\u00ae eco\u00b7r"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/gp\/#website","url":"https:\/\/www.waterair.com\/gp\/","name":"Piscines Waterair Guadeloupe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/gp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-GP"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/equipment-filtration\/18122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/equipment-filtration"}],"about":[{"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/types\/equipment-filtration"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/equipment-filtration\/18122\/revisions"}],"predecessor-version":[{"id":211401,"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/equipment-filtration\/18122\/revisions\/211401"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/media\/574484"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/gp\/wp-json\/wp\/v2\/media?parent=18122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}