{"id":24248,"date":"2021-10-25T00:23:46","date_gmt":"2021-10-24T22:23:46","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/obiteljska-sreca"},"modified":"2021-12-02T17:06:08","modified_gmt":"2021-12-02T16:06:08","slug":"obiteljska-sreca","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca","title":{"rendered":"Obiteljska sre\u0107a"},"content":{"rendered":"<div class=\"container block--core-heading\"><div class=\"row\"><div class=\"col-12 \">\n<h1 class=\"wp-block-heading\">U\u017eivajte u ugodi vode jo\u0161 ovog ljeta!<\/h1>\n<\/div><\/div><\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Va\u0161 bazen&nbsp;<span style=\"color:#f39c12;\">C\u00e9line<\/span><\/h2>\n<p>To je bazen&nbsp;<strong>sa potpisom Waterair<\/strong>. Ugao ku\u0107e, drvo koje treba zaobi\u0107i, ni\u0161ta ga ne zaustavlja, znati \u0107e se&nbsp;<strong>uklopiti u oblike va\u0161eg terena<\/strong>. Dodajte izlazne stepenice (opcionalno) Orbis, Paso ili Welcome, i u tren oka \u0107ete svojoj obitelji pru\u017eiti po mjeri oblikovan prostor za slobodno vrijeme kojeg \u0107ete itekako cijeniti tijekom vru\u0107ih ljetnih dana.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                    <a\tdata-wa=\"button\" data-wa-wave=\"secondary\"\n\tclass=\"btn btn--secondary mt-3\"\n\t\t\thref=\"#catalogue-form\"\n\t\t>\n\t\tZatra\u017eite studiju provedbe    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"495\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-880x495.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"c\u00e9line\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-880x495.jpg 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-1440x810.jpg 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-768x432.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-1536x864.jpg 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-1360x765.jpg 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-440x248.jpg 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-1840x1035.jpg 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine-920x518.jpg 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/celine.jpg 1920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2><span style=\"color:#f39c12;\">200 000 ina\u010dica<\/span>&nbsp;za jedinstveni bazen!<\/h2>\n<p>Bazeni Waterair, stru\u010dnjaci za bazene u kompletu, nude vam vi\u0161e od <strong><span style=\"color:#f39c12;\">90 modela i 200 000 ina\u010dica<\/span><\/strong> koje se mogu prilagoditi svim vrstama prirodnog terena, kako bi va\u0161 vrt bio jedinstveno i personalizirano mjesto.<\/p>\n<p>Unosom svojih podataka za kontakt u nastavku primit \u0107ete besplatni <strong>katalog Bazena Waterair<\/strong> koji \u0107e vam pru\u017eiti inspiraciju do sastanka o realizaciji!<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                    <a\tdata-wa=\"button\" data-wa-wave=\"primary\"\n\tclass=\"btn btn--primary mt-3\"\n\t\t\thref=\"#catalogue-form\"\n\t\t>\n\t\tMoja inspiracija    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-3  \">\n                                <div class=\"content-block__media   is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"550\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-880x550.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"catalogue\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-880x550.jpg 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-1440x900.jpg 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-768x480.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-1536x960.jpg 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-440x275.jpg 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-1840x1150.jpg 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp-920x575.jpg 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/mockup-catalogue_exp.jpg 1920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div data-wa=\"fade-up\"  class=\"block-slider   content-block\">\n    \n                <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-12\">\n                            <div\n                            class=\"js-slider\"\n                            data-infinite=\"true\"\n                            data-slides-to-show=\"1\"\n                            data-slides-to-scroll=\"1\"\n                            data-fade=\"true\"\n                            data-adaptive-height=\"true\"\n                            data-dots=\"true\"\n                            data-arrows=\"true\"\n                    >\n                                                    <div class=\"block-slider__image\">\n                                \t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"765\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-ambiance-famille-1360x765.jpg\" class=\"item-slide__image item-slide\" alt=\"\" loading=\"1\" srcset=\"\" sizes=\"auto, \" \/>\t                            <\/div>\n                                                    <div class=\"block-slider__image\">\n                                \t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"765\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-haricot-celine-4-1360x765.jpg\" class=\"item-slide__image item-slide\" alt=\"\" loading=\"1\" srcset=\"\" sizes=\"auto, \" \/>\t                            <\/div>\n                                                    <div class=\"block-slider__image\">\n                                \t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"765\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-1360x765.jpg\" class=\"item-slide__image item-slide\" alt=\"Piscine Cl\u00e9a sur terrasse devant une maison moderne\" loading=\"1\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-1360x765.jpg 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-1440x810.jpg 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-768x432.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-1536x864.jpg 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-880x495.jpg 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-440x248.jpg 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-1840x1035.jpg 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1-920x518.jpg 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-forme-libre-clea-3-1.jpg 1920w\" sizes=\"auto, (max-width: 1360px) 100vw, 1360px\" \/>\t                            <\/div>\n                                                    <div class=\"block-slider__image\">\n                                \t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1360\" height=\"765\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/offres-juillet-ambiance-1360x765.jpg\" class=\"item-slide__image item-slide\" alt=\"\" loading=\"1\" srcset=\"\" sizes=\"auto, \" \/>\t                            <\/div>\n                                            <\/div>\n                            <\/div>\n                <\/div>\n            <\/div>\n        \n    <\/div>\n\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2><span style=\"color:#f39c12;\">3D<\/span> Projekcija va\u0161eg Waterair bazena<\/h2>\n<p>Stvari brzo postaju konkretne. Pomo\u0107u svog tableta i softverskog programa za pro\u0161irenu stvarnost koji je posebno razvijen od strane Piscines Waterair, va\u0161 savjetnik \u0107e vam pokazati kako \u0107e izgledati va\u0161 vrt s bazenom kojeg ste odabrali!<\/p>\n<p>Studiju provedbe \u0107e realizirati vama najbli\u017ei savjetnik Bazena Waterair, a ona je <b>besplatna, personalizirana i bez obveze<\/b>.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                    <a\tdata-wa=\"button\" data-wa-wave=\"primary\"\n\tclass=\"btn btn--primary mt-3\"\n\t\t\thref=\"#form\"\n\t\ttarget=\"_blank\">\n\t\tTra\u017eim besplatnu studiju provedbe    <\/a>\n                                <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/image-rendez-vous-etude-implantation-piscine-simulee.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"Exemple de rendu de piscine dans le logiciel de r\u00e9alit\u00e9 augment\u00e9e\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/image-rendez-vous-etude-implantation-piscine-simulee.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/image-rendez-vous-etude-implantation-piscine-simulee-1360x765.jpg 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/image-rendez-vous-etude-implantation-piscine-simulee-440x248.jpg 440w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <div  class=\"block-form-catalogue content-block mt-2\" data-tab-section>\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div data-wa=\"fade-up\" class=\"block-form-catalogue__intro text-center h6 col-12 col-md-10 offset-md-1\">\n                        <h2>Besplatna studija provedbe<\/h2>\n                    <\/div>\n                <\/div>\n                                    <div class=\"row pt-10\">\n    <div data-wa=\"fade-up\" class=\"col-12 col-lg-8 offset-lg-2\" data-code-action=\"DMD_EI__\" data-affiliate-form=\"0\" data-source-form-coupon=\"landingpage\">\n        <form id=\"catalogue-form\" action=\"#catalogue-form\" method=\"post\" class=\"adipso-form js-validation-form text-left\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"ffbf03b29e\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/hr\/wp-json\/wp\/v2\/pages\/24248\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7\">Va\u0161i podatci za kontakt<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col mt-4\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Prezime                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-form_name\"\n            name=\"catalogue-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col mt-4\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Ime                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-form_firstname\"\n            name=\"catalogue-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required col\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Po\u0161tanski                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-form_address_postal_code\"\n                        name=\"catalogue-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off504873\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Grad                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-form_address_city\"\n                        name=\"catalogue-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off428698\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u010c\u0106\u0110\u0160\u017d\u00c0\u00c1\u0200\u0202\u0100\u00c8\u00c9\u0204\u0206\u0112\u00cc\u00cd\u0208\u020a\u012a\u00d2\u00d3\u020c\u020e\u014c\u00d9\u00da\u0214\u0216\u016a\u010d\u0107\u0111\u0161\u017e\u00e0\u00e1\u0201\u0203\u0101\u00e8\u00e9\u0205\u0207\u0113\u00ec\u00ed\u0209\u020b\u012b\u00f2\u00f3\u020d\u020f\u014d\u00f9\u00fa\u0215\u0217\u016b\u0154\u0210\u0212\u0155\u0211\u0213()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ku\u0107ni broj i adresa                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-form_address_line_1\"\n                        name=\"catalogue-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off479543\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u010c\u0106\u0110\u0160\u017d\u00c0\u00c1\u0200\u0202\u0100\u00c8\u00c9\u0204\u0206\u0112\u00cc\u00cd\u0208\u020a\u012a\u00d2\u00d3\u020c\u020e\u014c\u00d9\u00da\u0214\u0216\u016a\u010d\u0107\u0111\u0161\u017e\u00e0\u00e1\u0201\u0203\u0101\u00e8\u00e9\u0205\u0207\u0113\u00ec\u00ed\u0209\u020b\u012b\u00f2\u00f3\u020d\u020f\u014d\u00f9\u00fa\u0215\u0217\u016b\u0154\u0210\u0212\u0155\u0211\u0213()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-form[address][language]\" value=\"hr\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t    <div class=\"adipso-form__field adipso-form__field-select2 adipso-form__field--required adipso-form__field-select2--required col mt-4\">\n        \n        <div class=\"input-wrapper\">\n            <select\n                    name=\"catalogue-form[country]\"\n                                 required='required'                                                    data-language=\"en\"\n                    data-init-ajax=\"0\"\n                    data-ajax-args=\"[]\"\n                    data-form-name=\"catalogue-form\"\n                    data-field-name=\"country\"\n            >\n                                    <option\n                            value=\"\"\n                                            >Dr\u017eava<\/option>\n                                                    <option\n                            value=\"ALLEMAGNE\"\n                                            >Deutschland<\/option>\n                                    <option\n                            value=\"ARABIE SAOUDITE\"\n                                            >\u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629<\/option>\n                                    <option\n                            value=\"AUTRICHE\"\n                                            >\u00d6sterreich<\/option>\n                                    <option\n                            value=\"BELGIQUE\"\n                                            >Belgique<\/option>\n                                    <option\n                            value=\"CROATIE\"\n                         selected='selected'                    >Hrvatska<\/option>\n                                    <option\n                            value=\"EMIRATS ARABES UNIS\"\n                                            >United Arab Emirates<\/option>\n                                    <option\n                            value=\"ESPAGNE\"\n                                            >Espa\u00f1a<\/option>\n                                    <option\n                            value=\"FINLANDE\"\n                                            >Suomi<\/option>\n                                    <option\n                            value=\"FRANCE\"\n                                            >France<\/option>\n                                    <option\n                            value=\"GUYANE FRANCAISE\"\n                                            >Guyane<\/option>\n                                    <option\n                            value=\"GUADELOUPE\"\n                                            >Guadeloupe<\/option>\n                                    <option\n                            value=\"HONGRIE\"\n                                            >Magyarorsz\u00e1g<\/option>\n                                    <option\n                            value=\"REUNION\"\n                                            >Ile de la R\u00e9union<\/option>\n                                    <option\n                            value=\"ITALIE\"\n                                            >Italia<\/option>\n                                    <option\n                            value=\"LUXEMBOURG\"\n                                            >Luxembourg<\/option>\n                                    <option\n                            value=\"MARTINIQUE\"\n                                            >Martinique<\/option>\n                                    <option\n                            value=\"PAYS BAS\"\n                                            >Nederland<\/option>\n                                    <option\n                            value=\"POLOGNE\"\n                                            >Polska<\/option>\n                                    <option\n                            value=\"POLYNESIE FRANCAISE\"\n                                            >Polyn\u00e9sie<\/option>\n                                    <option\n                            value=\"PORTUGAL\"\n                                            >Portugal<\/option>\n                                    <option\n                            value=\"REPUBLIQUE TCHEQUE\"\n                                            >\u010cesk\u00e1 republika<\/option>\n                                    <option\n                            value=\"ROUMANIE\"\n                                            >Rom\u00e2nia<\/option>\n                                    <option\n                            value=\"ROYAUME UNI\"\n                                            >United Kingdom<\/option>\n                                    <option\n                            value=\"SUEDE\"\n                                            >Sverige<\/option>\n                                    <option\n                            value=\"SUISSE\"\n                                            >Suisse<\/option>\n                                    <option\n                            value=\"SLOVAQUIE\"\n                                            >Slovensko<\/option>\n                                    <option\n                            value=\"TUNISIE\"\n                                            >Tunisie<\/option>\n                            <\/select>\n\n                    <\/div>\n\n            <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col mt-4\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Telefon                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-form_phone\"\n            name=\"catalogue-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Telefonski broj mora imati barem \u0161est znakova.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col mt-4\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-form_email\"\n            name=\"catalogue-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 \">Kako biste \u017eeljeli primiti svoj katalog? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format inverted \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_catalogue_format_paper\"\n                    name=\"catalogue-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Po\u0161tom na moju ku\u0107nu adresu<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_catalogue_format_digital\"\n                    name=\"catalogue-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>E-po\u0161tom u digitalnom formatu<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6\">Adresa mojeg projekta<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            Adresa mojeg projekta ista je kao moja osobna adresa        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_second_address_non\"\n                    name=\"catalogue-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Da<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_second_address_oui\"\n                    name=\"catalogue-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Ne<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address col mt-4 adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Po\u0161tanski                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-form_project_address_postal_code\"\n                        name=\"catalogue-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off465178\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Grad                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-form_project_address_city\"\n                        name=\"catalogue-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off702767\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u010c\u0106\u0110\u0160\u017d\u00c0\u00c1\u0200\u0202\u0100\u00c8\u00c9\u0204\u0206\u0112\u00cc\u00cd\u0208\u020a\u012a\u00d2\u00d3\u020c\u020e\u014c\u00d9\u00da\u0214\u0216\u016a\u010d\u0107\u0111\u0161\u017e\u00e0\u00e1\u0201\u0203\u0101\u00e8\u00e9\u0205\u0207\u0113\u00ec\u00ed\u0209\u020b\u012b\u00f2\u00f3\u020d\u020f\u014d\u00f9\u00fa\u0215\u0217\u016b\u0154\u0210\u0212\u0155\u0211\u0213()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ku\u0107ni broj i adresa                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-form_project_address_line_1\"\n                        name=\"catalogue-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off315878\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u010c\u0106\u0110\u0160\u017d\u00c0\u00c1\u0200\u0202\u0100\u00c8\u00c9\u0204\u0206\u0112\u00cc\u00cd\u0208\u020a\u012a\u00d2\u00d3\u020c\u020e\u014c\u00d9\u00da\u0214\u0216\u016a\u010d\u0107\u0111\u0161\u017e\u00e0\u00e1\u0201\u0203\u0101\u00e8\u00e9\u0205\u0207\u0113\u00ec\u00ed\u0209\u020b\u012b\u00f2\u00f3\u020d\u020f\u014d\u00f9\u00fa\u0215\u0217\u016b\u0154\u0210\u0212\u0155\u0211\u0213()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-form[project_address][language]\" value=\"hr\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t    <div class=\"adipso-form__field adipso-form__field-select2 col mt-4\">\n        \n        <div class=\"input-wrapper\">\n            <select\n                    name=\"catalogue-form[project_country]\"\n                                                                                    data-language=\"en\"\n                    data-init-ajax=\"0\"\n                    data-ajax-args=\"[]\"\n                    data-form-name=\"catalogue-form\"\n                    data-field-name=\"project_country\"\n            >\n                                    <option\n                            value=\"\"\n                                            >Dr\u017eava<\/option>\n                                                    <option\n                            value=\"ALLEMAGNE\"\n                                            >Deutschland<\/option>\n                                    <option\n                            value=\"ARABIE SAOUDITE\"\n                                            >\u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629<\/option>\n                                    <option\n                            value=\"AUTRICHE\"\n                                            >\u00d6sterreich<\/option>\n                                    <option\n                            value=\"BELGIQUE\"\n                                            >Belgique<\/option>\n                                    <option\n                            value=\"CROATIE\"\n                         selected='selected'                    >Hrvatska<\/option>\n                                    <option\n                            value=\"EMIRATS ARABES UNIS\"\n                                            >United Arab Emirates<\/option>\n                                    <option\n                            value=\"ESPAGNE\"\n                                            >Espa\u00f1a<\/option>\n                                    <option\n                            value=\"FINLANDE\"\n                                            >Suomi<\/option>\n                                    <option\n                            value=\"FRANCE\"\n                                            >France<\/option>\n                                    <option\n                            value=\"GUYANE FRANCAISE\"\n                                            >Guyane<\/option>\n                                    <option\n                            value=\"GUADELOUPE\"\n                                            >Guadeloupe<\/option>\n                                    <option\n                            value=\"HONGRIE\"\n                                            >Magyarorsz\u00e1g<\/option>\n                                    <option\n                            value=\"REUNION\"\n                                            >Ile de la R\u00e9union<\/option>\n                                    <option\n                            value=\"ITALIE\"\n                                            >Italia<\/option>\n                                    <option\n                            value=\"LUXEMBOURG\"\n                                            >Luxembourg<\/option>\n                                    <option\n                            value=\"MARTINIQUE\"\n                                            >Martinique<\/option>\n                                    <option\n                            value=\"PAYS BAS\"\n                                            >Nederland<\/option>\n                                    <option\n                            value=\"POLOGNE\"\n                                            >Polska<\/option>\n                                    <option\n                            value=\"POLYNESIE FRANCAISE\"\n                                            >Polyn\u00e9sie<\/option>\n                                    <option\n                            value=\"PORTUGAL\"\n                                            >Portugal<\/option>\n                                    <option\n                            value=\"REPUBLIQUE TCHEQUE\"\n                                            >\u010cesk\u00e1 republika<\/option>\n                                    <option\n                            value=\"ROUMANIE\"\n                                            >Rom\u00e2nia<\/option>\n                                    <option\n                            value=\"ROYAUME UNI\"\n                                            >United Kingdom<\/option>\n                                    <option\n                            value=\"SUEDE\"\n                                            >Sverige<\/option>\n                                    <option\n                            value=\"SUISSE\"\n                                            >Suisse<\/option>\n                                    <option\n                            value=\"SLOVAQUIE\"\n                                            >Slovensko<\/option>\n                                    <option\n                            value=\"TUNISIE\"\n                                            >Tunisie<\/option>\n                            <\/select>\n\n                    <\/div>\n\n            <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html is-hide\">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title js-sponsor-container h7 mt-6\">Dolazim po preporuci sponzora<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-4 js-sponsor-container is-hide\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col js-display-field js-display-field--sponsor1 js-sponsor-container\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-form_sponsor_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_sponsor_oui\"\n                    name=\"catalogue-form[sponsor]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Da<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_sponsor_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_sponsor_non\"\n                    name=\"catalogue-form[sponsor]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Ne<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor1_wrapper is-hide mt-3 mb-2\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Prezime                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-form_sponsor_name\"\n            name=\"catalogue-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col mt-4 mt-sm-0 adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ime                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-form_sponsor_firstname\"\n            name=\"catalogue-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-4\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Po\u0161tanski                    <\/label>\n        <input\n            autocomplete=\"off775934\"            type=\"text\"\n            id=\"catalogue-form_sponsor_zip_code\"\n            name=\"catalogue-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off527103\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col mt-4 mt-sm-0 adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Grad                    <\/label>\n        <input\n            autocomplete=\"off756807\"            type=\"text\"\n            id=\"catalogue-form_sponsor_city\"\n            name=\"catalogue-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off585350\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-4\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ku\u0107ni broj i adresa                    <\/label>\n        <input\n            autocomplete=\"off755035\"            type=\"text\"\n            id=\"catalogue-form_sponsor_street_address\"\n            name=\"catalogue-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off591555\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n    <div class=\"adipso-form__field adipso-form__field-select2 col mt-4 mt-sm-0 adipso-form__field--required\">\n        \n        <div class=\"input-wrapper\">\n            <select\n                    name=\"catalogue-form[sponsor_country]\"\n                                                                                    data-language=\"en\"\n                    data-init-ajax=\"0\"\n                    data-ajax-args=\"[]\"\n                    data-form-name=\"catalogue-form\"\n                    data-field-name=\"sponsor_country\"\n            >\n                                    <option\n                            value=\"\"\n                         selected='selected'                    >Dr\u017eava<\/option>\n                                                    <option\n                            value=\"ALLEMAGNE\"\n                                            >Deutschland<\/option>\n                                    <option\n                            value=\"ARABIE SAOUDITE\"\n                                            >\u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629<\/option>\n                                    <option\n                            value=\"AUTRICHE\"\n                                            >\u00d6sterreich<\/option>\n                                    <option\n                            value=\"BELGIQUE\"\n                                            >Belgique<\/option>\n                                    <option\n                            value=\"CROATIE\"\n                                            >Hrvatska<\/option>\n                                    <option\n                            value=\"EMIRATS ARABES UNIS\"\n                                            >United Arab Emirates<\/option>\n                                    <option\n                            value=\"ESPAGNE\"\n                                            >Espa\u00f1a<\/option>\n                                    <option\n                            value=\"FINLANDE\"\n                                            >Suomi<\/option>\n                                    <option\n                            value=\"FRANCE\"\n                                            >France<\/option>\n                                    <option\n                            value=\"GUYANE FRANCAISE\"\n                                            >Guyane<\/option>\n                                    <option\n                            value=\"GUADELOUPE\"\n                                            >Guadeloupe<\/option>\n                                    <option\n                            value=\"HONGRIE\"\n                                            >Magyarorsz\u00e1g<\/option>\n                                    <option\n                            value=\"REUNION\"\n                                            >Ile de la R\u00e9union<\/option>\n                                    <option\n                            value=\"ITALIE\"\n                                            >Italia<\/option>\n                                    <option\n                            value=\"LUXEMBOURG\"\n                                            >Luxembourg<\/option>\n                                    <option\n                            value=\"MARTINIQUE\"\n                                            >Martinique<\/option>\n                                    <option\n                            value=\"PAYS BAS\"\n                                            >Nederland<\/option>\n                                    <option\n                            value=\"POLOGNE\"\n                                            >Polska<\/option>\n                                    <option\n                            value=\"POLYNESIE FRANCAISE\"\n                                            >Polyn\u00e9sie<\/option>\n                                    <option\n                            value=\"PORTUGAL\"\n                                            >Portugal<\/option>\n                                    <option\n                            value=\"REPUBLIQUE TCHEQUE\"\n                                            >\u010cesk\u00e1 republika<\/option>\n                                    <option\n                            value=\"ROUMANIE\"\n                                            >Rom\u00e2nia<\/option>\n                                    <option\n                            value=\"ROYAUME UNI\"\n                                            >United Kingdom<\/option>\n                                    <option\n                            value=\"SUEDE\"\n                                            >Sverige<\/option>\n                                    <option\n                            value=\"SUISSE\"\n                                            >Suisse<\/option>\n                                    <option\n                            value=\"SLOVAQUIE\"\n                                            >Slovensko<\/option>\n                                    <option\n                            value=\"TUNISIE\"\n                                            >Tunisie<\/option>\n                            <\/select>\n\n                    <\/div>\n\n            <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-4\">\n\t<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Telefon                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-form_sponsor_phone\"\n            name=\"catalogue-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Telefonski broj mora imati barem \u0161est znakova.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col mt-4 mt-sm-0 adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Broj kupca                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-form_sponsor_client_id\"\n            name=\"catalogue-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_do_it_yourself_oui\"\n                    name=\"catalogue-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Da<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_do_it_yourself_non\"\n                    name=\"catalogue-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Ne<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_time_limit_maintenant\"\n                    name=\"catalogue-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-form_time_limit_plus_tard\"\n                    name=\"catalogue-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Ovla\u0161\u0107ujem Waterair da mi dostavlja cjenike, digitalni katalog i promocije :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">E-po\u0161tom<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">SMS-om<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\">Offres commerciales revendeurs<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Va\u0161i su podatci ustupljeni na\u0161em ekskluzivnom zastupniku poduze\u0107a Piscines Waterair za va\u0161u dr\u017eavu.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[lang]\"\n\tvalue=\"hr\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[affiliate_form]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Po\u0161alji zahtjev<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">Polja ozna\u010dena zvjezdicom* su obvezna<br \/>\r\nGroupe Waterair prikuplja Va\u0161e podatke u okviru va\u0161eg zahtjeva. Za vi\u0161e informacija pogledajte na\u0161u politiku privatnosti koja je dostupna na dnu na\u0161e internetske stranice.<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n    <\/div>\n<\/div>\n        <\/div>\n    <\/div>\n\n\n<div  class=\"block-chiffres  content-block\">\n\t\t\t<svg class=\"content-block__wave\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" preserveAspectRatio=\"none\" width=\"792\" height=\"113\" viewBox=\"0 0 792 113\">\n\t\t\t<path fill=\"#0080C8\" d=\"M431.725539,-340.566487 C409.271632,-304.562081 392.525634,-252.714767 387.640542,-179.798441 C369.042596,122.812782 497.396885,38.5205026 497.396885,452.206968 C497.55866,212.705563 497.186394,-340.754832 497.396885,-340.566487 C497.607458,-340.372208 431.896885,-340.551731 431.725539,-340.566487 Z\" transform=\"matrix(0 1 1 0 340.564 -384.897)\"\/>\n\t\t<\/svg>\n\t\t<div class=\"content-block__wrapper\">\n\t\t\t<div class=\"container\">\n\t\t\t\t<div class=\"row justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-lg-7\">\n\t\t\t\t\t\t\t<h2 data-wa=\"fade-up\" class=\"content-block__title h1 text-inherit mb-0\">Vode\u0107i proizvo\u0111a\u010d kompleta bazena u Europi<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"200\" class=\"row justify-content-center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-block__number col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__value\"><span data-wa=\"counter\">30<\/span> godina<\/p>\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__label\">jamstvo na konstrukciju*<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-block__number col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__value\">+<span data-wa=\"counter\">50<\/span> godina<\/p>\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__label\">iskustva proizvo\u0111a\u010da<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-block__number col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__value\">+<span data-wa=\"counter\">20<\/span>%<\/p>\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__label\">vrijednost imovine<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content-block__number col-md-6 col-lg-3\">\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__value\"><span data-wa=\"counter\">139 000<\/span><\/p>\n\t\t\t\t\t\t\t\t<p class=\"content-block__number__label\">zadovoljnih kupaca<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/08\/made-in-france.svg\" width=\"120\" height=\"120\" class=\"content-block__picto\" alt=\"\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"content-block__wave-outline-1\">\n\t\t\t<svg width=\"678\" height=\"589\" viewBox=\"0 0 1000 1000\">\n\t\t\t\t<path fill=\"none\" stroke=\"#FFF\" stroke-width=\"2\" opacity=\".2\" data-blob='{\"minRadius\": \"430\",\"maxRadius\":\"490\", \"numPoints\": \"16\"}'><\/path>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t\t<div class=\"content-block__wave-outline-2\">\n\t\t\t<svg width=\"678\" height=\"589\" viewBox=\"0 0 1000 1000\">\n\t\t\t\t<path fill=\"none\" stroke=\"#FFF\" stroke-width=\"2\" opacity=\".2\" data-blob='{\"minRadius\": \"430\",\"maxRadius\":\"490\", \"numPoints\": \"16\"}'><\/path>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p class=\"legend\">(1) Navo\u0111enjem svoje adrese e-po\u0161te, mogli biste primati komercijalne informacije od tvrtke Bazeni Waterair. Pretplatu mo\u017eete otkazati u svakom trenutku klikom na poveznicu koju \u0107ete primiti sa svakom e-po\u0161tom. Imate pravo pristupiti, mijenjati, ispravljati i brisati podatke koji se odnose na vas (\u010dl. 34. Zakona o za\u0161titi podataka). Da biste iskoristili ovo pravo obratite se slu\u017ebi za korisnike na Service Communication &#8211; Piscines Waterair ZA &#8211; INT &#8211; 68580 Seppois-le-Bas.<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p class=\"notice\">\u00a9 Autori fotografija: Thierry Foulon, Dominique Gianelli.<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p class=\"notice\">* Obavezna polja.<\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p class=\"notice\">** Plo\u010de Waterair imaju jamstvo na 20 godina. Bez umanjivanja. U skladu s na\u0161im op\u0107im uvjetima jamstva.<\/p>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>U\u017eivajte u ugodi vode jo\u0161 ovog ljeta! (1) Navo\u0111enjem svoje adrese e-po\u0161te, mogli biste primati komercijalne informacije od tvrtke Bazeni Waterair. Pretplatu mo\u017eete otkazati u svakom trenutku klikom na poveznicu koju \u0107ete primiti sa svakom e-po\u0161tom. Imate pravo pristupiti, mijenjati, ispravljati i brisati podatke koji se odnose na vas (\u010dl. 34. Zakona o za\u0161titi podataka). [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21675,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"models\/landing.php","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-24248","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>U\u017eivajte u ugodi vode | Bazeni Waterair<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"hr_HR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obiteljska sre\u0107a\" \/>\n<meta property=\"og:description\" content=\"U\u017eivajte u ugodi vode jo\u0161 ovog ljeta! (1) Navo\u0111enjem svoje adrese e-po\u0161te, mogli biste primati komercijalne informacije od tvrtke Bazeni Waterair. Pretplatu mo\u017eete otkazati u svakom trenutku klikom na poveznicu koju \u0107ete primiti sa svakom e-po\u0161tom. Imate pravo pristupiti, mijenjati, ispravljati i brisati podatke koji se odnose na vas (\u010dl. 34. Zakona o za\u0161titi podataka). [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca\" \/>\n<meta property=\"og:site_name\" content=\"Bazeni Waterair\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-02T16:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca\",\"url\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca\",\"name\":\"U\u017eivajte u ugodi vode | Bazeni Waterair\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/hr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg\",\"datePublished\":\"2021-10-24T22:23:46+00:00\",\"dateModified\":\"2021-12-02T16:06:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#breadcrumb\"},\"inLanguage\":\"hr-HR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hr-HR\",\"@id\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg\",\"width\":1920,\"height\":747},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Po\u010detna stranica\",\"item\":\"https:\/\/www.waterair.com\/hr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Obiteljska sre\u0107a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/hr\/#website\",\"url\":\"https:\/\/www.waterair.com\/hr\/\",\"name\":\"Bazeni Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/hr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hr-HR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"U\u017eivajte u ugodi vode | Bazeni Waterair","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"hr_HR","og_type":"article","og_title":"Obiteljska sre\u0107a","og_description":"U\u017eivajte u ugodi vode jo\u0161 ovog ljeta! (1) Navo\u0111enjem svoje adrese e-po\u0161te, mogli biste primati komercijalne informacije od tvrtke Bazeni Waterair. Pretplatu mo\u017eete otkazati u svakom trenutku klikom na poveznicu koju \u0107ete primiti sa svakom e-po\u0161tom. Imate pravo pristupiti, mijenjati, ispravljati i brisati podatke koji se odnose na vas (\u010dl. 34. Zakona o za\u0161titi podataka). [&hellip;]","og_url":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca","og_site_name":"Bazeni Waterair","article_modified_time":"2021-12-02T16:06:08+00:00","og_image":[{"width":1920,"height":747,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca","url":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca","name":"U\u017eivajte u ugodi vode | Bazeni Waterair","isPartOf":{"@id":"https:\/\/www.waterair.com\/hr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg","datePublished":"2021-10-24T22:23:46+00:00","dateModified":"2021-12-02T16:06:08+00:00","breadcrumb":{"@id":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#breadcrumb"},"inLanguage":"hr-HR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca"]}]},{"@type":"ImageObject","inLanguage":"hr-HR","@id":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/ambiance-piscine-famille-diner.jpg","width":1920,"height":747},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/hr\/lp\/obiteljska-sreca#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Po\u010detna stranica","item":"https:\/\/www.waterair.com\/hr"},{"@type":"ListItem","position":2,"name":"Obiteljska sre\u0107a"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/hr\/#website","url":"https:\/\/www.waterair.com\/hr\/","name":"Bazeni Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hr-HR"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/pages\/24248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/comments?post=24248"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/pages\/24248\/revisions"}],"predecessor-version":[{"id":100614,"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/pages\/24248\/revisions\/100614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/media\/21675"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/hr\/wp-json\/wp\/v2\/media?parent=24248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}