{"id":21493,"date":"2021-10-18T17:49:58","date_gmt":"2021-10-18T15:49:58","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/securite\/couverture-piscine-solae-2"},"modified":"2026-01-23T14:35:39","modified_gmt":"2026-01-23T13:35:39","slug":"couverture-piscine-solae-2","status":"publish","type":"equipment-security","link":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae","title":{"rendered":"Solae Waterair\u00ae : Couverture de piscine solaire multi-usages"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>La couverture solaire multi-usages Solae Waterair<sup>\u00ae<\/sup> est une innovation exclusive et brevet\u00e9e<\/p>\n<\/div><\/div><\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p>Cette nouvelle g\u00e9n\u00e9ration de couvertures de piscine cumule de nombreuses fonctions :<\/p>\n<ul>\n<li><strong>Le chauffage de votre piscine<\/strong> avec un gain jusqu\u2019\u00e0 9\u00b0* gr\u00e2ce \u00e0 l\u2019\u00e9nergie solaire par effet de serre<\/li>\n<li><strong>La s\u00e9curit\u00e9<\/strong>, en \u00e9tant conforme \u00e0 la norme NF P90-308<\/li>\n<li><strong>La simplicit\u00e9<\/strong> : facile \u00e0 enrouler gr\u00e2ce \u00e0 son enrouleur \u00e9lectrique fourni<\/li>\n<li><strong>L&#8217;entretien facile<\/strong> : elle prot\u00e8ge la piscine des impuret\u00e9s ext\u00e9rieures<\/li>\n<li><strong>L&#8217;hivernage<\/strong> : ses modules opaques \u00e9vitent la photosynth\u00e8se en hiver pour une remise en service facilit\u00e9e<\/li>\n<\/ul>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p><strong>Labellis\u00e9 eco\u00b7r, Solae Waterair<sup>\u00ae<\/sup> est un produit con\u00e7u dans une logique \u00e9conologique et de d\u00e9veloppement durable<\/strong> afin de respecter l\u2019environnement et de vous apporter un maximum de confort.<\/p>\n<p>Une innovation majeure, <strong>particuli\u00e8rement \u00e9conomique, permettant de prolonger la p\u00e9riode des baignades de mani\u00e8re significative<\/strong>.<br \/>\n<em>* r\u00e9sultat constat\u00e9 par huissier<\/em><\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-3  \">\n                                <div class=\"content-block__media   is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"555\" height=\"312\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor.jpg 555w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor-1360x765.jpg 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/logo-ecor-440x247.jpg 440w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div data-wa=\"fade-up\"  class=\"block-media  content-block\">\n\t\t\t<div class=\"container\">\n\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-12 col-md-10 offset-md-1\">\n                                            <div class=\"content-block__media\">\n                                                                                                <button\n                                            class=\"content-block__button\"\n                                            data-video='{\"provider\": \"vimeo\", \"id\": \"413088345\", \"poster\": \"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/vignette-solae-1-1340x1260.png\"}'\n                                    >\n                                        Voir la vid\u00e9o                                        <i class=\"app-icon app-icon-play-fill app-icon--sm\"><\/i>\n                                    <\/button>\n                                \n                                <img decoding=\"async\"\n                                        src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/vignette-solae-1-920x518.png\"\n                                        srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/vignette-solae-1-1840x1035.png 2x\"\n                                        alt=\"\"\n                                >\n                                                    <\/div>\n                                    <\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                            \t<\/div>\n\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Solae Waterair<sup>\u00ae<\/sup> : un concept ing\u00e9nieux et innovant<\/h2>\n<ol>\n<li>Des filets, des barres en aluminium et un cadre technique pour assurer la s\u00e9curit\u00e9 de votre piscine<\/li>\n<li>des panneaux translucides qui se glissent entre les barres qui gr\u00e2ce \u00e0 l\u2019effet de serre augmente la temp\u00e9rature de votre eau<\/li>\n<li>des panneaux opaques qui remplacent les panneaux translucides pour hiverner votre piscine et \u00e9viter la photosynth\u00e8se<\/li>\n<\/ol>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"622\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-880x622.webp\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-880x622.webp 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-1440x1018.webp 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-2037x1440.webp 2037w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-768x543.webp 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-1536x1086.webp 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-2048x1448.webp 2048w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-440x311.webp 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-1840x1301.webp 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2024\/02\/waterair-plaquette-solae-fr-print-schema-920x650.webp 920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Chauffez votre piscine gratuitement jusqu\u2019\u00e0 +9\u00b0C<\/h2>\n<p>Compos\u00e9e de panneaux translucides, la couverture Solae Waterair<sup>\u00ae<\/sup> permet de <strong>chauffer naturellement et gratuitement votre piscine<\/strong> par effet de serre. Elle augmente la temp\u00e9rature de l\u2019eau jusqu\u2019\u00e0 +9\u00b0C (r\u00e9sultats constat\u00e9s et authentifi\u00e9s par Ma\u00eetre Corbari, huissier de justice). <strong>Prolongez la saison de baignade<\/strong> d\u2019avril \u00e0 octobre (selon les r\u00e9gions) gr\u00e2ce \u00e0 ces degr\u00e9s suppl\u00e9mentaires.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-3  \">\n                                <div class=\"content-block__media   is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"550\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-880x550.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-880x550.jpg 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-1440x900.jpg 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-768x480.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-1536x960.jpg 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-440x275.jpg 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-1840x1150.jpg 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2-920x575.jpg 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-solaire-2.jpg 1920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>S\u00e9curisez votre piscine<\/h2>\n<p>Solae Waterair<sup>\u00ae<\/sup> est con\u00e7ue pour <strong>garantir la s\u00e9curit\u00e9<\/strong> autour de votre piscine. Gr\u00e2ce aux filets et aux barres en aluminium, cette couverture de piscine r\u00e9pond aux exigences de s\u00e9curit\u00e9 de la norme en vigueur (NF P90-308). Les filets permettent \u00e9galement de <strong>r\u00e9guler en toute tranquillit\u00e9 la temp\u00e9rature de l\u2019eau<\/strong> de votre piscine. Par forte chaleur, il vous suffit de retirer un ou plusieurs panneaux translucides. Les filets continuent de s\u00e9curiser la piscine.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Prot\u00e9gez efficacement votre piscine<\/h2>\n<p>Solae Waterair<sup>\u00ae<\/sup> est v\u00e9ritablement une <strong>couverture multifonctions<\/strong>. Les panneaux translucides assurent la protection de votre piscine des pollutions ext\u00e9rieures. Par ailleurs, la couverture recouvre l\u2019ensemble de la piscine ainsi qu\u2019une partie de la plage, maintenant ainsi la propret\u00e9 de votre eau de baignade. <strong>Couvrir votre piscine apr\u00e8s chaque baignade vous permet de<\/strong> :<\/p>\n<ul>\n<li>limiter l\u2019usage des produits d\u2019entretien<\/li>\n<li>limiter l\u2019\u00e9vaporation de l\u2019eau<\/li>\n<li>limiter la fr\u00e9quence d\u2019entretien<\/li>\n<li>chauffer l\u2019eau gratuitement<\/li>\n<\/ul>\n<p>Un entretien simplifi\u00e9, \u00e9conomique et \u00e9cologique vous assure une eau claire et cristalline.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-3  \">\n                                <div class=\"content-block__media   is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"495\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-880x495.webp\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-880x495.webp 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-1440x809.webp 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-768x432.webp 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-1536x863.webp 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-1360x765.webp 1360w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-440x247.webp 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-1840x1034.webp 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse-920x517.webp 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/piscine-rectangle-vue-drone-nageuse.webp 2000w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Une installation adapt\u00e9e \u00e0 tout type de piscine<\/h2>\n<p>La mise en \u0153uvre de Solae Waterair<sup>\u00ae<\/sup> est tr\u00e8s simple : selon la largeur de la piscine, 3 \u00e0 4 pitons \u00e0 chaque extr\u00e9mit\u00e9 suffiront pour assurer sa mise en tension. Universelle, Solae Waterair<sup>\u00ae<\/sup> <strong>couvre toutes les piscines<\/strong> allant jusqu\u2019\u00e0 10,70 m de longueur et 52 m<sup>2<\/sup> de surface, quelle que soit la marque ou la forme.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"550\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-880x550.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-880x550.jpg 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-1440x900.jpg 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-768x480.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-1536x960.jpg 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-440x275.jpg 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-1840x1150.jpg 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre-920x575.jpg 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-piscine-forme-libre.jpg 1920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-12 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Couvrir et d\u00e9couvrir votre piscine est simple et rapide !<\/h2>\n<p>Une fois ferm\u00e9e en bout de piscine, Solae Waterair<sup>\u00ae<\/sup> occupe peu d\u2019espace. Elle se fait donc <strong>discr\u00e8te pour pr\u00e9server l\u2019esth\u00e9tique<\/strong> de votre piscine et son environnement. Une sangle suffit pour d\u00e9rouler Solae Waterair<sup>\u00ae<\/sup> et couvrir votre piscine. Pour la s\u00e9curiser, vous disposez de cliquets de fixation ergonomiques afin de tendre la couverture ais\u00e9ment.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row align-items-center\">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Hivernez votre piscine en toute s\u00e9r\u00e9nit\u00e9<\/h2>\n<p>Pour \u00e9viter la photosynth\u00e8se et la prolif\u00e9ration d\u2019algues, la couverture Solae Waterair<sup>\u00ae<\/sup> est \u00e9quip\u00e9e de panneaux opaques qui viennent en remplacement des panneaux translucides. Ainsi, elle <strong>facilite la remise en service<\/strong> de votre piscine au printemps.<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  is-not-absolute\">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"550\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-880x550.jpg\" class=\"attachment-content_media_2x size-content_media_2x\" alt=\"como invernar con \u00e9xito mi piscina\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-880x550.jpg 880w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-1440x900.jpg 1440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-768x480.jpg 768w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-1536x960.jpg 1536w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-440x275.jpg 440w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-1840x1150.jpg 1840w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine-920x575.jpg 920w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/couverture-hivernage-piscine.jpg 1920w\" sizes=\"auto, (max-width: 880px) 100vw, 880px\" \/>                                                                                    <\/span>\n                                                                        \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/accessoires-de-piscine\/enrouleur-derouleur-automatique\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">ED, l&#8217;enrouleur-d\u00e9rouleur de couverture \u00e0 barres<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>D\u00e9couvrez ED, la solution id\u00e9ale pour automatiser l&#8217;enroulement et le d\u00e9roulement de votre couverture \u00e0 barres.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-540x540.jpg\" class=\"attachment-card size-card\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/enrouleur-automatique-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>Jetez-vous \u00e0 l&#8217;eau ! <\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_CATA\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"a12b41798d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/mq\/wp-json\/wp\/v2\/equipment-security\/21493\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Nom                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Pr\u00e9nom                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Code postal                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off374545\"\n                         required='required'                                                                        maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ville                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off823726\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Num\u00e9ro et rue                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off626198\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{5,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"mq\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            T\u00e9l\u00e9phone                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Le num\u00e9ro de t\u00e9l\u00e9phone doit contenir au minimum 6 caract\u00e8res.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 is-hide\">Comment souhaitez-vous recevoir votre catalogue ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                     checked='checked'                \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Par courrier \u00e0 mon domicile<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>Par e-mail en format num\u00e9rique<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Adresse du projet<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            L\u2018adresse de mon projet est identique \u00e0 mon adresse personnelle        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Oui<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Non<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Code postal                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off521944\"\n                                                                                                maxlength=\"5\"\n                        pattern=\"^[0-9]{5}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ville                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off288748\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Num\u00e9ro et rue                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off369318\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00c0\u00c2\u00c6\u00c7\u00c9\u00c8\u00ca\u00cb\u00ce\u00cf\u00d4\u0152\u00d9\u00db\u00dc\u0178\u00e0\u00e2\u00e6\u00e7\u00e9\u00e8\u00ea\u00eb\u00ee\u00ef\u00f4\u0153\u00f9\u00fb\u00fc\u00ff()\\-\/\\.,&#039;]{5,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"mq\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"MARTINIQUE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nom                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Pr\u00e9nom                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Code postal                    <\/label>\n        <input\n            autocomplete=\"off760851\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off258929\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Num\u00e9ro et rue                    <\/label>\n        <input\n            autocomplete=\"off568558\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off144126\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ville                    <\/label>\n        <input\n            autocomplete=\"off190857\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off606089\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            T\u00e9l\u00e9phone                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Le num\u00e9ro de t\u00e9l\u00e9phone doit contenir au minimum 6 caract\u00e8res.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Num\u00e9ro de client Waterair                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Oui<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Non<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">J\u2019autorise Waterair \u00e0 me faire parvenir les tarifs, le catalogue num\u00e9rique et les promotions :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Par e-mail<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Par SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Vos coordonn\u00e9es sont transf\u00e9r\u00e9es \u00e0 notre revendeur exclusif Piscines Waterair dans votre pays.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Je viens de la part d&#8217;un parrain<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"mq\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Envoyer la demande<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\tLes champs marqu\u00e9s d&#8217;un * sont obligatoires.<br \/>\r\nVos donn\u00e9es sont collect\u00e9es par Groupe Waterair dans le cadre de votre demande. Pour plus d&#8217;informations, veuillez consulter notre politique de confidentialit\u00e9 disponible en bas de page de notre site internet\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n<div  class=\"block-links  content-block\">\n\t\t\t\t\t\t<div class=\"container mb-md-8 mb-4\">\n\t\t\t\t<div class=\"row align-items-end\">\n\t\t\t\t\t<div class=\"col-12\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 data-wa=\"fade-up\" class=\"content-block__title mb-0\">Les autres \u00e9quipements de s\u00e9curit\u00e9 piscine<\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div data-wa=\"fade-up\" data-wa-delay=\"300\" class=\"content-block__slider splide\" data-splide>\n\t\t\t\t<div class=\"splide__track\">\n\t\t\t\t\t<div class=\"splide__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/barrieres\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Barri\u00e8res piscine<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Barri\u00e8res de s\u00e9curit\u00e9 pour piscine souples ou rigides, con\u00e7ues pour emp\u00eacher les jeunes enfants d&#8217;acc\u00e9der \u00e0 la piscine.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Barri\u00e8re pour s\u00e9curiser sa piscine\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/barriere-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a data-wa=\"fade-up\" href=\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine\" class=\"item-card is-size-card splide__slide has-description\">\n\t<div class=\"item-card__infos item-card__infos--simple\">\n\t\t<h3 class=\"item-card__title mb-0 c-white\">Couverture piscine s\u00e9curis\u00e9es<\/h3>\n\t\t\t\t\t\t\t\t\t<div class=\"item-card__description mb-0\"><p>Se baigner en famille ou entre amis passe avant tout par la s\u00e9curit\u00e9 de tous. La loi pr\u00e9voit une r\u00e9glementation stricte par rapport \u00e0 la s\u00e9curit\u00e9 des piscines priv\u00e9es enterr\u00e9es. Parmi les \u00e9quipements de s\u00e9curit\u00e9 qui s\u2019offrent \u00e0 vous, d\u00e9couvrez les couvertures de piscines et leurs avantages.<\/p>\r\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-540x540.jpg\" class=\"attachment-card size-card\" alt=\"Couverture de piscine coverwat Waterair\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-540x540.jpg 540w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-1080x1080.jpg 1080w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-480x480.jpg 480w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-240x240.jpg 240w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-150x150.jpg 150w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-75x75.jpg 75w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-780x780.jpg 780w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-390x390.jpg 390w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-320x320.jpg 320w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/securite-piscine-couverture-coverwat-160x160.jpg 160w\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" \/><\/a>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>La couverture solaire multi-usages Solae Waterair\u00ae est une innovation exclusive et brevet\u00e9e<\/p>\n","protected":false},"featured_media":21024,"template":"","class_list":["post-21493","equipment-security","type-equipment-security","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Couverture de Piscine Solaire Multi-Usages Solae Waterair\u00ae | Piscines Waterair<\/title>\n<meta name=\"description\" content=\"Innovation exclusive brevet\u00e9e par Piscines Waterair, d\u00e9couvrez notre couverture multi-usage et quatre saisons qui allie chauffage, protection, s\u00e9curit\u00e9 et hivernage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solae Waterair\u00ae : Couverture de piscine solaire multi-usages\" \/>\n<meta property=\"og:description\" content=\"Innovation exclusive brevet\u00e9e par Piscines Waterair, d\u00e9couvrez notre couverture multi-usage et quatre saisons qui allie chauffage, protection, s\u00e9curit\u00e9 et hivernage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae\" \/>\n<meta property=\"og:site_name\" content=\"Piscines Waterair\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T13:35:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae\",\"url\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae\",\"name\":\"Couverture de Piscine Solaire Multi-Usages Solae Waterair\u00ae | Piscines Waterair\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/mq\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg\",\"datePublished\":\"2021-10-18T15:49:58+00:00\",\"dateModified\":\"2026-01-23T13:35:39+00:00\",\"description\":\"Innovation exclusive brevet\u00e9e par Piscines Waterair, d\u00e9couvrez notre couverture multi-usage et quatre saisons qui allie chauffage, protection, s\u00e9curit\u00e9 et hivernage.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#breadcrumb\"},\"inLanguage\":\"fr-MQ\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-MQ\",\"@id\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg\",\"width\":1920,\"height\":1200,\"caption\":\"Piscine enterr\u00e9e Sara + couverture de piscine Solae\u00ae Waterair\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.waterair.com\/mq\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9curit\u00e9\",\"item\":\"https:\/\/www.waterair.com\/mq\/securite\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Solae Waterair\u00ae : Couverture de piscine solaire multi-usages\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/mq\/#website\",\"url\":\"https:\/\/www.waterair.com\/mq\/\",\"name\":\"Piscines Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/mq\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-MQ\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Couverture de Piscine Solaire Multi-Usages Solae Waterair\u00ae | Piscines Waterair","description":"Innovation exclusive brevet\u00e9e par Piscines Waterair, d\u00e9couvrez notre couverture multi-usage et quatre saisons qui allie chauffage, protection, s\u00e9curit\u00e9 et hivernage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae","og_locale":"fr_FR","og_type":"article","og_title":"Solae Waterair\u00ae : Couverture de piscine solaire multi-usages","og_description":"Innovation exclusive brevet\u00e9e par Piscines Waterair, d\u00e9couvrez notre couverture multi-usage et quatre saisons qui allie chauffage, protection, s\u00e9curit\u00e9 et hivernage.","og_url":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae","og_site_name":"Piscines Waterair","article_modified_time":"2026-01-23T13:35:39+00:00","og_image":[{"width":1920,"height":1200,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae","url":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae","name":"Couverture de Piscine Solaire Multi-Usages Solae Waterair\u00ae | Piscines Waterair","isPartOf":{"@id":"https:\/\/www.waterair.com\/mq\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg","datePublished":"2021-10-18T15:49:58+00:00","dateModified":"2026-01-23T13:35:39+00:00","description":"Innovation exclusive brevet\u00e9e par Piscines Waterair, d\u00e9couvrez notre couverture multi-usage et quatre saisons qui allie chauffage, protection, s\u00e9curit\u00e9 et hivernage.","breadcrumb":{"@id":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#breadcrumb"},"inLanguage":"fr-MQ","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae"]}]},{"@type":"ImageObject","inLanguage":"fr-MQ","@id":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/10\/homepage_sara_solae.jpg","width":1920,"height":1200,"caption":"Piscine enterr\u00e9e Sara + couverture de piscine Solae\u00ae Waterair"},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/mq\/piscines-et-equipements\/equipements\/securite-piscine\/couverture-piscine-solae#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.waterair.com\/mq"},{"@type":"ListItem","position":2,"name":"S\u00e9curit\u00e9","item":"https:\/\/www.waterair.com\/mq\/securite"},{"@type":"ListItem","position":3,"name":"Solae Waterair\u00ae : Couverture de piscine solaire multi-usages"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/mq\/#website","url":"https:\/\/www.waterair.com\/mq\/","name":"Piscines Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/mq\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-MQ"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/equipment-security\/21493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/equipment-security"}],"about":[{"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/types\/equipment-security"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/equipment-security\/21493\/revisions"}],"predecessor-version":[{"id":422021,"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/equipment-security\/21493\/revisions\/422021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/media\/21024"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/mq\/wp-json\/wp\/v2\/media?parent=21493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}