{"id":112906,"date":"2022-01-21T10:50:12","date_gmt":"2022-01-21T09:50:12","guid":{"rendered":"https:\/\/www.waterair.com\/?page_id=112906"},"modified":"2022-01-21T10:50:12","modified_gmt":"2022-01-21T09:50:12","slug":"configurati-va-piscina","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina","title":{"rendered":"Configura\u021bi-v\u0103 piscina"},"content":{"rendered":"<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><\/p>\n<\/div><\/div><\/div>\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p>Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i <strong>simula\u021bi diferite configura\u021bii.<\/strong> Alege\u021bi scara \u0219i pozi\u021bia acesteia, alege\u021bi liner-ul, personaliza\u021bi-v\u0103 piscina \u0219i face\u021bi-v\u0103 o <strong>idee despre modul \u00een care va ar\u0103ta<\/strong>.<\/p>\n<\/div><\/div><\/div>\n\n\n<div data-wa=\"fade-up\"  class=\"block-configurateur-piscine  content-block\">\n\t\n\t\t\t\n<style>\n#modalPreview .config-preview-modal-escalier {\n  position: absolute;\n  top: 0;\n  left: 0;\n  width: 100%;\n  height: 100%;\n}\n\n@media screen and (min-width: 1351px)\n{\n  .configurateur-parametres {\n    min-width: 500px;\n  }\n}\n\n.contract {\n  position: absolute;\n  left: 50px;\n  bottom: 20px;\n  display: inline-block;\n  color: white;\n  font-size: 12px;\n  font-weight: 700;\n}\n@media screen and (max-width: 1200px)\n{\n  .contract {\n    left: 15px;\n    bottom: 15px;\n  }\n}\n@media screen and (max-width: 500px)\n{\n  .configurateur-parametres__options .post-equipment-wrapper {\n    padding: 0 1.5px;\n  }\n}\n<\/style>\n\n<section class=\"section section-primary section-configurateur js-waterair-configurateur-piscine\" id=\"configurateur\">\n    <div class=\"modal fade\" id=\"modalPreview\" tabindex=\"-1\" role=\"dialog\" aria-labelledby=\"exampleModalLabel\" aria-hidden=\"true\">\n    <div class=\"modal-dialog\" role=\"document\">\n      <div class=\"modal-content\">\n        <div class=\"close\" data-dismiss=\"modal\" aria-label=\"Close\">\n          <img decoding=\"async\" class=\"close-image\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/config-off-full-screen.png\" alt=\"Ie\u0219i\u021bi din modul ecran complet\">\n        <\/div>\n        <img decoding=\"async\" class=\"config-preview-modal-base\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/configurateur\/resized\/modal\/webp\/Base_Ra_TOSCANE.webp\"\/>\n        <img decoding=\"async\" class=\"config-preview-modal-escalier\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/configurateur\/resized\/modal\/webp\/R_E1_TOSCANE.webp\"\/>\n      <\/div>\n    <\/div>\n  <\/div>\n\n    <div class=\"section-content\">\n    <div class=\"row wrapper-col\">\n      <div class=\"col-xl-8\">\n        <div class=\"configurateur-preview\">\n                              <div class=\"configurateur-esc-position js-pos-FLC-E position-i-hidden position-FLC-E1i\" data-group=\"FLC-E\" data-escalier=\"E\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLC-Pa position-i-hidden position-FLC-Pa1i\" data-group=\"FLC-Pa\" data-escalier=\"Pa\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLC-E position-FLC-E1\" data-group=\"FLC-E\" data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLC-Pa position-FLC-Pa1\" data-group=\"FLC-Pa\" data-escalier=\"Pa\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLB-E position-i-hidden position-FLB-E1i\" data-group=\"FLB-E\" data-escalier=\"E\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLB-Eb position-i-hidden position-FLB-Eb1i\" data-group=\"FLB-Eb\" data-escalier=\"Eb\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLB-Pi position-i-hidden position-FLB-Pi1i\" data-group=\"FLB-Pi\" data-escalier=\"Pi\" data-pos=\"1i\" style=\"right:30%;top:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLB-E position-FLB-E1\" data-group=\"FLB-E\" data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLB-Eb position-FLB-Eb1\" data-group=\"FLB-Eb\" data-escalier=\"Eb\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLB-Pi position-FLB-Pi1\" data-group=\"FLB-Pi\" data-escalier=\"Pi\" data-pos=\"1\" style=\"right:30%;top:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLBMini-E position-i-hidden position-FLBMini-E1i\" data-group=\"FLBMini-E\" data-escalier=\"E\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLBMini-Eb position-i-hidden position-FLBMini-Eb1i\" data-group=\"FLBMini-Eb\" data-escalier=\"Eb\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLBMini-Pi position-i-hidden position-FLBMini-Pi1i\" data-group=\"FLBMini-Pi\" data-escalier=\"Pi\" data-pos=\"1i\" style=\"right:32%;top:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLBMini-E position-FLBMini-E1\" data-group=\"FLBMini-E\" data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLBMini-Eb position-FLBMini-Eb1\" data-group=\"FLBMini-Eb\" data-escalier=\"Eb\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-FLBMini-Pi position-FLBMini-Pi1\" data-group=\"FLBMini-Pi\" data-escalier=\"Pi\" data-pos=\"1\" style=\"right:32%;top:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-E position-i-hidden position-H-E1i\" data-group=\"H-E\" data-escalier=\"E\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-P position-i-hidden position-H-P1i\" data-group=\"H-P\" data-escalier=\"P\" data-pos=\"1i\" style=\"right:66%;top:24%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-P position-i-hidden position-H-P2i\" data-group=\"H-P\" data-escalier=\"P\" data-pos=\"2i\" style=\"right:45%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-O position-i-hidden position-H-O1i\" data-group=\"H-O\" data-escalier=\"O\" data-pos=\"1i\" style=\"right:67%;top:27%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-O position-i-hidden position-H-O2i\" data-group=\"H-O\" data-escalier=\"O\" data-pos=\"2i\" style=\"right:41%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-W position-i-hidden position-H-W1i\" data-group=\"H-W\" data-escalier=\"W\" data-pos=\"1i\" style=\"right:64%;top:24%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-W position-i-hidden position-H-W2i\" data-group=\"H-W\" data-escalier=\"W\" data-pos=\"2i\" style=\"right:46%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-Pa position-i-hidden position-H-Pa1i\" data-group=\"H-Pa\" data-escalier=\"Pa\" data-pos=\"1i\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-En position-i-hidden position-H-En1i\" data-group=\"H-En\" data-escalier=\"En\" data-pos=\"1i\" style=\"right:66%;top:39%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-En position-i-hidden position-H-En2i\" data-group=\"H-En\" data-escalier=\"En\" data-pos=\"2i\" style=\"right:39.5%;bottom:33%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-E position-H-E1\" data-group=\"H-E\" data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-P position-H-P1\" data-group=\"H-P\" data-escalier=\"P\" data-pos=\"1\" style=\"left:66%;top:24%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-P position-H-P2\" data-group=\"H-P\" data-escalier=\"P\" data-pos=\"2\" style=\"left:45%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-O position-H-O1\" data-group=\"H-O\" data-escalier=\"O\" data-pos=\"1\" style=\"left:67%;top:27%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-O position-H-O2\" data-group=\"H-O\" data-escalier=\"O\" data-pos=\"2\" style=\"left:41%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-W position-H-W1\" data-group=\"H-W\" data-escalier=\"W\" data-pos=\"1\" style=\"left:64%;top:24%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-W position-H-W2\" data-group=\"H-W\" data-escalier=\"W\" data-pos=\"2\" style=\"left:46%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-Pa position-H-Pa1\" data-group=\"H-Pa\" data-escalier=\"Pa\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-En position-H-En1\" data-group=\"H-En\" data-escalier=\"En\" data-pos=\"1\" style=\"left:65.5%;top:39.5%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-H-En position-H-En2\" data-group=\"H-En\" data-escalier=\"En\" data-pos=\"2\" style=\"left:39%;bottom:33%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-E position-O-E1\"  data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-P position-O-P1\"  data-escalier=\"P\" data-pos=\"1\" style=\"left:49%;top:15%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-P position-O-P2\"  data-escalier=\"P\" data-pos=\"2\" style=\"right:14%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-P position-O-P3\"  data-escalier=\"P\" data-pos=\"3\" style=\"right:49%;bottom:15%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-P position-O-P4\"  data-escalier=\"P\" data-pos=\"4\" style=\"left:14%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-O position-O-O1\"  data-escalier=\"O\" data-pos=\"1\" style=\"left:49%;top:16%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-O position-O-O2\"  data-escalier=\"O\" data-pos=\"2\" style=\"right:15%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-O position-O-O3\"  data-escalier=\"O\" data-pos=\"3\" style=\"right:49%;bottom:16%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-O position-O-O4\"  data-escalier=\"O\" data-pos=\"4\" style=\"left:15%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-W position-O-W1\"  data-escalier=\"W\" data-pos=\"1\" style=\"left:49%;top:14%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-W position-O-W2\"  data-escalier=\"W\" data-pos=\"2\" style=\"right:16%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-W position-O-W3\"  data-escalier=\"W\" data-pos=\"3\" style=\"right:49%;bottom:14%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-W position-O-W4\"  data-escalier=\"W\" data-pos=\"4\" style=\"left:16%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-Pa position-O-Pa1\"  data-escalier=\"Pa\" data-pos=\"1\" style=\"left:25%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-Pa position-O-Pa2\"  data-escalier=\"Pa\" data-pos=\"2\" style=\"right:25%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-En position-O-En1\"  data-escalier=\"En\" data-pos=\"1\" style=\"left:28%;top:33%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-En position-O-En2\"  data-escalier=\"En\" data-pos=\"2\" style=\"right:28%;top:33%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-En position-O-En3\"  data-escalier=\"En\" data-pos=\"3\" style=\"right:28%;bottom:33%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-O-En position-O-En4\"  data-escalier=\"En\" data-pos=\"4\" style=\"left:28%;bottom:33%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-OMini-E position-OMini-E1\"  data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-OMini-P position-OMini-P1\"  data-escalier=\"P\" data-pos=\"1\" style=\"left:48%;top:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-OMini-P position-OMini-P2\"  data-escalier=\"P\" data-pos=\"2\" style=\"right:49.5%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-OMini-O position-OMini-O1\"  data-escalier=\"O\" data-pos=\"1\" style=\"left:48%;top:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-OMini-O position-OMini-O2\"  data-escalier=\"O\" data-pos=\"2\" style=\"right:50.4%;bottom:22%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-E position-RC-E1\"  data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-L position-RC-L1\"  data-escalier=\"L\" data-pos=\"1\" style=\"left:24%;top:41%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-L position-RC-L2\"  data-escalier=\"L\" data-pos=\"2\" style=\"right:24%;top:41%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-L position-RC-L3\"  data-escalier=\"L\" data-pos=\"3\" style=\"right:24%;bottom:41%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-L position-RC-L4\"  data-escalier=\"L\" data-pos=\"4\" style=\"left:24%;bottom:41%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-P position-RC-P1\"  data-escalier=\"P\" data-pos=\"1\" style=\"left:49%;top:20%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-P position-RC-P2\"  data-escalier=\"P\" data-pos=\"2\" style=\"right:11%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-P position-RC-P3\"  data-escalier=\"P\" data-pos=\"3\" style=\"right:49%;bottom:20%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-P position-RC-P4\"  data-escalier=\"P\" data-pos=\"4\" style=\"left:11%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-O position-RC-O1\"  data-escalier=\"O\" data-pos=\"1\" style=\"left:49%;top:20%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-O position-RC-O2\"  data-escalier=\"O\" data-pos=\"2\" style=\"right:11%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-O position-RC-O3\"  data-escalier=\"O\" data-pos=\"3\" style=\"right:49%;bottom:20%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-O position-RC-O4\"  data-escalier=\"O\" data-pos=\"4\" style=\"left:11%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-W position-RC-W1\"  data-escalier=\"W\" data-pos=\"1\" style=\"left:49%;top:20%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-W position-RC-W2\"  data-escalier=\"W\" data-pos=\"2\" style=\"right:11%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-W position-RC-W3\"  data-escalier=\"W\" data-pos=\"3\" style=\"right:49%;bottom:20%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RC-W position-RC-W4\"  data-escalier=\"W\" data-pos=\"4\" style=\"left:11%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-E position-RCMini-E1\"  data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-L position-RCMini-L1\"  data-escalier=\"L\" data-pos=\"1\" style=\"left:35%;top:38%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-L position-RCMini-L2\"  data-escalier=\"L\" data-pos=\"2\" style=\"right:35%;top:38%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-L position-RCMini-L3\"  data-escalier=\"L\" data-pos=\"3\" style=\"right:35%;bottom:38%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-L position-RCMini-L4\"  data-escalier=\"L\" data-pos=\"4\" style=\"left:35%;bottom:38%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-P position-RCMini-P1\"  data-escalier=\"P\" data-pos=\"1\" style=\"left:49%;top:21%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-P position-RCMini-P2\"  data-escalier=\"P\" data-pos=\"2\" style=\"right:23%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-P position-RCMini-P3\"  data-escalier=\"P\" data-pos=\"3\" style=\"right:49%;bottom:21%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-P position-RCMini-P4\"  data-escalier=\"P\" data-pos=\"4\" style=\"left:23%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-O position-RCMini-O1\"  data-escalier=\"O\" data-pos=\"1\" style=\"left:49%;top:21%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-O position-RCMini-O2\"  data-escalier=\"O\" data-pos=\"2\" style=\"right:23%;top:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-O position-RCMini-O3\"  data-escalier=\"O\" data-pos=\"3\" style=\"right:49%;bottom:21%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RCMini-O position-RCMini-O4\"  data-escalier=\"O\" data-pos=\"4\" style=\"left:23%;bottom:49%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-E position-RB-E1\"  data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-Eb position-RB-Eb1\"  data-escalier=\"Eb\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-Pi position-RB-Pi1\"  data-escalier=\"Pi\" data-pos=\"1\" style=\"left:29%;top:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-Pi position-RB-Pi2\"  data-escalier=\"Pi\" data-pos=\"2\" style=\"right:29%;top:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-Pi position-RB-Pi3\"  data-escalier=\"Pi\" data-pos=\"3\" style=\"right:29%;bottom:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-Pi position-RB-Pi4\"  data-escalier=\"Pi\" data-pos=\"4\" style=\"left:29%;bottom:32%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-S position-RB-S1\"  data-escalier=\"S\" data-pos=\"1\" style=\"left:24%;top:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-S position-RB-S2\"  data-escalier=\"S\" data-pos=\"2\" style=\"right:24%;top:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-S position-RB-S3\"  data-escalier=\"S\" data-pos=\"3\" style=\"right:24%;bottom:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RB-S position-RB-S4\"  data-escalier=\"S\" data-pos=\"4\" style=\"left:24%;bottom:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RBMini-E position-RBMini-E1\"  data-escalier=\"E\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RBMini-Eb position-RBMini-Eb1\"  data-escalier=\"Eb\" data-pos=\"1\" style=\"left:0;top:0;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RBMini-Pi position-RBMini-Pi1\"  data-escalier=\"Pi\" data-pos=\"1\" style=\"left:32%;top:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RBMini-Pi position-RBMini-Pi2\"  data-escalier=\"Pi\" data-pos=\"2\" style=\"right:32%;top:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RBMini-Pi position-RBMini-Pi3\"  data-escalier=\"Pi\" data-pos=\"3\" style=\"right:32%;bottom:35%;\"><\/div>\n                                      <div class=\"configurateur-esc-position js-pos-RBMini-Pi position-RBMini-Pi4\"  data-escalier=\"Pi\" data-pos=\"4\" style=\"left:32%;bottom:35%;\"><\/div>\n                  \n          \n                              <img decoding=\"async\" class=\"config-preview-base\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/aa502ea7-Base_TOSCANE_V3.png\"\/>\n          <img decoding=\"async\" class=\"config-preview-escalier\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/cb31ac74-FLC_E1_TOSCANE.png\"\/>\n\n                              <img class=\"config-preview-escalier-pos\"\/>\n          <div class=\"preview-full-screen\" data-toggle=\"modal\" data-target=\"#modalPreview\">\n            <img decoding=\"async\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/config-full-screen.png\" alt=\"Modul ecran complet\">\n          <\/div>\n\n          <div class=\"config-preview-mirror\">\n            <img decoding=\"async\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/icon_mirror.svg\"\/>\n            <span>Inversa\u021bi orientarea bazinului<\/span>\n          <\/div>\n\n          <span class=\"contract\">Imagens n\u00e3o contratuais<\/span>\n        <\/div>\n      <\/div>\n      <div class=\"configurateur-parametres col-xl-4\">\n        <ul class=\"configurateur-tabs nav nav-tabs\" role=\"tablist\">\n          <li class=\"nav-item active nav-item-shape\" role=\"presentation\">\n            <a class=\"nav-link active\" data-toggle=\"tab\" href=\"#tab-shape\" role=\"tab\">1<\/a>\n          <\/li>\n          <li class=\"nav-item nav-item-esc\" role=\"presentation\">\n            <a class=\"nav-link\" data-toggle=\"tab\" href=\"#tab-esc\" role=\"tab\">2<\/a>\n          <\/li>\n          <li class=\"nav-item nav-item-liner\" role=\"presentation\">\n            <a class=\"nav-link\" data-toggle=\"tab\" href=\"#tab-liner\" role=\"tab\">3<\/a>\n          <\/li>\n        <\/ul>\n\n        <div class=\"tab-content\">\n                    <div class=\"tab-pane active in show fade\" id=\"tab-shape\">\n            <div class=\"tab-arrow tab-arrow-right\" data-toggle=\"tab\" data-go=\"esc\" href=\"#tab-esc\">\n              <img decoding=\"async\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/config-arrow.png\">\n            <\/div>\n\n                        <div class=\"configurateur-parametres__item\">\n              <span class=\"configurateur-heading\">Forma piscinei<\/span>\n              <p class=\"param-value js-value-shape\">Dreptunghiular\u0103<\/p>\n              \n              <span class=\"switch-mini off\">\n                <span class=\"switch-mini__label std\">Standard<\/span>\n                <span class=\"toggle-mini\"><\/span>\n                <span class=\"switch-mini__label min\">Mini<\/span>\n              <\/span>\n\n              <div class=\"configurateur-parametres__options\">\n                <div>\n                                      <div class=\"post-equipment-wrapper ico-notmini link js-config-link-shape selected\" data-shape=\"RB\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/04\/rectangle-commun.svg\" alt=\"Dreptunghiular\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-notmini link js-config-link-shape selected\" data-shape=\"RC\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/3cfac61b-rectangle-cintre-commun.svg\" alt=\"Dreptunghiular\u0103 rotunjit\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-notmini link js-config-link-shape selected\" data-shape=\"O\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/e6366c19-ovale-commun.svg\" alt=\"Oval\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-notmini link js-config-link-shape selected\" data-shape=\"H\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/24c50f7b-haricot.svg\" alt=\"Bob de fasole\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-notmini link js-config-link-shape selected\" data-shape=\"FLB\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/04\/forme-libre-commun.svg\" alt=\"Form\u0103 liber\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-notmini link js-config-link-shape selected\" data-shape=\"FLC\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/9e8e8c6c-forme-libre-cintre-commun.svg\" alt=\"Form\u0103 liber\u0103 rotunjit\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                  \n                                      <div class=\"post-equipment-wrapper ico-mini link js-config-link-shape selected\" data-shape=\"RBMini\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/04\/rectangle-commun.svg\" alt=\"Mini dreptunghiular\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-mini link js-config-link-shape selected\" data-shape=\"RCMini\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/ffed486a-rectangle-mini-cintre-commun.svg\" alt=\"Mini Dreptunghiular\u0103 rotunjit\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-mini link js-config-link-shape selected\" data-shape=\"OMini\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/7fea86e4-ovale-mini-commun.svg\" alt=\"Mini ovale\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper ico-mini link js-config-link-shape selected\" data-shape=\"FLBMini\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_shape\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/04\/forme-libre-commun.svg\" alt=\"Mini form\u0103 liber\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                    <\/div>\n                <\/div>\n\n                <div class=\"is--standard\">\n                                  <\/div>\n                <div class=\"is--slim\">\n                                <\/div>\n            <\/div>\n          <\/div>\n\n                    <div class=\"tab-pane fade\" id=\"tab-esc\">\n            <div class=\"tab-arrow tab-arrow-left\" data-toggle=\"tab\" data-go=\"shape\" href=\"#tab-shape\">\n              <img decoding=\"async\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/config-arrow.png\">\n            <\/div>\n            <div class=\"tab-arrow tab-arrow-right\" data-toggle=\"tab\" data-go=\"liner\" href=\"#tab-liner\">\n              <img decoding=\"async\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/config-arrow.png\">\n            <\/div>\n\n            <div class=\"configurateur-parametres__item\">\n              <span class=\"configurateur-heading\">Scar\u0103\/Acces<\/span>\n              <p class=\"param-value js-value-escalier\">Scar\u0103<\/p>\n\n              <div class=\"configurateur-parametres__options\">\n\n                <div>\n                                      <div class=\"post-equipment-wrapper link selected js-config-link-escalier\" data-escalier=\"E\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/a8b9f394-echelle.svg\" alt=\"Scar\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"Eb\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/04\/banc-echelle.svg\" alt=\"Banchet\u0103 + scar\u0103\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"Pi\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/04\/escalier-piano.svg\" alt=\"Banchet\u0103 + trepte Piano\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"L\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/7470a637-escalier-lobby.svg\" alt=\"Escalier Lobby\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"O\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/8a34566a-escalier-orbis.svg\" alt=\"Scar\u0103 Orbis\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"P\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/a056c93b-escalier-paso.svg\" alt=\"Scar\u0103 Paso\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"Pa\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/081e9c35-escalier-pacio.svg\" alt=\"Scar\u0103 Pacio\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"S\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/65bd00e9-escalier-square.svg\" alt=\"Scar\u0103 Square\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"W\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/adb17d52-escalier-welcome.svg\" alt=\"Scar\u0103 Welcome\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-escalier\" data-escalier=\"En\">\n                      <figure class=\"post-equipment-figure post-equipment-figure_escalier\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2026\/03\/escalier-enjoy.svg\" alt=\"Scar\u0103 Enjoy\" \/>\n                      <\/figure>\n                    <\/div>\n                                  <\/div>\n\n                              <\/div>\n            <\/div>\n          <\/div>\n\n                    <div class=\"tab-pane fade\" id=\"tab-liner\">\n            <div class=\"tab-arrow tab-arrow-left\" data-toggle=\"tab\" data-go=\"esc\" href=\"#tab-esc\">\n              <img decoding=\"async\" src=\"\/wp-content\/plugins\/adipso-waterair-configurateur\/assets\/images\/config-arrow.png\">\n            <\/div>\n\n            <div class=\"configurateur-parametres__item\">\n              <span class=\"configurateur-heading\">Culoare liner<\/span>\n              <p class=\"param-value js-value-liner\">Toscana<\/p>\n              \n              <div class=\"configurateur-parametres__options\">\n                <div>\n                                      <div class=\"post-equipment-wrapper link selected js-config-link-liner\" data-liner=\"toscane\">\n                      <figure class=\"post-equipment-figure\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/6fe36eed-liner-toscane.jpg\" alt=\"Toscana\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-liner\" data-liner=\"gris\">\n                      <figure class=\"post-equipment-figure\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/66fda704-liner-gris-souris.jpg\" alt=\"Gri\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-liner\" data-liner=\"ardoise\">\n                      <figure class=\"post-equipment-figure\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/e2b80cb6-liner-marbre-ardoise.jpg\" alt=\"Marmorat, de culoarea ardeziei\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-liner\" data-liner=\"argent\">\n                      <figure class=\"post-equipment-figure\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/2beb2b49-liner-gris-argent.jpg\" alt=\"Gri argintiu\" \/>\n                      <\/figure>\n                    <\/div>\n                                      <div class=\"post-equipment-wrapper link  js-config-link-liner\" data-liner=\"bali\">\n                      <figure class=\"post-equipment-figure\">\n                        <img decoding=\"async\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2025\/12\/670c10f3-liner-bali.jpg\" alt=\"Pierre de Bali\" \/>\n                      <\/figure>\n                    <\/div>\n                                  <\/div>\n              \n                              <\/div>\n            <\/div>\n          <\/div>\n        <\/div>  \n\n        <div class=\"configurateur-parametres__bottom configurateur-parametres__bottom_wrap\">\n          <div class=\"configurateur-price\">\n                          <p>Contacta\u021bi partenerul dumneavoastr\u0103 Waterair pentru un studiu personalizat<\/p>\n                      <\/div>\n          <a href=\"#catalogue-form\" class=\"btn btn--secondary js-config-link\">Cere\u021bi un deviz<\/a>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/div>\n<\/section>\n\n<script type=\"text\/javascript\">\n  var shapes = [\n          {\n        id: \"RB\",\n        text: \"Dreptunghiular\u0103\"\n      },\n          {\n        id: \"RBMini\",\n        text: \"Mini dreptunghiular\u0103\"\n      },\n          {\n        id: \"RC\",\n        text: \"Dreptunghiular\u0103 rotunjit\u0103\"\n      },\n          {\n        id: \"RCMini\",\n        text: \"Mini Dreptunghiular\u0103 rotunjit\u0103\"\n      },\n          {\n        id: \"O\",\n        text: \"Oval\u0103\"\n      },\n          {\n        id: \"OMini\",\n        text: \"Mini ovale\"\n      },\n          {\n        id: \"H\",\n        text: \"Bob de fasole\"\n      },\n          {\n        id: \"FLB\",\n        text: \"Form\u0103 liber\u0103\"\n      },\n          {\n        id: \"FLBMini\",\n        text: \"Mini form\u0103 liber\u0103\"\n      },\n          {\n        id: \"FLC\",\n        text: \"Form\u0103 liber\u0103 rotunjit\u0103\"\n      },\n    \n      ];\n\n  var stairs = [\n          {\n        id: \"E\",\n        text: \"Scar\u0103\"\n      },\n          {\n        id: \"Eb\",\n        text: \"Banchet\u0103 + scar\u0103\"\n      },\n          {\n        id: \"Pi\",\n        text: \"Banchet\u0103 + trepte Piano\"\n      },\n          {\n        id: \"L\",\n        text: \"Escalier Lobby\"\n      },\n          {\n        id: \"O\",\n        text: \"Scar\u0103 Orbis\"\n      },\n          {\n        id: \"P\",\n        text: \"Scar\u0103 Paso\"\n      },\n          {\n        id: \"Pa\",\n        text: \"Scar\u0103 Pacio\"\n      },\n          {\n        id: \"S\",\n        text: \"Scar\u0103 Square\"\n      },\n          {\n        id: \"W\",\n        text: \"Scar\u0103 Welcome\"\n      },\n          {\n        id: \"En\",\n        text: \"Scar\u0103 Enjoy\"\n      },\n    \n      ];\n\n  var liners = [\n          {\n        id: \"TOSCANE\",\n        text: \"Toscana\"\n      },\n          {\n        id: \"GRIS\",\n        text: \"Gri\"\n      },\n          {\n        id: \"ARDOISE\",\n        text: \"Marmorat, de culoarea ardeziei\"\n      },\n          {\n        id: \"ARGENT\",\n        text: \"Gri argintiu\"\n      },\n          {\n        id: \"BALI\",\n        text: \"Pierre de Bali\"\n      },\n    \n      ];\n\n  \/* test *\/\n    \n  window.matchingShapeStairs = {\"RB\":[\"E\",\"Eb\",\"Pi\",\"S\"],\"RBMini\":[\"E\",\"Eb\",\"Pi\"],\"RC\":[\"E\",\"L\",\"O\",\"P\",\"W\"],\"RCMini\":[\"E\",\"L\",\"O\",\"P\"],\"O\":[\"E\",\"O\",\"P\",\"Pa\",\"W\",\"En\"],\"OMini\":[\"E\",\"P\",\"O\"],\"H\":[\"E\",\"O\",\"P\",\"Pa\",\"W\",\"En\"],\"FLB\":[\"E\",\"Eb\",\"Pi\"],\"FLBMini\":[\"E\",\"Eb\",\"Pi\"],\"FLC\":[\"E\",\"Pa\"]};\n\n  \n  window.configurateurData = {\"FLC_E1i_TOSCANE\":{\"price\":\"11 000 \\u20ac\",\"name\":\"Maria FLCi, Echelle position 1, liner Toscane\",\"img_base\":\"Base_FLC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa502ea7-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa502ea7-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/cb31ac74-FLC_E1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/cb31ac74-FLC_E1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1i_TOSCANE\":{\"price\":\"13 700 \\u20ac\",\"name\":\"Maria FLCi, Escalier Pacio position 1, liner Toscane\",\"img_base\":\"Base_FLC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa502ea7-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa502ea7-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/437beb77-FLC_Pa1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/437beb77-FLC_Pa1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1i_GRIS\":{\"price\":\"11 000 \\u20ac\",\"name\":\"Maria FLCi, Echelle position 1, liner Gris\",\"img_base\":\"Base_FLC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4738814f-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4738814f-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0dbeec31-FLC_E1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0dbeec31-FLC_E1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1i_GRIS\":{\"price\":\"13 700 \\u20ac\",\"name\":\"Maria FLCi, Escalier Pacio position 1, liner Gris\",\"img_base\":\"Base_FLC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4738814f-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4738814f-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a118998-FLC_Pa1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a118998-FLC_Pa1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1i_ARDOISE\":{\"price\":\"11 449 \\u20ac\",\"name\":\"Maria FLCi, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/87a8c964-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/87a8c964-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d569ab70-FLC_E1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d569ab70-FLC_E1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1i_ARDOISE\":{\"price\":\"14 149 \\u20ac\",\"name\":\"Maria FLCi, Escalier Pacio position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/87a8c964-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/87a8c964-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5d23ec73-FLC_Pa1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5d23ec73-FLC_Pa1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1i_ARGENT\":{\"price\":\"11 449 \\u20ac\",\"name\":\"Maria FLCi, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/93db353e-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/93db353e-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a4c2a4a5-FLC_E1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a4c2a4a5-FLC_E1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1i_ARGENT\":{\"price\":\"14 149 \\u20ac\",\"name\":\"Maria FLCi, Escalier Pacio position 1, liner Gris Argent\",\"img_base\":\"Base_FLC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/93db353e-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/93db353e-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e6df417d-FLC_Pa1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e6df417d-FLC_Pa1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1i_BALI\":{\"price\":\"11 747 \\u20ac\",\"name\":\"Maria FLCi, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5d1a7f4a-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5d1a7f4a-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/69f57a96-FLC_E1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/69f57a96-FLC_E1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1i_BALI\":{\"price\":\"14 447 \\u20ac\",\"name\":\"Maria FLCi, Escalier Pacio position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5d1a7f4a-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5d1a7f4a-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1e5a1f3f-FLC_Pa1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1e5a1f3f-FLC_Pa1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1_TOSCANE\":{\"price\":\"11 000 \\u20ac\",\"name\":\"Maria FLC, Echelle position 1, liner Toscane\",\"img_base\":\"Base_FLC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1024c85d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1024c85d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6fe15380-FLC_E1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6fe15380-FLC_E1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1_TOSCANE\":{\"price\":\"13 700 \\u20ac\",\"name\":\"Maria FLC, Escalier Pacio position 1, liner Toscane\",\"img_base\":\"Base_FLC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1024c85d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1024c85d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b3c5b023-FLC_Pa1_TOSCANE_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b3c5b023-FLC_Pa1_TOSCANE_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1_GRIS\":{\"price\":\"11 000 \\u20ac\",\"name\":\"Maria FLC, Echelle position 1, liner Gris\",\"img_base\":\"Base_FLC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7d0e10e-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7d0e10e-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3037b33b-FLC_E1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3037b33b-FLC_E1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1_GRIS\":{\"price\":\"13 700 \\u20ac\",\"name\":\"Maria FLC, Escalier Pacio position 1, liner Gris\",\"img_base\":\"Base_FLC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7d0e10e-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7d0e10e-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cf1c2673-FLC_Pa1_GRIS_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cf1c2673-FLC_Pa1_GRIS_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1_ARDOISE\":{\"price\":\"11 449 \\u20ac\",\"name\":\"Maria FLC, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3ddc2f9e-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3ddc2f9e-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71b95484-FLC_E1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71b95484-FLC_E1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1_ARDOISE\":{\"price\":\"14 149 \\u20ac\",\"name\":\"Maria FLC, Escalier Pacio position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3ddc2f9e-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3ddc2f9e-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b185dbce-FLC_Pa1_ARDOISE_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b185dbce-FLC_Pa1_ARDOISE_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1_ARGENT\":{\"price\":\"11 449 \\u20ac\",\"name\":\"Maria FLC, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/370bcaca-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/370bcaca-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a5f93dc3-FLC_E1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a5f93dc3-FLC_E1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1_ARGENT\":{\"price\":\"14 149 \\u20ac\",\"name\":\"Maria FLC, Escalier Pacio position 1, liner Gris Argent\",\"img_base\":\"Base_FLC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/370bcaca-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/370bcaca-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a70c0d39-FLC_Pa1_ARGENT_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a70c0d39-FLC_Pa1_ARGENT_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_E1_BALI\":{\"price\":\"11 747 \\u20ac\",\"name\":\"Maria FLC, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bdf21f0b-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bdf21f0b-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/547c259c-FLC_E1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/547c259c-FLC_E1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLC_Pa1_BALI\":{\"price\":\"14 447 \\u20ac\",\"name\":\"Maria FLC, Escalier Pacio position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bdf21f0b-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bdf21f0b-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/bf6cf002-FLC_Pa1_BALI_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/bf6cf002-FLC_Pa1_BALI_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1i_TOSCANE\":{\"price\":\"8 850 \\u20ac\",\"name\":\"Inaya FLBi, Echelle position 1, liner Toscane\",\"img_base\":\"Base_FLB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f9496be5-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f9496be5-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1749574a-FLB_E1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1749574a-FLB_E1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1i_TOSCANE\":{\"price\":\"11 150 \\u20ac\",\"name\":\"Inaya FLBi, Banc + \\u00e9chelle position 1, liner Toscane\",\"img_base\":\"Base_FLB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f9496be5-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f9496be5-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4d3c98f0-FLB_EB1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4d3c98f0-FLB_EB1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1i_TOSCANE\":{\"price\":\"13 570 \\u20ac\",\"name\":\"Inaya FLBi, Banc + marches Piano position 1, liner Toscane\",\"img_base\":\"Base_FLB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f9496be5-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f9496be5-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2d9e1d16-FLB_P1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2d9e1d16-FLB_P1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1i_GRIS\":{\"price\":\"8 850 \\u20ac\",\"name\":\"Inaya FLBi, Echelle position 1, liner Gris\",\"img_base\":\"Base_FLB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af982061-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af982061-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2ea66ebe-FLB_E1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2ea66ebe-FLB_E1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1i_GRIS\":{\"price\":\"11 150 \\u20ac\",\"name\":\"Inaya FLBi, Banc + \\u00e9chelle position 1, liner Gris\",\"img_base\":\"Base_FLB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af982061-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af982061-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/118dc335-FLB_EB1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/118dc335-FLB_EB1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1i_GRIS\":{\"price\":\"13 570 \\u20ac\",\"name\":\"Inaya FLBi, Banc + marches Piano position 1, liner Gris\",\"img_base\":\"Base_FLB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af982061-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af982061-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/17fc407a-FLB_P1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/17fc407a-FLB_P1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1i_ARDOISE\":{\"price\":\"9 159 \\u20ac\",\"name\":\"Inaya FLBi, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d4b18c26-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d4b18c26-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/15093ca7-FLB_E1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/15093ca7-FLB_E1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1i_ARDOISE\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Inaya FLBi, Banc + \\u00e9chelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d4b18c26-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d4b18c26-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4f7cf31d-FLB_EB1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/4f7cf31d-FLB_EB1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1i_ARDOISE\":{\"price\":\"13 879 \\u20ac\",\"name\":\"Inaya FLBi, Banc + marches Piano position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d4b18c26-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d4b18c26-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/33c61a12-FLB_P1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/33c61a12-FLB_P1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1i_ARGENT\":{\"price\":\"9 159 \\u20ac\",\"name\":\"Inaya FLBi, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/390d47cc-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/390d47cc-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/89292c5b-FLB_E1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/89292c5b-FLB_E1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1i_ARGENT\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Inaya FLBi, Banc + \\u00e9chelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/390d47cc-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/390d47cc-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f9398da5-FLB_EB1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f9398da5-FLB_EB1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1i_ARGENT\":{\"price\":\"13 879 \\u20ac\",\"name\":\"Inaya FLBi, Banc + marches Piano position 1, liner Gris Argent\",\"img_base\":\"Base_FLB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/390d47cc-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/390d47cc-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/682fc7ea-FLB_P1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/682fc7ea-FLB_P1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1i_BALI\":{\"price\":\"9 364 \\u20ac\",\"name\":\"Inaya FLBi, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b5bade64-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b5bade64-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5ed6b8cf-FLB_E1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5ed6b8cf-FLB_E1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1i_BALI\":{\"price\":\"11 664 \\u20ac\",\"name\":\"Inaya FLBi, Banc + \\u00e9chelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b5bade64-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b5bade64-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/61fd1544-FLB_EB1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/61fd1544-FLB_EB1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1i_BALI\":{\"price\":\"14 084 \\u20ac\",\"name\":\"Inaya FLBi, Banc + marches Piano position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b5bade64-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b5bade64-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/73b7d6dd-FLB_P1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/73b7d6dd-FLB_P1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1_TOSCANE\":{\"price\":\"8 850 \\u20ac\",\"name\":\"Inaya FLB, Echelle position 1, liner Toscane\",\"img_base\":\"Base_FLB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a821cbe1-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a821cbe1-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/aeb4f1c0-FLB_E2_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/aeb4f1c0-FLB_E2_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1_TOSCANE\":{\"price\":\"11 150 \\u20ac\",\"name\":\"Inaya FLB, Banc + \\u00e9chelle position 1, liner Toscane\",\"img_base\":\"Base_FLB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a821cbe1-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a821cbe1-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f9f4898e-FLB_EB2_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f9f4898e-FLB_EB2_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1_TOSCANE\":{\"price\":\"13 570 \\u20ac\",\"name\":\"Inaya FLB, Banc + marches Piano position 1, liner Toscane\",\"img_base\":\"Base_FLB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a821cbe1-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a821cbe1-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/556fac2f-FLB_P2_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/556fac2f-FLB_P2_TOSCANE_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1_GRIS\":{\"price\":\"8 850 \\u20ac\",\"name\":\"Inaya FLB, Echelle position 1, liner Gris\",\"img_base\":\"Base_FLB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b04dad5b-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b04dad5b-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/03afeb61-FLB_E2_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/03afeb61-FLB_E2_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1_GRIS\":{\"price\":\"11 150 \\u20ac\",\"name\":\"Inaya FLB, Banc + \\u00e9chelle position 1, liner Gris\",\"img_base\":\"Base_FLB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b04dad5b-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b04dad5b-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6ad04a57-FLB_EB2_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6ad04a57-FLB_EB2_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1_GRIS\":{\"price\":\"13 570 \\u20ac\",\"name\":\"Inaya FLB, Banc + marches Piano position 1, liner Gris\",\"img_base\":\"Base_FLB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b04dad5b-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b04dad5b-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/28136cb5-FLB_P2_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/28136cb5-FLB_P2_GRIS_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1_ARDOISE\":{\"price\":\"9 159 \\u20ac\",\"name\":\"Inaya FLB, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d92c22-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d92c22-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/acf49a2d-FLB_E2_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/acf49a2d-FLB_E2_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1_ARDOISE\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Inaya FLB, Banc + \\u00e9chelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d92c22-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d92c22-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/fbb4e263-FLB_EB2_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/fbb4e263-FLB_EB2_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1_ARDOISE\":{\"price\":\"13 879 \\u20ac\",\"name\":\"Inaya FLB, Banc + marches Piano position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d92c22-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d92c22-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/78974bec-FLB_P2_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/78974bec-FLB_P2_ARDOISE_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1_ARGENT\":{\"price\":\"9 159 \\u20ac\",\"name\":\"Inaya FLB, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fad79fd-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fad79fd-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/125baf2d-FLB_E2_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/125baf2d-FLB_E2_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1_ARGENT\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Inaya FLB, Banc + \\u00e9chelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fad79fd-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fad79fd-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3a96c459-FLB_EB2_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3a96c459-FLB_EB2_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1_ARGENT\":{\"price\":\"13 879 \\u20ac\",\"name\":\"Inaya FLB, Banc + marches Piano position 1, liner Gris Argent\",\"img_base\":\"Base_FLB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fad79fd-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fad79fd-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a333cde7-FLB_P2_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a333cde7-FLB_P2_ARGENT_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_E1_BALI\":{\"price\":\"9 364 \\u20ac\",\"name\":\"Inaya FLB, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6f535e-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6f535e-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/73df3d10-FLB_E2_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/73df3d10-FLB_E2_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Eb1_BALI\":{\"price\":\"11 664 \\u20ac\",\"name\":\"Inaya FLB, Banc + \\u00e9chelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6f535e-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6f535e-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1aa09c26-FLB_EB2_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1aa09c26-FLB_EB2_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLB_Pi1_BALI\":{\"price\":\"14 084 \\u20ac\",\"name\":\"Inaya FLB, Banc + marches Piano position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6f535e-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6f535e-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/323192b0-FLB_P2_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/323192b0-FLB_P2_BALI_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1i_TOSCANE\":{\"price\":\"8 130 \\u20ac\",\"name\":\"Mini Inaya FLBi, Echelle position 1, liner Toscane\",\"img_base\":\"Base_FLBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2b619f22-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2b619f22-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c6cc5b1e-FLB_E1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c6cc5b1e-FLB_E1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1i_TOSCANE\":{\"price\":\"10 430 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + \\u00e9chelle position 1, liner Toscane\",\"img_base\":\"Base_FLBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2b619f22-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2b619f22-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/21eb8811-FLB_EB1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/21eb8811-FLB_EB1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1i_TOSCANE\":{\"price\":\"12 850 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + marches Piano position 1, liner Toscane\",\"img_base\":\"Base_FLBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2b619f22-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2b619f22-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/08ef2730-FLB_P1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/08ef2730-FLB_P1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1i_GRIS\":{\"price\":\"8 130 \\u20ac\",\"name\":\"Mini Inaya FLBi, Echelle position 1, liner Gris\",\"img_base\":\"Base_FLBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/46ecfaf3-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/46ecfaf3-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/fc8e9a79-FLB_E1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/fc8e9a79-FLB_E1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1i_GRIS\":{\"price\":\"10 430 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + \\u00e9chelle position 1, liner Gris\",\"img_base\":\"Base_FLBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/46ecfaf3-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/46ecfaf3-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/145fbcd2-FLB_EB1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/145fbcd2-FLB_EB1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1i_GRIS\":{\"price\":\"12 850 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + marches Piano position 1, liner Gris\",\"img_base\":\"Base_FLBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/46ecfaf3-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/46ecfaf3-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0083e77c-FLB_P1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0083e77c-FLB_P1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1i_ARDOISE\":{\"price\":\"8 390 \\u20ac\",\"name\":\"Mini Inaya FLBi, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/069978e1-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/069978e1-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c48c30f3-FLB_E1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c48c30f3-FLB_E1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1i_ARDOISE\":{\"price\":\"10 690 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + \\u00e9chelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/069978e1-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/069978e1-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/23abe3fc-FLB_EB1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/23abe3fc-FLB_EB1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1i_ARDOISE\":{\"price\":\"13 110 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + marches Piano position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/069978e1-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/069978e1-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16b72034-FLB_P1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16b72034-FLB_P1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1i_ARGENT\":{\"price\":\"8 390 \\u20ac\",\"name\":\"Mini Inaya FLBi, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1c7c7dea-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1c7c7dea-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b74289ff-FLB_E1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b74289ff-FLB_E1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1i_ARGENT\":{\"price\":\"10 690 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + \\u00e9chelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1c7c7dea-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1c7c7dea-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/28bc81f1-FLB_EB1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/28bc81f1-FLB_EB1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1i_ARGENT\":{\"price\":\"13 110 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + marches Piano position 1, liner Gris Argent\",\"img_base\":\"Base_FLBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1c7c7dea-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1c7c7dea-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76c74158-FLB_P1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76c74158-FLB_P1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1i_BALI\":{\"price\":\"8 563 \\u20ac\",\"name\":\"Mini Inaya FLBi, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5cce04f6-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5cce04f6-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8cfe4c08-FLB_E1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8cfe4c08-FLB_E1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1i_BALI\":{\"price\":\"10 863 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + \\u00e9chelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5cce04f6-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5cce04f6-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/642f6aa3-FLB_EB1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/642f6aa3-FLB_EB1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1i_BALI\":{\"price\":\"13 283 \\u20ac\",\"name\":\"Mini Inaya FLBi, Banc + marches Piano position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5cce04f6-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5cce04f6-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/64c871db-FLB_P1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/64c871db-FLB_P1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1_TOSCANE\":{\"price\":\"8 130 \\u20ac\",\"name\":\"Mini Inaya FLB, Echelle position 1, liner Toscane\",\"img_base\":\"Base_FLBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76eed66a-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76eed66a-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b763b642-FLB_E2_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b763b642-FLB_E2_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1_TOSCANE\":{\"price\":\"10 430 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + \\u00e9chelle position 1, liner Toscane\",\"img_base\":\"Base_FLBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76eed66a-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76eed66a-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/fa5bbcc5-FLB_EB2_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/fa5bbcc5-FLB_EB2_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1_TOSCANE\":{\"price\":\"12 850 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + marches Piano position 1, liner Toscane\",\"img_base\":\"Base_FLBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76eed66a-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76eed66a-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/52770104-FLB_P2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/52770104-FLB_P2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1_GRIS\":{\"price\":\"8 130 \\u20ac\",\"name\":\"Mini Inaya FLB, Echelle position 1, liner Gris\",\"img_base\":\"Base_FLBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f456cd77-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f456cd77-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dd60f6ea-FLB_E2_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dd60f6ea-FLB_E2_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1_GRIS\":{\"price\":\"10 430 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + \\u00e9chelle position 1, liner Gris\",\"img_base\":\"Base_FLBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f456cd77-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f456cd77-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1064dfe2-FLB_EB2_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1064dfe2-FLB_EB2_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1_GRIS\":{\"price\":\"12 850 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + marches Piano position 1, liner Gris\",\"img_base\":\"Base_FLBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f456cd77-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f456cd77-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ec88f0c6-FLB_P2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ec88f0c6-FLB_P2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1_ARDOISE\":{\"price\":\"8 390 \\u20ac\",\"name\":\"Mini Inaya FLB, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b1631a9-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b1631a9-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b523ddaf-FLB_E2_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b523ddaf-FLB_E2_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1_ARDOISE\":{\"price\":\"10 690 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + \\u00e9chelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b1631a9-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b1631a9-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f81bd728-FLB_EB2_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f81bd728-FLB_EB2_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1_ARDOISE\":{\"price\":\"13 110 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + marches Piano position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_FLBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b1631a9-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b1631a9-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4c2f0600-FLB_P2_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4c2f0600-FLB_P2_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1_ARGENT\":{\"price\":\"8 390 \\u20ac\",\"name\":\"Mini Inaya FLB, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb2e3710-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb2e3710-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a92a5cbb-FLB_E2_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a92a5cbb-FLB_E2_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1_ARGENT\":{\"price\":\"10 690 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + \\u00e9chelle position 1, liner Gris Argent\",\"img_base\":\"Base_FLBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb2e3710-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb2e3710-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/234183db-FLB_EB2_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/234183db-FLB_EB2_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1_ARGENT\":{\"price\":\"13 110 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + marches Piano position 1, liner Gris Argent\",\"img_base\":\"Base_FLBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb2e3710-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb2e3710-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/eb3e6ea6-FLB_P2_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/eb3e6ea6-FLB_P2_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_E1_BALI\":{\"price\":\"8 563 \\u20ac\",\"name\":\"Mini Inaya FLB, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ee743372-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ee743372-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ad10209b-FLB_E2_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/ad10209b-FLB_E2_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Eb1_BALI\":{\"price\":\"10 863 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + \\u00e9chelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ee743372-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ee743372-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/60140993-FLB_EB2_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/60140993-FLB_EB2_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"FLBMini_Pi1_BALI\":{\"price\":\"13 283 \\u20ac\",\"name\":\"Mini Inaya FLB, Banc + marches Piano position 1, liner Pierre de Bali\",\"img_base\":\"Base_FLBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ee743372-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ee743372-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/88c36661-FLB_P2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/88c36661-FLB_P2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_E1i_TOSCANE\":{\"price\":\"8 425 \\u20ac\",\"name\":\"Adele Hi, Echelle position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8b101c33-H_E1i_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8b101c33-H_E1i_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1i_TOSCANE\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/08f1f6d7-H_Paso1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/08f1f6d7-H_Paso1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7-2400x1714.webp\"}},\"H_P2i_TOSCANE\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/15de45c4-H_Paso4_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/15de45c4-H_Paso4_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7-2400x1714.webp\"}},\"H_O1i_TOSCANE\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ec1f6125-H_O1i_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ec1f6125-H_O1i_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7-2400x1714.webp\"}},\"H_O2i_TOSCANE\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/907e44fe-H_O2i_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/907e44fe-H_O2i_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7-2400x1714.webp\"}},\"H_W1i_TOSCANE\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/21a7d905-H_W1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/21a7d905-H_W1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7-2400x1714.webp\"}},\"H_W2i_TOSCANE\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3c886a16-H_W4_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3c886a16-H_W4_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7-2400x1714.webp\"}},\"H_Pa1i_TOSCANE\":{\"price\":\"11 125 \\u20ac\",\"name\":\"Adele Hi, Escalier Pacio position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ae51c2a0-H_Pa1i_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ae51c2a0-H_Pa1i_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1i_TOSCANE\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1fddd791-H_En1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1fddd791-H_En1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\"}},\"H_En2i_TOSCANE\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/76f0d43d-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/eb733b1d-H_En4_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/eb733b1d-H_En4_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\"}},\"H_E1i_GRIS\":{\"price\":\"8 425 \\u20ac\",\"name\":\"Adele Hi, Echelle position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/875595e7-H_E1i_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/875595e7-H_E1i_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1i_GRIS\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/75fd8299-H_Paso1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/75fd8299-H_Paso1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7-2400x1714.webp\"}},\"H_P2i_GRIS\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/93d449dd-H_Paso4_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/93d449dd-H_Paso4_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7-2400x1714.webp\"}},\"H_O1i_GRIS\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6d627d86-H_O1i_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6d627d86-H_O1i_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7-2400x1714.webp\"}},\"H_O2i_GRIS\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f4801b87-H_O2i_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f4801b87-H_O2i_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7-2400x1714.webp\"}},\"H_W1i_GRIS\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/72fe998e-H_W1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/72fe998e-H_W1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7-2400x1714.webp\"}},\"H_W2i_GRIS\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94d752ca-H_W4_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94d752ca-H_W4_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7-2400x1714.webp\"}},\"H_Pa1i_GRIS\":{\"price\":\"11 125 \\u20ac\",\"name\":\"Adele Hi, Escalier Pacio position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/04c3e7d0-H_Pa1i_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/04c3e7d0-H_Pa1i_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1i_GRIS\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dca2e738-H_En1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dca2e738-H_En1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\"}},\"H_En2i_GRIS\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7dc53f5-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/58018955-H_En4_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/58018955-H_En4_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\"}},\"H_E1i_ARDOISE\":{\"price\":\"8 759 \\u20ac\",\"name\":\"Adele Hi, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/95481b37-H_E1i_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/95481b37-H_E1i_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1i_ARDOISE\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16a9f1d3-H_Paso1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16a9f1d3-H_Paso1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7-2400x1714.webp\"}},\"H_P2i_ARDOISE\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0b8642c0-H_Paso4_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0b8642c0-H_Paso4_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7-2400x1714.webp\"}},\"H_O1i_ARDOISE\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f2476621-H_O1i_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f2476621-H_O1i_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7-2400x1714.webp\"}},\"H_O2i_ARDOISE\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8e2643fa-H_O2i_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8e2643fa-H_O2i_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7-2400x1714.webp\"}},\"H_W1i_ARDOISE\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3fffde01-H_W1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3fffde01-H_W1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7-2400x1714.webp\"}},\"H_W2i_ARDOISE\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/22d06d12-H_W4_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/22d06d12-H_W4_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7-2400x1714.webp\"}},\"H_Pa1i_ARDOISE\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Adele Hi, Escalier Pacio position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b009c5a4-H_Pa1i_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b009c5a4-H_Pa1i_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1i_ARDOISE\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1d9dbc7c-H_En1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1d9dbc7c-H_En1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\"}},\"H_En2i_ARDOISE\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b0833fe-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e93350f0-H_En4_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e93350f0-H_En4_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\"}},\"H_E1i_ARGENT\":{\"price\":\"8 759 \\u20ac\",\"name\":\"Adele Hi, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5a79854f-H_E1i_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5a79854f-H_E1i_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1i_ARGENT\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6816a658-H_Paso1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6816a658-H_Paso1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7-2400x1714.webp\"}},\"H_P2i_ARGENT\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f0b5d148-H_Paso4_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f0b5d148-H_Paso4_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7-2400x1714.webp\"}},\"H_O1i_ARGENT\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/884e5fd4-H_O1i_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/884e5fd4-H_O1i_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7-2400x1714.webp\"}},\"H_O2i_ARGENT\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3584331a-H_O2i_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3584331a-H_O2i_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7-2400x1714.webp\"}},\"H_W1i_ARGENT\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7f0ec21-H_W1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e7f0ec21-H_W1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7-2400x1714.webp\"}},\"H_W2i_ARGENT\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7f539b31-H_W4_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7f539b31-H_W4_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7-2400x1714.webp\"}},\"H_Pa1i_ARGENT\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Adele Hi, Escalier Pacio position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7475b6fd-H_Pa1i_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7475b6fd-H_Pa1i_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1i_ARGENT\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7094da16-H_En1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7094da16-H_En1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\"}},\"H_En2i_ARGENT\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e52c6010-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0acd0700-H_En4_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0acd0700-H_En4_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\"}},\"H_E1i_BALI\":{\"price\":\"8 982 \\u20ac\",\"name\":\"Adele Hi, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e31e0340-H_E1i_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e31e0340-H_E1i_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1i_BALI\":{\"price\":\"11 102 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/11b6143e-H_Paso1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/11b6143e-H_Paso1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b34fcf8-H_Paso1_pos_V7-2400x1714.webp\"}},\"H_P2i_BALI\":{\"price\":\"11 102 \\u20ac\",\"name\":\"Adele Hi, Escalier Paso position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f79fdf7a-H_Paso4_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f79fdf7a-H_Paso4_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/261b4feb-H_Paso4_pos_V7-2400x1714.webp\"}},\"H_O1i_BALI\":{\"price\":\"10 192 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0929eb21-H_O1i_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0929eb21-H_O1i_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dfda6b0a-H_O1i_pos_V7-2400x1714.webp\"}},\"H_O2i_BALI\":{\"price\":\"10 192 \\u20ac\",\"name\":\"Adele Hi, Escalier Orbis position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/90cb8d20-H_O2i_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/90cb8d20-H_O2i_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3bb4ed1-H_O2i_pos_V7-2400x1714.webp\"}},\"H_W1i_BALI\":{\"price\":\"11 512 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16b50f29-H_W1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16b50f29-H_W1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1262d32a-H_W1_pos_V7-2400x1714.webp\"}},\"H_W2i_BALI\":{\"price\":\"11 512 \\u20ac\",\"name\":\"Adele Hi, Escalier Welcome position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f09cc46d-H_W4_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f09cc46d-H_W4_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f4d6039-H_W4_pos_V7-2400x1714.webp\"}},\"H_Pa1i_BALI\":{\"price\":\"11 682 \\u20ac\",\"name\":\"Adele Hi, Escalier Pacio position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/60887177-H_Pa1i_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/60887177-H_Pa1i_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1i_BALI\":{\"price\":\"11 402 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/acd23149-H_En1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/acd23149-H_En1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a0c9ec1b-H_En1_pos_V9.webp\"}},\"H_En2i_BALI\":{\"price\":\"11 402 \\u20ac\",\"name\":\"Adele Hi, Escalier Enjoy position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdfeadf0-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/28715f24-H_En4_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/28715f24-H_En4_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/bde65f08-H_En4_pos_V9.webp\"}},\"H_E1_TOSCANE\":{\"price\":\"8 425 \\u20ac\",\"name\":\"Adele H, Echelle position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0d1660c8-H_E1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0d1660c8-H_E1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1_TOSCANE\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/66400077-H_Paso2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/66400077-H_Paso2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7-2400x1714.webp\"}},\"H_P2_TOSCANE\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bbd6d9f2-H_Paso3_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bbd6d9f2-H_Paso3_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7-2400x1714.webp\"}},\"H_O1_TOSCANE\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/df21ba53-H_O1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/df21ba53-H_O1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7-2400x1714.webp\"}},\"H_O2_TOSCANE\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/62ebd69d-H_O2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/62ebd69d-H_O2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7-2400x1714.webp\"}},\"H_W1_TOSCANE\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3700f4c7-H_W2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3700f4c7-H_W2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7-2400x1714.webp\"}},\"H_W2_TOSCANE\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4ac7abbb-H_W3_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4ac7abbb-H_W3_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7-2400x1714.webp\"}},\"H_Pa1_TOSCANE\":{\"price\":\"11 125 \\u20ac\",\"name\":\"Adele H, Escalier Pacio position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/816a331c-H_Pa1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/816a331c-H_Pa1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1_TOSCANE\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 1, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a7e3631d-H_En2_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a7e3631d-H_En2_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\"}},\"H_En2_TOSCANE\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 2, liner Toscane\",\"img_base\":\"Base_H_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/07a474ba-Base_TOSCANE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2045a85e-H_En3_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2045a85e-H_En3_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\"}},\"H_E1_GRIS\":{\"price\":\"8 425 \\u20ac\",\"name\":\"Adele H, Echelle position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/88852890-H_E1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/88852890-H_E1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1_GRIS\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/35a77896-H_Paso2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/35a77896-H_Paso2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7-2400x1714.webp\"}},\"H_P2_GRIS\":{\"price\":\"10 545 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/da6513a8-H_Paso3_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/da6513a8-H_Paso3_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7-2400x1714.webp\"}},\"H_O1_GRIS\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6a2a7014-H_O1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6a2a7014-H_O1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7-2400x1714.webp\"}},\"H_O2_GRIS\":{\"price\":\"9 635 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/811dcb17-H_O2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/811dcb17-H_O2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7-2400x1714.webp\"}},\"H_W1_GRIS\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9528ee99-H_W2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9528ee99-H_W2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7-2400x1714.webp\"}},\"H_W2_GRIS\":{\"price\":\"10 955 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f88b3d7-H_W3_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0f88b3d7-H_W3_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7-2400x1714.webp\"}},\"H_Pa1_GRIS\":{\"price\":\"11 125 \\u20ac\",\"name\":\"Adele H, Escalier Pacio position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/db452122-H_Pa1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/db452122-H_Pa1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1_GRIS\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 1, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0dad5784-H_En2_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/0dad5784-H_En2_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\"}},\"H_En2_GRIS\":{\"price\":\"10 845 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 2, liner Gris\",\"img_base\":\"Base_H_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/314e0410-Base_GRIS_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/90a2b6f2-H_En3_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/90a2b6f2-H_En3_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\"}},\"H_E1_ARDOISE\":{\"price\":\"8 759 \\u20ac\",\"name\":\"Adele H, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/134e67cc-H_E1_ARDOISE.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/134e67cc-H_E1_ARDOISE.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1_ARDOISE\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/78180773-H_Paso2_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/78180773-H_Paso2_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7-2400x1714.webp\"}},\"H_P2_ARDOISE\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a58edef6-H_Paso3_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a58edef6-H_Paso3_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7-2400x1714.webp\"}},\"H_O1_ARDOISE\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c179bd57-H_O1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c179bd57-H_O1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7-2400x1714.webp\"}},\"H_O2_ARDOISE\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7cb3d199-H_O2_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7cb3d199-H_O2_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7-2400x1714.webp\"}},\"H_W1_ARDOISE\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2958f3c3-H_W2_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2958f3c3-H_W2_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7-2400x1714.webp\"}},\"H_W2_ARDOISE\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4887c056-H_W3_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4887c056-H_W3_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7-2400x1714.webp\"}},\"H_Pa1_ARDOISE\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Adele H, Escalier Pacio position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9f323418-H_Pa1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9f323418-H_Pa1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1_ARDOISE\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a5a308f0-H_En2_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a5a308f0-H_En2_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\"}},\"H_En2_ARDOISE\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_H_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/05e41f57-Base_ARDOISE_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2205c3b3-H_En3_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/2205c3b3-H_En3_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\"}},\"H_E1_ARGENT\":{\"price\":\"8 759 \\u20ac\",\"name\":\"Adele H, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fd7aa9f-H_E1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fd7aa9f-H_E1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1_ARGENT\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b2e6e1cf-H_Paso2_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b2e6e1cf-H_Paso2_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7-2400x1714.webp\"}},\"H_P2_ARGENT\":{\"price\":\"10 879 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2943ada0-H_Paso3_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2943ada0-H_Paso3_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7-2400x1714.webp\"}},\"H_O1_ARGENT\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b588ccb9-H_O1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b588ccb9-H_O1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7-2400x1714.webp\"}},\"H_O2_ARGENT\":{\"price\":\"9 969 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c2161e49-H_O2_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c2161e49-H_O2_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7-2400x1714.webp\"}},\"H_W1_ARGENT\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2c126bfe-H_W2_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2c126bfe-H_W2_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7-2400x1714.webp\"}},\"H_W2_ARGENT\":{\"price\":\"11 289 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/eaf400b0-H_W3_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/eaf400b0-H_W3_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7-2400x1714.webp\"}},\"H_Pa1_ARGENT\":{\"price\":\"11 459 \\u20ac\",\"name\":\"Adele H, Escalier Pacio position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/20f88dc1-H_Pa1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/20f88dc1-H_Pa1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1_ARGENT\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 1, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f3855921-H_En2_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f3855921-H_En2_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\"}},\"H_En2_ARGENT\":{\"price\":\"11 179 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 2, liner Gris Argent\",\"img_base\":\"Base_H_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3b4a59d0-Base_ARGENT_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5dedc8b0-H_En3_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5dedc8b0-H_En3_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\"}},\"H_E1_BALI\":{\"price\":\"8 982 \\u20ac\",\"name\":\"Adele H, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/eccebe37-H_E1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/eccebe37-H_E1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_P1_BALI\":{\"price\":\"11 102 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/51ecee31-H_Paso2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/51ecee31-H_Paso2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55850a58-H_Paso2_pos_V7-2400x1714.webp\"}},\"H_P2_BALI\":{\"price\":\"11 102 \\u20ac\",\"name\":\"Adele H, Escalier Paso position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/be2e850f-H_Paso3_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/be2e850f-H_Paso3_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8813d3dd-H_Paso3_pos_V7-2400x1714.webp\"}},\"H_O1_BALI\":{\"price\":\"10 192 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0e61e6b3-H_O1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0e61e6b3-H_O1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ece4b07c-H_O1_pos_V7-2400x1714.webp\"}},\"H_O2_BALI\":{\"price\":\"10 192 \\u20ac\",\"name\":\"Adele H, Escalier Orbis position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e5565db0-H_O2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e5565db0-H_O2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/512edcb2-H_O2_pos_V7-2400x1714.webp\"}},\"H_W1_BALI\":{\"price\":\"11 512 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f163783e-H_W2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f163783e-H_W2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/04c5fee8-H_W2_pos_V7-2400x1714.webp\"}},\"H_W2_BALI\":{\"price\":\"11 512 \\u20ac\",\"name\":\"Adele H, Escalier Welcome position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7ff865a6-H_W3_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7ff865a6-H_W3_BALI_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d953276d-H_W3_pos_V7-2400x1714.webp\"}},\"H_Pa1_BALI\":{\"price\":\"11 682 \\u20ac\",\"name\":\"Adele H, Escalier Pacio position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bf0eb785-H_Pa1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bf0eb785-H_Pa1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"H_En1_BALI\":{\"price\":\"11 402 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 1, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7ddd81f5-H_En2_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7ddd81f5-H_En2_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/141ea1bf-H_En2_pos_V9.webp\"}},\"H_En2_BALI\":{\"price\":\"11 402 \\u20ac\",\"name\":\"Adele H, Escalier Enjoy position 2, liner Pierre de Bali\",\"img_base\":\"Base_H_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/413ed261-Base_BALI_V7.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e0d26083-H_En3_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e0d26083-H_En3_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c988783a-H_En3_pos_V9.webp\"}},\"O_E1_TOSCANE\":{\"price\":\"8 250 \\u20ac\",\"name\":\"Ilona, Echelle position 1, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8a46ce5c-O_E1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8a46ce5c-O_E1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"O_P1_TOSCANE\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 1, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a7fbc81-O_Paso1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a7fbc81-O_Paso1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7-2400x1714.webp\"}},\"O_P2_TOSCANE\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 2, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b30f19fa-O_Paso2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b30f19fa-O_Paso2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7-2400x1714.webp\"}},\"O_P3_TOSCANE\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 3, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/34a9d2b9-O_Paso3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/34a9d2b9-O_Paso3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7-2400x1714.webp\"}},\"O_P4_TOSCANE\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 4, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/143baef2-O_Paso4_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/143baef2-O_Paso4_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7-2400x1714.webp\"}},\"O_O1_TOSCANE\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 1, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/587114c7-O_O1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/587114c7-O_O1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7-2400x1714.webp\"}},\"O_O2_TOSCANE\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 2, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/91f87ea9-O_O2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/91f87ea9-O_O2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7-2400x1714.webp\"}},\"O_O3_TOSCANE\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 3, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/165eb5ea-O_O3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/165eb5ea-O_O3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7-2400x1714.webp\"}},\"O_O4_TOSCANE\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 4, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/36ccc9a1-O_O4_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/36ccc9a1-O_O4_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7-2400x1714.webp\"}},\"O_W1_TOSCANE\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 1, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/470ec4e7-O_W1_TOSCANE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/470ec4e7-O_W1_TOSCANE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7-2400x1714.webp\"}},\"O_W2_TOSCANE\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 2, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14949f63-O_W2_TOSCANE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14949f63-O_W2_TOSCANE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7-2400x1714.webp\"}},\"O_W3_TOSCANE\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 3, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/93325420-O_W3_TOSCANE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/93325420-O_W3_TOSCANE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7-2400x1714.webp\"}},\"O_W4_TOSCANE\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 4, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b3a0286b-O_W4_TOSCANE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b3a0286b-O_W4_TOSCANE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7-2400x1714.webp\"}},\"O_Pa1_TOSCANE\":{\"price\":\"10 950 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 1, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c94025e0-O_Pa1_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c94025e0-O_Pa1_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7-2400x1714.webp\"}},\"O_Pa2_TOSCANE\":{\"price\":\"10 950 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 2, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/9ada7e64-O_Pa2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/9ada7e64-O_Pa2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7-2400x1714.webp\"}},\"O_En1_TOSCANE\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 1, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6535f743-O_En1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6535f743-O_En1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\"}},\"O_En2_TOSCANE\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 2, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/36afacc7-O_En2_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/36afacc7-O_En2_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\"}},\"O_En3_TOSCANE\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 3, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b1096784-O_En3_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b1096784-O_En3_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\"}},\"O_En4_TOSCANE\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 4, liner Toscane\",\"img_base\":\"Base_O_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4e401520-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/919b1bcf-O_En4_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/919b1bcf-O_En4_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\"}},\"O_E1_GRIS\":{\"price\":\"8 250 \\u20ac\",\"name\":\"Ilona, Echelle position 1, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32dcd3c8-O_E1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32dcd3c8-O_E1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"O_P1_GRIS\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 1, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/59c06d01-O_Paso1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/59c06d01-O_Paso1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7-2400x1714.webp\"}},\"O_P2_GRIS\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 2, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3cdc4d9c-O_Paso2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3cdc4d9c-O_Paso2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7-2400x1714.webp\"}},\"O_P3_GRIS\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 3, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a1d3acea-O_Paso3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a1d3acea-O_Paso3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7-2400x1714.webp\"}},\"O_P4_GRIS\":{\"price\":\"10 370 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 4, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c41e062a-O_Paso4_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c41e062a-O_Paso4_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7-2400x1714.webp\"}},\"O_O1_GRIS\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 1, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d0738b4c-O_O1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d0738b4c-O_O1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7-2400x1714.webp\"}},\"O_O2_GRIS\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 2, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a341a791-O_O2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a341a791-O_O2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7-2400x1714.webp\"}},\"O_O3_GRIS\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 3, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3e4e46e7-O_O3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3e4e46e7-O_O3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7-2400x1714.webp\"}},\"O_O4_GRIS\":{\"price\":\"9 460 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 4, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5b83ec27-O_O4_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5b83ec27-O_O4_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7-2400x1714.webp\"}},\"O_W1_GRIS\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 1, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e855c25c-O_W1_GRIS_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e855c25c-O_W1_GRIS_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7-2400x1714.webp\"}},\"O_W2_GRIS\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 2, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9434e787-O_W2_GRIS_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9434e787-O_W2_GRIS_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7-2400x1714.webp\"}},\"O_W3_GRIS\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 3, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/093b06f1-O_W3_GRIS_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/093b06f1-O_W3_GRIS_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7-2400x1714.webp\"}},\"O_W4_GRIS\":{\"price\":\"10 780 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 4, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6cf6ac31-O_W4_GRIS_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6cf6ac31-O_W4_GRIS_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7-2400x1714.webp\"}},\"O_Pa1_GRIS\":{\"price\":\"10 950 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 1, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/eabbd490-O_Pa1_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/eabbd490-O_Pa1_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7-2400x1714.webp\"}},\"O_Pa2_GRIS\":{\"price\":\"10 950 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 2, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/96daf14b-O_Pa2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/96daf14b-O_Pa2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7-2400x1714.webp\"}},\"O_En1_GRIS\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 1, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/558f34fe-O_En1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/558f34fe-O_En1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\"}},\"O_En2_GRIS\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 2, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/29ee1125-O_En2_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/29ee1125-O_En2_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\"}},\"O_En3_GRIS\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 3, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b4e1f053-O_En3_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b4e1f053-O_En3_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\"}},\"O_En4_GRIS\":{\"price\":\"10 670 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 4, liner Gris\",\"img_base\":\"Base_O_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/36184418-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/d12c5a93-O_En4_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/d12c5a93-O_En4_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\"}},\"O_E1_ARDOISE\":{\"price\":\"8 545 \\u20ac\",\"name\":\"Ilona, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/941ec958-O_E1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/941ec958-O_E1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"O_P1_ARDOISE\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6427bb85-O_Paso1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6427bb85-O_Paso1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7-2400x1714.webp\"}},\"O_P2_ARDOISE\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b14f7217-O_Paso2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b14f7217-O_Paso2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7-2400x1714.webp\"}},\"O_P3_ARDOISE\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/36e9b954-O_Paso3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/36e9b954-O_Paso3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7-2400x1714.webp\"}},\"O_P4_ARDOISE\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/167bc51f-O_Paso4_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/167bc51f-O_Paso4_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7-2400x1714.webp\"}},\"O_O1_ARDOISE\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/462913c3-O_O1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/462913c3-O_O1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7-2400x1714.webp\"}},\"O_O2_ARDOISE\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/93b81544-O_O2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/93b81544-O_O2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7-2400x1714.webp\"}},\"O_O3_ARDOISE\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/141ede07-O_O3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/141ede07-O_O3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7-2400x1714.webp\"}},\"O_O4_ARDOISE\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/348ca24c-O_O4_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/348ca24c-O_O4_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7-2400x1714.webp\"}},\"O_W1_ARDOISE\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454eaf0a-O_W1_ARDOISE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454eaf0a-O_W1_ARDOISE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7-2400x1714.webp\"}},\"O_W2_ARDOISE\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/16d4f48e-O_W2_ARDOISE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/16d4f48e-O_W2_ARDOISE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7-2400x1714.webp\"}},\"O_W3_ARDOISE\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/91723fcd-O_W3_ARDOISE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/91723fcd-O_W3_ARDOISE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7-2400x1714.webp\"}},\"O_W4_ARDOISE\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b1e04386-O_W4_ARDOISE_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b1e04386-O_W4_ARDOISE_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7-2400x1714.webp\"}},\"O_Pa1_ARDOISE\":{\"price\":\"11 245 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cb004e0d-O_Pa1_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cb004e0d-O_Pa1_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7-2400x1714.webp\"}},\"O_Pa2_ARDOISE\":{\"price\":\"11 245 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/989a1589-O_Pa2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/989a1589-O_Pa2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7-2400x1714.webp\"}},\"O_En1_ARDOISE\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/67759cae-O_En1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/67759cae-O_En1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\"}},\"O_En2_ARDOISE\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/34efc72a-O_En2_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/34efc72a-O_En2_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\"}},\"O_En3_ARDOISE\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b3490c69-O_En3_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b3490c69-O_En3_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\"}},\"O_En4_ARDOISE\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_O_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63b8f2e3-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/93db7022-O_En4_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/93db7022-O_En4_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\"}},\"O_E1_ARGENT\":{\"price\":\"8 545 \\u20ac\",\"name\":\"Ilona, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d7daec0e-O_E1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d7daec0e-O_E1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"O_P1_ARGENT\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 1, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e13b759e-O_Paso1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e13b759e-O_Paso1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7-2400x1714.webp\"}},\"O_P2_ARGENT\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 2, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ac91dc47-O_Paso2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ac91dc47-O_Paso2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7-2400x1714.webp\"}},\"O_P3_ARGENT\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 3, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/02f94dd6-O_Paso3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/02f94dd6-O_Paso3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7-2400x1714.webp\"}},\"O_P4_ARGENT\":{\"price\":\"10 665 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 4, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ff00b5a3-O_Paso4_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ff00b5a3-O_Paso4_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7-2400x1714.webp\"}},\"O_O1_ARGENT\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 1, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e6adee22-O_O1_ARGENT_V4-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e6adee22-O_O1_ARGENT_V4-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7-2400x1714.webp\"}},\"O_O2_ARGENT\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 2, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/59e036f1-O_O2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/59e036f1-O_O2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7-2400x1714.webp\"}},\"O_O3_ARGENT\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 3, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f788a760-O_O3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f788a760-O_O3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7-2400x1714.webp\"}},\"O_O4_ARGENT\":{\"price\":\"9 755 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 4, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0a715f15-O_O4_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0a715f15-O_O4_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7-2400x1714.webp\"}},\"O_W1_ARGENT\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 1, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3df7473e-O_W1_ARGENT_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3df7473e-O_W1_ARGENT_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7-2400x1714.webp\"}},\"O_W2_ARGENT\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 2, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/143ff3cc-O_W2_ARGENT_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/143ff3cc-O_W2_ARGENT_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7-2400x1714.webp\"}},\"O_W3_ARGENT\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 3, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba57625d-O_W3_ARGENT_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba57625d-O_W3_ARGENT_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7-2400x1714.webp\"}},\"O_W4_ARGENT\":{\"price\":\"11 075 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 4, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/47ae9a28-O_W4_ARGENT_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/47ae9a28-O_W4_ARGENT_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7-2400x1714.webp\"}},\"O_Pa1_ARGENT\":{\"price\":\"11 245 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 1, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/89f76ecc-O_Pa1_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/89f76ecc-O_Pa1_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7-2400x1714.webp\"}},\"O_Pa2_ARGENT\":{\"price\":\"11 245 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 2, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a03fda3e-O_Pa2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a03fda3e-O_Pa2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7-2400x1714.webp\"}},\"O_En1_ARGENT\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 1, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f2eea09d-O_En1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f2eea09d-O_En1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\"}},\"O_En2_ARGENT\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 2, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/db26146f-O_En2_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/db26146f-O_En2_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\"}},\"O_En3_ARGENT\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 3, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/754e85fe-O_En3_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/754e85fe-O_En3_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\"}},\"O_En4_ARGENT\":{\"price\":\"10 965 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 4, liner Gris Argent\",\"img_base\":\"Base_O_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3f0f65a2-Base_ARGENT_V4.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/88b77d8b-O_En4_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/88b77d8b-O_En4_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\"}},\"O_E1_BALI\":{\"price\":\"8 742 \\u20ac\",\"name\":\"Ilona, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5697456f-O_E1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5697456f-O_E1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"O_P1_BALI\":{\"price\":\"10 862 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 1, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3d8bfba6-O_Paso1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3d8bfba6-O_Paso1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49bab6ae-O_Paso1_pos_V7-2400x1714.webp\"}},\"O_P2_BALI\":{\"price\":\"10 862 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 2, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4cac9bed-O_Paso2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4cac9bed-O_Paso2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f470da60-O_Paso2_pos_V7-2400x1714.webp\"}},\"O_P3_BALI\":{\"price\":\"10 862 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 3, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d1a37a9b-O_Paso3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d1a37a9b-O_Paso3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29e603e5-O_Paso3_pos_V7-2400x1714.webp\"}},\"O_P4_BALI\":{\"price\":\"10 862 \\u20ac\",\"name\":\"Ilona, Escalier Paso position 4, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b46ed05b-O_Paso4_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b46ed05b-O_Paso4_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/549505bd-O_Paso4_pos_V7-2400x1714.webp\"}},\"O_O1_BALI\":{\"price\":\"9 952 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 1, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b4381deb-O_O1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b4381deb-O_O1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6bb41ee8-O_O1_pos_V7-2400x1714.webp\"}},\"O_O2_BALI\":{\"price\":\"9 952 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 2, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d33171e0-O_O2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d33171e0-O_O2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d67e7226-O_O2_pos_V7-2400x1714.webp\"}},\"O_O3_BALI\":{\"price\":\"9 952 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 3, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4e3e9096-O_O3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4e3e9096-O_O3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/0be8aba3-O_O3_pos_V7-2400x1714.webp\"}},\"O_O4_BALI\":{\"price\":\"9 952 \\u20ac\",\"name\":\"Ilona, Escalier Orbis position 4, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2bf33a56-O_O4_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2bf33a56-O_O4_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/769badfb-O_O4_pos_V7-2400x1714.webp\"}},\"O_W1_BALI\":{\"price\":\"11 272 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 1, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9825142d-O_W1_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9825142d-O_W1_BALI_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3e5f3cb2-O_W1_pos_V7-2400x1714.webp\"}},\"O_W2_BALI\":{\"price\":\"11 272 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 2, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e44431f6-O_W2_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e44431f6-O_W2_BALI_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8395507c-O_W2_pos_V7-2400x1714.webp\"}},\"O_W3_BALI\":{\"price\":\"11 272 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 3, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/794bd080-O_W3_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/794bd080-O_W3_BALI_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5e0389f9-O_W3_pos_V7-2400x1714.webp\"}},\"O_W4_BALI\":{\"price\":\"11 272 \\u20ac\",\"name\":\"Ilona, Escalier Welcome position 4, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1c867a40-O_W4_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1c867a40-O_W4_BALI_V8-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/23708fa1-O_W4_pos_V7-2400x1714.webp\"}},\"O_Pa1_BALI\":{\"price\":\"11 442 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 1, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/9acb02e1-O_Pa1_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/9acb02e1-O_Pa1_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/454a3ec0-O_Pa1_pos_V7-2400x1714.webp\"}},\"O_Pa2_BALI\":{\"price\":\"11 442 \\u20ac\",\"name\":\"Ilona, Escalier Pacio position 2, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e6aa273a-O_Pa2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e6aa273a-O_Pa2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f880520e-O_Pa2_pos_V7-2400x1714.webp\"}},\"O_En1_BALI\":{\"price\":\"11 162 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 1, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/25ffe28f-O_En1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/25ffe28f-O_En1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/5e31ca82-O_En1_pos_V9.webp\"}},\"O_En2_BALI\":{\"price\":\"11 162 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 2, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/599ec754-O_En2_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/599ec754-O_En2_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/e3fba64c-O_En2_pos_V9.webp\"}},\"O_En3_BALI\":{\"price\":\"11 162 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 3, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c4912622-O_En3_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c4912622-O_En3_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3e6d7fc9-O_En3_pos_V9.webp\"}},\"O_En4_BALI\":{\"price\":\"11 162 \\u20ac\",\"name\":\"Ilona, Escalier Enjoy position 4, liner Pierre de Bali\",\"img_base\":\"Base_O_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/671f1b0c-Base_BALI_V8-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a15c8ce2-O_En4_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/a15c8ce2-O_En4_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/431e7991-O_En4_pos_V9.webp\"}},\"OMini_E1_TOSCANE\":{\"price\":\"6 790 \\u20ac\",\"name\":\"Mini Ilona, Echelle position 1, liner Toscane\",\"img_base\":\"Base_OMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32622083-O_E1_TOSCANE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32622083-O_E1_TOSCANE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"OMini_P1_TOSCANE\":{\"price\":\"8 910 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 1, liner Toscane\",\"img_base\":\"Base_OMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e4705e60-O_Paso1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e4705e60-O_Paso1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7-2400x1714.webp\"}},\"OMini_P2_TOSCANE\":{\"price\":\"8 910 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 2, liner Toscane\",\"img_base\":\"Base_OMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6111eb4b-O_Paso2_TOSCANE_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6111eb4b-O_Paso2_TOSCANE_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7-2400x1714.webp\"}},\"OMini_O1_TOSCANE\":{\"price\":\"8 000 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 1, liner Toscane\",\"img_base\":\"Base_OMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5839592a-O_O1_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5839592a-O_O1_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7-2400x1714.webp\"}},\"OMini_O2_TOSCANE\":{\"price\":\"8 000 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 2, liner Toscane\",\"img_base\":\"Base_OMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d04ff7c1-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c0ffd10b-O_O2_TOSCANE_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c0ffd10b-O_O2_TOSCANE_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7-2400x1714.webp\"}},\"OMini_E1_GRIS\":{\"price\":\"6 790 \\u20ac\",\"name\":\"Mini Ilona, Echelle position 1, liner Gris\",\"img_base\":\"Base_OMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c653f6e1-O_E1_GRIS_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c653f6e1-O_E1_GRIS_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"OMini_P1_GRIS\":{\"price\":\"8 910 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 1, liner Gris\",\"img_base\":\"Base_OMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/26525f50-O_Paso1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/26525f50-O_Paso1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7-2400x1714.webp\"}},\"OMini_P2_GRIS\":{\"price\":\"8 910 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 2, liner Gris\",\"img_base\":\"Base_OMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6ddbe23e-O_Paso2_GRIS_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6ddbe23e-O_Paso2_GRIS_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7-2400x1714.webp\"}},\"OMini_O1_GRIS\":{\"price\":\"8 000 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 1, liner Gris\",\"img_base\":\"Base_OMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8efbd011-O_O1_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8efbd011-O_O1_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7-2400x1714.webp\"}},\"OMini_O2_GRIS\":{\"price\":\"8 000 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 2, liner Gris\",\"img_base\":\"Base_OMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/498a7649-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/39c6266f-O_O2_GRIS_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/39c6266f-O_O2_GRIS_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7-2400x1714.webp\"}},\"OMini_E1_ARDOISE\":{\"price\":\"7 007 \\u20ac\",\"name\":\"Mini Ilona, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_OMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1f9ac740-O_E1_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1f9ac740-O_E1_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"OMini_P1_ARDOISE\":{\"price\":\"9 127 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_OMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fa285964-O_Paso1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fa285964-O_Paso1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7-2400x1714.webp\"}},\"OMini_P2_ARDOISE\":{\"price\":\"9 127 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_OMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/635180a6-O_Paso2_ARDOISE_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/635180a6-O_Paso2_ARDOISE_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7-2400x1714.webp\"}},\"OMini_O1_ARDOISE\":{\"price\":\"8 217 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_OMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5a7932c7-O_O1_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5a7932c7-O_O1_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7-2400x1714.webp\"}},\"OMini_O2_ARDOISE\":{\"price\":\"8 217 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_OMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5658888d-Base_ARDOISE_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c2bfbae6-O_O2_ARDOISE_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c2bfbae6-O_O2_ARDOISE_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7-2400x1714.webp\"}},\"OMini_E1_ARGENT\":{\"price\":\"7 007 \\u20ac\",\"name\":\"Mini Ilona, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_OMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f629e3a9-O_E1_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f629e3a9-O_E1_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"OMini_P1_ARGENT\":{\"price\":\"9 127 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 1, liner Gris Argent\",\"img_base\":\"Base_OMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8a4c3799-O_Paso1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8a4c3799-O_Paso1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7-2400x1714.webp\"}},\"OMini_P2_ARGENT\":{\"price\":\"9 127 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 2, liner Gris Argent\",\"img_base\":\"Base_OMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/7ed2981f-O_Paso2_ARGENT_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/7ed2981f-O_Paso2_ARGENT_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7-2400x1714.webp\"}},\"OMini_O1_ARGENT\":{\"price\":\"8 217 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 1, liner Gris Argent\",\"img_base\":\"Base_OMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3efc1e9-O_O1_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3efc1e9-O_O1_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7-2400x1714.webp\"}},\"OMini_O2_ARGENT\":{\"price\":\"8 217 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 2, liner Gris Argent\",\"img_base\":\"Base_OMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/03464149-Base_ARGENT_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/417ba6be-O_O2_ARGENT_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/417ba6be-O_O2_ARGENT_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7-2400x1714.webp\"}},\"OMini_E1_BALI\":{\"price\":\"7 151 \\u20ac\",\"name\":\"Mini Ilona, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_OMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/dc7108e4-O_E1_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/dc7108e4-O_E1_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"OMini_P1_BALI\":{\"price\":\"9 271 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 1, liner Pierre de Bali\",\"img_base\":\"Base_OMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4219c9f7-O_Paso1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4219c9f7-O_Paso1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d7b5544f-O_Paso1_pos_V7-2400x1714.webp\"}},\"OMini_P2_BALI\":{\"price\":\"9 271 \\u20ac\",\"name\":\"Mini Ilona, Escalier Paso position 2, liner Pierre de Bali\",\"img_base\":\"Base_OMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1dab344f-O_Paso2_BALI_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1dab344f-O_Paso2_BALI_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6a7f3881-O_Paso2_pos_V7-2400x1714.webp\"}},\"OMini_O1_BALI\":{\"price\":\"8 361 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 1, liner Pierre de Bali\",\"img_base\":\"Base_OMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fe8b0660-O_O1_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/fe8b0660-O_O1_BALI_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/14262cb9-O_O1_pos_V7-2400x1714.webp\"}},\"OMini_O2_BALI\":{\"price\":\"8 361 \\u20ac\",\"name\":\"Mini Ilona, Escalier Orbis position 2, liner Pierre de Bali\",\"img_base\":\"Base_OMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c792fb82-Base_BALI_V5-2400x1714.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/49b6f01e-O_O2_BALI_V6-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/49b6f01e-O_O2_BALI_V6-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a9ec4077-O_O2_pos_V7-2400x1714.webp\"}},\"RC_E1_TOSCANE\":{\"price\":\"8 344 \\u20ac\",\"name\":\"Romy, Echelle position 1, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b4325329-RC_E1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b4325329-RC_E1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RC_L1_TOSCANE\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 1, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/46348310-RC_L1_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/46348310-RC_L1_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7-2400x1714.webp\"}},\"RC_L2_TOSCANE\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 2, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7aec0a7-RC_L2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7aec0a7-RC_L2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7-2400x1714.webp\"}},\"RC_L3_TOSCANE\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 3, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a381922-RC_L3_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a381922-RC_L3_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7-2400x1714.webp\"}},\"RC_L4_TOSCANE\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 4, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b29a6f9c-RC_L4_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b29a6f9c-RC_L4_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7-2400x1714.webp\"}},\"RC_P1_TOSCANE\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 1, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e39b71f2-RC_Paso1_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e39b71f2-RC_Paso1_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RC_P2_TOSCANE\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 2, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b0012a76-RC_Paso2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b0012a76-RC_Paso2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RC_P3_TOSCANE\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 3, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/37a7e135-RC_Paso3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/37a7e135-RC_Paso3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RC_P4_TOSCANE\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 4, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a6ede465-RC_Paso4_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a6ede465-RC_Paso4_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RC_O1_TOSCANE\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 1, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/660589b2-RC_O1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/660589b2-RC_O1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7-2400x1714.webp\"}},\"RC_O2_TOSCANE\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 2, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b2e0a4fd-RC_O2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b2e0a4fd-RC_O2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7-2400x1714.webp\"}},\"RC_O3_TOSCANE\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 3, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/35466fbe-RC_O3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/35466fbe-RC_O3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7-2400x1714.webp\"}},\"RC_O4_TOSCANE\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 4, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/15d413f5-RC_O4_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/15d413f5-RC_O4_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7-2400x1714.webp\"}},\"RC_W1_TOSCANE\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 1, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d8880d6d-RC_W1_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d8880d6d-RC_W1_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7-2400x1714.webp\"}},\"RC_W2_TOSCANE\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 2, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c6daf7e2-RC_W2_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c6daf7e2-RC_W2_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7-2400x1714.webp\"}},\"RC_W3_TOSCANE\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 3, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0cb49daa-RC_W3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0cb49daa-RC_W3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7-2400x1714.webp\"}},\"RC_W4_TOSCANE\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 4, liner Toscane\",\"img_base\":\"Base_RC_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1389d9a6-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2c26e1e1-RC_W4_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2c26e1e1-RC_W4_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7-2400x1714.webp\"}},\"RC_E1_GRIS\":{\"price\":\"8 344 \\u20ac\",\"name\":\"Romy, Echelle position 1, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdb92e27-RC_E1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fdb92e27-RC_E1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RC_L1_GRIS\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 1, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3c4b816-RC_L1_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a3c4b816-RC_L1_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7-2400x1714.webp\"}},\"RC_L2_GRIS\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 2, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6dc3aba1-RC_L2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6dc3aba1-RC_L2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7-2400x1714.webp\"}},\"RC_L3_GRIS\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 3, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8201c09f-RC_L3_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8201c09f-RC_L3_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7-2400x1714.webp\"}},\"RC_L4_GRIS\":{\"price\":\"10 764 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 4, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2767d67b-RC_L4_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2767d67b-RC_L4_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7-2400x1714.webp\"}},\"RC_P1_GRIS\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 1, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/63a5b213-RC_Paso1_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/63a5b213-RC_Paso1_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RC_P2_GRIS\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 2, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1fc497c8-RC_Paso2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1fc497c8-RC_Paso2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RC_P3_GRIS\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 3, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/82cb76be-RC_Paso3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/82cb76be-RC_Paso3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RC_P4_GRIS\":{\"price\":\"10 464 \\u20ac\",\"name\":\"Romy, Escalier Paso position 4, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/819d3b30-RC_Paso4_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/819d3b30-RC_Paso4_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RC_O1_GRIS\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 1, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1f1676a3-RC_O1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1f1676a3-RC_O1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7-2400x1714.webp\"}},\"RC_O2_GRIS\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 2, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/831056bf-RC_O2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/831056bf-RC_O2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7-2400x1714.webp\"}},\"RC_O3_GRIS\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 3, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1e1fb7c9-RC_O3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/1e1fb7c9-RC_O3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7-2400x1714.webp\"}},\"RC_O4_GRIS\":{\"price\":\"9 554 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 4, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/7bd21d09-RC_O4_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/7bd21d09-RC_O4_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7-2400x1714.webp\"}},\"RC_W1_GRIS\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 1, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/749a20ac-RC_W1_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/749a20ac-RC_W1_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7-2400x1714.webp\"}},\"RC_W2_GRIS\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 2, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4533a47c-RC_W2_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4533a47c-RC_W2_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7-2400x1714.webp\"}},\"RC_W3_GRIS\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 3, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/95f4e401-RC_W3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/95f4e401-RC_W3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7-2400x1714.webp\"}},\"RC_W4_GRIS\":{\"price\":\"10 874 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 4, liner Gris\",\"img_base\":\"Base_RC_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9729fa5d-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f0394ec1-RC_W4_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f0394ec1-RC_W4_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7-2400x1714.webp\"}},\"RC_E1_ARDOISE\":{\"price\":\"8 638 \\u20ac\",\"name\":\"Romy, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6a542d-RC_E1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/aa6a542d-RC_E1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RC_L1_ARDOISE\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4474e8fd-RC_L1_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/4474e8fd-RC_L1_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7-2400x1714.webp\"}},\"RC_L2_ARDOISE\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b9f6c7a3-RC_L2_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b9f6c7a3-RC_L2_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7-2400x1714.webp\"}},\"RC_L3_ARDOISE\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/64601e26-RC_L3_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/64601e26-RC_L3_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7-2400x1714.webp\"}},\"RC_L4_ARDOISE\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b0da0471-RC_L4_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b0da0471-RC_L4_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7-2400x1714.webp\"}},\"RC_P1_ARDOISE\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e1db1a1f-RC_Paso1_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e1db1a1f-RC_Paso1_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RC_P2_ARDOISE\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b241419b-RC_Paso2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b241419b-RC_Paso2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RC_P3_ARDOISE\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/35e78ad8-RC_Paso3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/35e78ad8-RC_Paso3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RC_P4_ARDOISE\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b8b5e361-RC_Paso4_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b8b5e361-RC_Paso4_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RC_O1_ARDOISE\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/785d8eb6-RC_O1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/785d8eb6-RC_O1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7-2400x1714.webp\"}},\"RC_O2_ARDOISE\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b0a0cf10-RC_O2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b0a0cf10-RC_O2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7-2400x1714.webp\"}},\"RC_O3_ARDOISE\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/37060453-RC_O3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/37060453-RC_O3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7-2400x1714.webp\"}},\"RC_O4_ARDOISE\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/17947818-RC_O4_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/17947818-RC_O4_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7-2400x1714.webp\"}},\"RC_W1_ARDOISE\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/dac86680-RC_W1_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/dac86680-RC_W1_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7-2400x1714.webp\"}},\"RC_W2_ARDOISE\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c49a9c0f-RC_W2_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c49a9c0f-RC_W2_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7-2400x1714.webp\"}},\"RC_W3_ARDOISE\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0ef4f647-RC_W3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0ef4f647-RC_W3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7-2400x1714.webp\"}},\"RC_W4_ARDOISE\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RC_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3e713e65-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2e668a0c-RC_W4_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2e668a0c-RC_W4_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7-2400x1714.webp\"}},\"RC_E1_ARGENT\":{\"price\":\"8 638 \\u20ac\",\"name\":\"Romy, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/cd3042e9-RC_E1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/cd3042e9-RC_E1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RC_L1_ARGENT\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 1, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/afc7937b-RC_L1_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/afc7937b-RC_L1_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7-2400x1714.webp\"}},\"RC_L2_ARGENT\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 2, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dae9937-RC_L2_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dae9937-RC_L2_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7-2400x1714.webp\"}},\"RC_L3_ARGENT\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 3, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/345542df-RC_L3_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/345542df-RC_L3_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7-2400x1714.webp\"}},\"RC_L4_ARGENT\":{\"price\":\"11 058 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 4, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d59e4e6d-RC_L4_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d59e4e6d-RC_L4_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7-2400x1714.webp\"}},\"RC_P1_ARGENT\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 1, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3d88e837-RC_Paso1_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3d88e837-RC_Paso1_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RC_P2_ARGENT\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 2, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/14405cc5-RC_Paso2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/14405cc5-RC_Paso2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RC_P3_ARGENT\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 3, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ba28cd54-RC_Paso3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ba28cd54-RC_Paso3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RC_P4_ARGENT\":{\"price\":\"10 758 \\u20ac\",\"name\":\"Romy, Escalier Paso position 4, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4861c969-RC_Paso4_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4861c969-RC_Paso4_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RC_O1_ARGENT\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 1, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b51b47bc-RC_O1_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b51b47bc-RC_O1_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7-2400x1714.webp\"}},\"RC_O2_ARGENT\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 2, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/985ddd06-RC_O2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/985ddd06-RC_O2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7-2400x1714.webp\"}},\"RC_O3_ARGENT\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 3, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/36354c97-RC_O3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/36354c97-RC_O3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7-2400x1714.webp\"}},\"RC_O4_ARGENT\":{\"price\":\"9 848 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 4, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cbccb4e2-RC_O4_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cbccb4e2-RC_O4_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7-2400x1714.webp\"}},\"RC_W1_ARGENT\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 1, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/40d4bf17-RC_W1_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/40d4bf17-RC_W1_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7-2400x1714.webp\"}},\"RC_W2_ARGENT\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 2, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/24d4aaee-RC_W2_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/24d4aaee-RC_W2_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7-2400x1714.webp\"}},\"RC_W3_ARGENT\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 3, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c7749a74-RC_W3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c7749a74-RC_W3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7-2400x1714.webp\"}},\"RC_W4_ARGENT\":{\"price\":\"11 168 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 4, liner Gris Argent\",\"img_base\":\"Base_RC_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cf83d48-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3a8d6201-RC_W4_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/3a8d6201-RC_W4_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7-2400x1714.webp\"}},\"RC_E1_BALI\":{\"price\":\"8 834 \\u20ac\",\"name\":\"Romy, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/99f2b880-RC_E1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/99f2b880-RC_E1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RC_L1_BALI\":{\"price\":\"11 254 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 1, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d3b46e67-RC_L1_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d3b46e67-RC_L1_BALI_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29a1a646-RC_L1_pos_V7-2400x1714.webp\"}},\"RC_L2_BALI\":{\"price\":\"11 254 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 2, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/09883d06-RC_L2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/09883d06-RC_L2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/946bca88-RC_L2_pos_V7-2400x1714.webp\"}},\"RC_L3_BALI\":{\"price\":\"11 254 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 3, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e64a5638-RC_L3_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e64a5638-RC_L3_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49fd130d-RC_L3_pos_V7-2400x1714.webp\"}},\"RC_L4_BALI\":{\"price\":\"11 254 \\u20ac\",\"name\":\"Romy, Escalier Lobby position 4, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5717000a-RC_L4_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5717000a-RC_L4_BALI_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/348e1555-RC_L4_pos_V7-2400x1714.webp\"}},\"RC_P1_BALI\":{\"price\":\"10 954 \\u20ac\",\"name\":\"Romy, Escalier Paso position 1, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13d56462-RC_Paso1_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/13d56462-RC_Paso1_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/88075d59-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RC_P2_BALI\":{\"price\":\"10 954 \\u20ac\",\"name\":\"Romy, Escalier Paso position 2, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6fb441b9-RC_Paso2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6fb441b9-RC_Paso2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35cd3197-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RC_P3_BALI\":{\"price\":\"10 954 \\u20ac\",\"name\":\"Romy, Escalier Paso position 3, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f2bba0cf-RC_Paso3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f2bba0cf-RC_Paso3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e85be812-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RC_P4_BALI\":{\"price\":\"10 954 \\u20ac\",\"name\":\"Romy, Escalier Paso position 4, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e5d6ad97-RC_Paso4_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e5d6ad97-RC_Paso4_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9528ee4a-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RC_O1_BALI\":{\"price\":\"10 044 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 1, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7b5de004-RC_O1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7b5de004-RC_O1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/55c0839d-RC_O1_pos_V7-2400x1714.webp\"}},\"RC_O2_BALI\":{\"price\":\"10 044 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 2, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f36080ce-RC_O2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/f36080ce-RC_O2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/e80aef53-RC_O2_pos_V7-2400x1714.webp\"}},\"RC_O3_BALI\":{\"price\":\"10 044 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 3, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6e6f61b8-RC_O3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6e6f61b8-RC_O3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/359c36d6-RC_O3_pos_V7-2400x1714.webp\"}},\"RC_O4_BALI\":{\"price\":\"10 044 \\u20ac\",\"name\":\"Romy, Escalier Orbis position 4, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0ba2cb78-RC_O4_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/0ba2cb78-RC_O4_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/48ef308e-RC_O4_pos_V7-2400x1714.webp\"}},\"RC_W1_BALI\":{\"price\":\"11 364 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 1, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/04eaf6dd-RC_W1_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/04eaf6dd-RC_W1_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/002ba1c7-RC_W1_pos_V7-2400x1714.webp\"}},\"RC_W2_BALI\":{\"price\":\"11 364 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 2, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3543720d-RC_W2_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/3543720d-RC_W2_BALI_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/bde1cd09-RC_W2_pos_V7-2400x1714.webp\"}},\"RC_W3_BALI\":{\"price\":\"11 364 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 3, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e5843270-RC_W3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e5843270-RC_W3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6077148c-RC_W3_pos_V7-2400x1714.webp\"}},\"RC_W4_BALI\":{\"price\":\"11 364 \\u20ac\",\"name\":\"Romy, Escalier Welcome position 4, liner Pierre de Bali\",\"img_base\":\"Base_RC_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8d0b0458-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/804998b0-RC_W4_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/804998b0-RC_W4_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d0412d4-RC_W4_pos_V7-2400x1714.webp\"}},\"RCMini_E1_TOSCANE\":{\"price\":\"7 824 \\u20ac\",\"name\":\"Mini Romy, Echelle position 1, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a852afc1-RC_E1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a852afc1-RC_E1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RCMini_L1_TOSCANE\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 1, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/06045081-RC_L1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/06045081-RC_L1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7-2400x1714.webp\"}},\"RCMini_L2_TOSCANE\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 2, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bbce3c4f-RC_L2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bbce3c4f-RC_L2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7-2400x1714.webp\"}},\"RCMini_L3_TOSCANE\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 3, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d770854a-RC_L3_TOSCANE_V3-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d770854a-RC_L3_TOSCANE_V3-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7-2400x1714.webp\"}},\"RCMini_L4_TOSCANE\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 4, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1b2be392-RC_L4_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1b2be392-RC_L4_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7-2400x1714.webp\"}},\"RCMini_P1_TOSCANE\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 1, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e988199b-RC_Paso1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e988199b-RC_Paso1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RCMini_P2_TOSCANE\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 2, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/61e3840e-RC_Paso2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/61e3840e-RC_Paso2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RCMini_P3_TOSCANE\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 3, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e6454f4d-RC_Paso3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e6454f4d-RC_Paso3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RCMini_P4_TOSCANE\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 4, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f4a7aa88-RC_Paso4_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f4a7aa88-RC_Paso4_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RCMini_O1_TOSCANE\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 1, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a65755a-RC_O1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7a65755a-RC_O1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7-2400x1714.webp\"}},\"RCMini_O2_TOSCANE\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 2, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6c097076-RC_O2_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6c097076-RC_O2_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7-2400x1714.webp\"}},\"RCMini_O3_TOSCANE\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 3, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ebafbb35-RC_O3_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ebafbb35-RC_O3_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7-2400x1714.webp\"}},\"RCMini_O4_TOSCANE\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 4, liner Toscane\",\"img_base\":\"Base_RCMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/31250215-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cb3dc77e-RC_O4_TOSCANE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/cb3dc77e-RC_O4_TOSCANE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7-2400x1714.webp\"}},\"RCMini_E1_GRIS\":{\"price\":\"7 824 \\u20ac\",\"name\":\"Mini Romy, Echelle position 1, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d88a779d-RC_E1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/d88a779d-RC_E1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RCMini_L1_GRIS\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 1, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a3c74918-RC_L1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a3c74918-RC_L1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7-2400x1714.webp\"}},\"RCMini_L2_GRIS\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 2, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/48f0f21b-RC_L2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/48f0f21b-RC_L2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7-2400x1714.webp\"}},\"RCMini_L3_GRIS\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 3, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7329925-RC_L3_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7329925-RC_L3_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7-2400x1714.webp\"}},\"RCMini_L4_GRIS\":{\"price\":\"10 244 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 4, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/45ee825c-RC_L4_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/45ee825c-RC_L4_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7-2400x1714.webp\"}},\"RCMini_P1_GRIS\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 1, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7bd40c9c-RC_Paso1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/7bd40c9c-RC_Paso1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RCMini_P2_GRIS\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 2, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c12d4343-RC_Paso2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c12d4343-RC_Paso2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RCMini_P3_GRIS\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 3, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5c22a235-RC_Paso3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5c22a235-RC_Paso3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RCMini_P4_GRIS\":{\"price\":\"9 944 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 4, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9dfdc7d8-RC_Paso4_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9dfdc7d8-RC_Paso4_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RCMini_O1_GRIS\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 1, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3a252f19-RC_O1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3a252f19-RC_O1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7-2400x1714.webp\"}},\"RCMini_O2_GRIS\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 2, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2ddd5c09-RC_O2_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2ddd5c09-RC_O2_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7-2400x1714.webp\"}},\"RCMini_O3_GRIS\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 3, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b0d2bd7f-RC_O3_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b0d2bd7f-RC_O3_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7-2400x1714.webp\"}},\"RCMini_O4_GRIS\":{\"price\":\"9 034 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 4, liner Gris\",\"img_base\":\"Base_RCMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/9bb4700c-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d51f17bf-RC_O4_GRIS_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/d51f17bf-RC_O4_GRIS_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7-2400x1714.webp\"}},\"RCMini_E1_ARDOISE\":{\"price\":\"8 085 \\u20ac\",\"name\":\"Mini Romy, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b60aa8c5-RC_E1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b60aa8c5-RC_E1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RCMini_L1_ARDOISE\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/73d40466-RC_L1_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/73d40466-RC_L1_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7-2400x1714.webp\"}},\"RCMini_L2_ARDOISE\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5a1cb094-RC_L2_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5a1cb094-RC_L2_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7-2400x1714.webp\"}},\"RCMini_L3_ARDOISE\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c91408b5-RC_L3_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c91408b5-RC_L3_ARDOISE_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7-2400x1714.webp\"}},\"RCMini_L4_ARDOISE\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/098dd970-RC_L4_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/098dd970-RC_L4_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7-2400x1714.webp\"}},\"RCMini_P1_ARDOISE\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7d01968-RC_Paso1_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a7d01968-RC_Paso1_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RCMini_P2_ARDOISE\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/63a3efe3-RC_Paso2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/63a3efe3-RC_Paso2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RCMini_P3_ARDOISE\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e40524a0-RC_Paso3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e40524a0-RC_Paso3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RCMini_P4_ARDOISE\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/dd89c47e-RC_Paso4_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/dd89c47e-RC_Paso4_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RCMini_O1_ARDOISE\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/204e5fe2-RC_O1_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/204e5fe2-RC_O1_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7-2400x1714.webp\"}},\"RCMini_O2_ARDOISE\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6e491b9b-RC_O2_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/6e491b9b-RC_O2_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7-2400x1714.webp\"}},\"RCMini_O3_ARDOISE\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e9efd0d8-RC_O3_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e9efd0d8-RC_O3_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7-2400x1714.webp\"}},\"RCMini_O4_ARDOISE\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RCMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1cdde5d6-Base_ARDOISE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c97dac93-RC_O4_ARDOISE_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c97dac93-RC_O4_ARDOISE_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7-2400x1714.webp\"}},\"RCMini_E1_ARGENT\":{\"price\":\"8 085 \\u20ac\",\"name\":\"Mini Romy, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c1adc8b8-RC_E1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c1adc8b8-RC_E1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RCMini_L1_ARGENT\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 1, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/be7f28fd-RC_L1_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/be7f28fd-RC_L1_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7-2400x1714.webp\"}},\"RCMini_L2_ARGENT\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 2, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af024284-RC_L2_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/af024284-RC_L2_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7-2400x1714.webp\"}},\"RCMini_L3_ARGENT\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 3, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16f9996c-RC_L3_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/16f9996c-RC_L3_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7-2400x1714.webp\"}},\"RCMini_L4_ARGENT\":{\"price\":\"10 505 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 4, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8df89676-RC_L4_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8df89676-RC_L4_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7-2400x1714.webp\"}},\"RCMini_P1_ARGENT\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 1, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0152c49e-RC_Paso1_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0152c49e-RC_Paso1_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RCMini_P2_ARGENT\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 2, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4d89d561-RC_Paso2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/4d89d561-RC_Paso2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RCMini_P3_ARGENT\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 3, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e3e144f0-RC_Paso3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/e3e144f0-RC_Paso3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RCMini_P4_ARGENT\":{\"price\":\"10 205 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 4, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32d57a15-RC_Paso4_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32d57a15-RC_Paso4_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RCMini_O1_ARGENT\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 1, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/97b79c0f-RC_O1_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/97b79c0f-RC_O1_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7-2400x1714.webp\"}},\"RCMini_O2_ARGENT\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 2, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ca1793eb-RC_O2_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ca1793eb-RC_O2_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7-2400x1714.webp\"}},\"RCMini_O3_ARGENT\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 3, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/647f027a-RC_O3_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/647f027a-RC_O3_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7-2400x1714.webp\"}},\"RCMini_O4_ARGENT\":{\"price\":\"9 295 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 4, liner Gris Argent\",\"img_base\":\"Base_RCMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/823537fe-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/9986fa0f-RC_O4_ARGENT_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/9986fa0f-RC_O4_ARGENT_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7-2400x1714.webp\"}},\"RCMini_E1_BALI\":{\"price\":\"8 260 \\u20ac\",\"name\":\"Mini Romy, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bcc1e13a-RC_E1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/bcc1e13a-RC_E1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RCMini_L1_BALI\":{\"price\":\"10 680 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 1, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c78cdfbf-RC_L1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c78cdfbf-RC_L1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/35c15aae-RC_L1_pos_V7-2400x1714.webp\"}},\"RCMini_L2_BALI\":{\"price\":\"10 680 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 2, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cbb64bc-RC_L2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cbb64bc-RC_L2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/880b3660-RC_L2_pos_V7-2400x1714.webp\"}},\"RCMini_L3_BALI\":{\"price\":\"10 680 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 3, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/729d3893-RC_L3_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/729d3893-RC_L3_BALI_V3-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/559defe5-RC_L3_pos_V7-2400x1714.webp\"}},\"RCMini_L4_BALI\":{\"price\":\"10 680 \\u20ac\",\"name\":\"Mini Romy, Escalier Lobby position 4, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/21a514fb-RC_L4_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/21a514fb-RC_L4_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/28eee9bd-RC_L4_pos_V7-2400x1714.webp\"}},\"RCMini_P1_BALI\":{\"price\":\"10 380 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 1, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c02ded72-RC_Paso1_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c02ded72-RC_Paso1_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/da4d13b4-RC_Paso1_pos_V7-2400x1714.webp\"}},\"RCMini_P2_BALI\":{\"price\":\"10 380 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 2, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b15d9532-RC_Paso2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/b15d9532-RC_Paso2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/67877f7a-RC_Paso2_pos_V7-2400x1714.webp\"}},\"RCMini_P3_BALI\":{\"price\":\"10 380 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 3, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2c527444-RC_Paso3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/2c527444-RC_Paso3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ba11a6ff-RC_Paso3_pos_V7-2400x1714.webp\"}},\"RCMini_P4_BALI\":{\"price\":\"10 380 \\u20ac\",\"name\":\"Mini Romy, Escalier Paso position 4, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/dd025e61-RC_Paso4_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/dd025e61-RC_Paso4_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/c762a0a7-RC_Paso4_pos_V7-2400x1714.webp\"}},\"RCMini_O1_BALI\":{\"price\":\"9 470 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 1, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/53c081b3-RC_O1_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/53c081b3-RC_O1_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/49a07f75-RC_O1_pos_V7-2400x1714.webp\"}},\"RCMini_O2_BALI\":{\"price\":\"9 470 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 2, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5dad8a78-RC_O2_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/5dad8a78-RC_O2_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f46a13bb-RC_O2_pos_V7-2400x1714.webp\"}},\"RCMini_O3_BALI\":{\"price\":\"9 470 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 3, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c0a26b0e-RC_O3_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/c0a26b0e-RC_O3_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29fcca3e-RC_O3_pos_V7-2400x1714.webp\"}},\"RCMini_O4_BALI\":{\"price\":\"9 470 \\u20ac\",\"name\":\"Mini Romy, Escalier Orbis position 4, liner Pierre de Bali\",\"img_base\":\"Base_RCMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/81968e09-Base_BALI_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a56fc1ce-RC_O4_BALI_V5-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/a56fc1ce-RC_O4_BALI_V5-2400x1714.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/548fcc66-RC_O4_pos_V7-2400x1714.webp\"}},\"RB_E1_TOSCANE\":{\"price\":\"9 389 \\u20ac\",\"name\":\"Tina, Echelle position 1, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8a16b866-RB_E1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8a16b866-RB_E1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Eb1_TOSCANE\":{\"price\":\"11 009 \\u20ac\",\"name\":\"Tina, Banc + \\u00e9chelle position 1, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7f79abfc-RB_EB1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7f79abfc-RB_EB1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Pi1_TOSCANE\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 1, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7a45e4e9-RB_P1_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7a45e4e9-RB_P1_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7-2400x1714.webp\"}},\"RB_Pi2_TOSCANE\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 2, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29dfbf6d-RB_P2_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/29dfbf6d-RB_P2_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7-2400x1714.webp\"}},\"RB_Pi3_TOSCANE\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 3, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ae79742e-RB_P3_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ae79742e-RB_P3_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7-2400x1714.webp\"}},\"RB_Pi4_TOSCANE\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 4, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8eeb0865-RB_P4_TOSCANE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8eeb0865-RB_P4_TOSCANE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7-2400x1714.webp\"}},\"RB_S1_TOSCANE\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 1, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/52ffd863-RB_S1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/52ffd863-RB_S1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7-2400x1714.webp\"}},\"RB_S2_TOSCANE\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 2, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ef35b4ad-RB_S2_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ef35b4ad-RB_S2_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7-2400x1714.webp\"}},\"RB_S3_TOSCANE\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 3, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32a36d28-RB_S3_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/32a36d28-RB_S3_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7-2400x1714.webp\"}},\"RB_S4_TOSCANE\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 4, liner Toscane\",\"img_base\":\"Base_RB_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/399123d7-Base_TOSCANE_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4fd06b70-RB_S4_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4fd06b70-RB_S4_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7-2400x1714.webp\"}},\"RB_E1_GRIS\":{\"price\":\"9 389 \\u20ac\",\"name\":\"Tina, Echelle position 1, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1fcbe0b1-RB_E1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/1fcbe0b1-RB_E1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Eb1_GRIS\":{\"price\":\"11 009 \\u20ac\",\"name\":\"Tina, Banc + \\u00e9chelle position 1, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8103b32a-RB_EB1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8103b32a-RB_EB1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Pi1_GRIS\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 1, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5224a005-RB_P1_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5224a005-RB_P1_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7-2400x1714.webp\"}},\"RB_Pi2_GRIS\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 2, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2e4585de-RB_P2_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2e4585de-RB_P2_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7-2400x1714.webp\"}},\"RB_Pi3_GRIS\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 3, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b34a64a8-RB_P3_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/b34a64a8-RB_P3_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7-2400x1714.webp\"}},\"RB_Pi4_GRIS\":{\"price\":\"13 429 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 4, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d687ce68-RB_P4_GRIS_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/d687ce68-RB_P4_GRIS_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7-2400x1714.webp\"}},\"RB_S1_GRIS\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 1, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6a09d962-RB_S1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6a09d962-RB_S1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7-2400x1714.webp\"}},\"RB_S2_GRIS\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 2, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/813e6261-RB_S2_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/813e6261-RB_S2_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7-2400x1714.webp\"}},\"RB_S3_GRIS\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 3, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6efc095f-RB_S3_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6efc095f-RB_S3_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7-2400x1714.webp\"}},\"RB_S4_GRIS\":{\"price\":\"11 919 \\u20ac\",\"name\":\"Tina, Escalier Square position 4, liner Gris\",\"img_base\":\"Base_RB_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/94e713fd-Base_GRIS_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8c201226-RB_S4_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8c201226-RB_S4_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7-2400x1714.webp\"}},\"RB_E1_ARDOISE\":{\"price\":\"9 705 \\u20ac\",\"name\":\"Tina, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8856d38b-RB_E1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/8856d38b-RB_E1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Eb1_ARDOISE\":{\"price\":\"11 325 \\u20ac\",\"name\":\"Tina, Banc + \\u00e9chelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7d39c011-RB_EB1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7d39c011-RB_EB1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Pi1_ARDOISE\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/78058f04-RB_P1_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/78058f04-RB_P1_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7-2400x1714.webp\"}},\"RB_Pi2_ARDOISE\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2b9fd480-RB_P2_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/2b9fd480-RB_P2_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7-2400x1714.webp\"}},\"RB_Pi3_ARDOISE\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ac391fc3-RB_P3_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/ac391fc3-RB_P3_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7-2400x1714.webp\"}},\"RB_Pi4_ARDOISE\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8cab6388-RB_P4_ARDOISE_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/8cab6388-RB_P4_ARDOISE_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7-2400x1714.webp\"}},\"RB_S1_ARDOISE\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4ca7df67-RB_S1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4ca7df67-RB_S1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7-2400x1714.webp\"}},\"RB_S2_ARDOISE\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f16db3a9-RB_S2_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/f16db3a9-RB_S2_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7-2400x1714.webp\"}},\"RB_S3_ARDOISE\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cfb6a2c-RB_S3_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/2cfb6a2c-RB_S3_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7-2400x1714.webp\"}},\"RB_S4_ARDOISE\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RB_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1469c414-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/51886c74-RB_S4_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/51886c74-RB_S4_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7-2400x1714.webp\"}},\"RB_E1_ARGENT\":{\"price\":\"9 705 \\u20ac\",\"name\":\"Tina, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/04b1afde-RB_E1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/04b1afde-RB_E1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Eb1_ARGENT\":{\"price\":\"11 325 \\u20ac\",\"name\":\"Tina, Banc + \\u00e9chelle position 1, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/64666289-RB_EB1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/64666289-RB_EB1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Pi1_ARGENT\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 1, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dd44bb5f-RB_P1_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dd44bb5f-RB_P1_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7-2400x1714.webp\"}},\"RB_Pi2_ARGENT\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 2, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f48c0fad-RB_P2_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/f48c0fad-RB_P2_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7-2400x1714.webp\"}},\"RB_Pi3_ARGENT\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 3, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5ae49e3c-RB_P3_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/5ae49e3c-RB_P3_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7-2400x1714.webp\"}},\"RB_Pi4_ARGENT\":{\"price\":\"13 745 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 4, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a71d6649-RB_P4_ARGENT_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a71d6649-RB_P4_ARGENT_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7-2400x1714.webp\"}},\"RB_S1_ARGENT\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 1, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63e709a6-RB_S1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63e709a6-RB_S1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7-2400x1714.webp\"}},\"RB_S2_ARGENT\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 2, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1479db56-RB_S2_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1479db56-RB_S2_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7-2400x1714.webp\"}},\"RB_S3_ARGENT\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 3, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fdc9739-RB_S3_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8fdc9739-RB_S3_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7-2400x1714.webp\"}},\"RB_S4_ARGENT\":{\"price\":\"12 235 \\u20ac\",\"name\":\"Tina, Escalier Square position 4, liner Gris Argent\",\"img_base\":\"Base_RB_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/5b29d8b3-Base_ARGENT_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb447eb6-RB_S4_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fb447eb6-RB_S4_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7-2400x1714.webp\"}},\"RB_E1_BALI\":{\"price\":\"9 915 \\u20ac\",\"name\":\"Tina, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6fbb36c0-RB_E1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/6fbb36c0-RB_E1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Eb1_BALI\":{\"price\":\"11 535 \\u20ac\",\"name\":\"Tina, Banc + \\u00e9chelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f173655b-RB_EB1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/f173655b-RB_EB1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RB_Pi1_BALI\":{\"price\":\"13 955 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 1, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/073b0951-RB_P1_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/073b0951-RB_P1_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/1d5bf797-RB_P1_pos_V7-2400x1714.webp\"}},\"RB_Pi2_BALI\":{\"price\":\"13 955 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 2, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/baf1659f-RB_P2_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/baf1659f-RB_P2_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a0919b59-RB_P2_pos_V7-2400x1714.webp\"}},\"RB_Pi3_BALI\":{\"price\":\"13 955 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 3, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6767bc1a-RB_P3_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6767bc1a-RB_P3_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7d0742dc-RB_P3_pos_V7-2400x1714.webp\"}},\"RB_Pi4_BALI\":{\"price\":\"13 955 \\u20ac\",\"name\":\"Tina, Banc + marches Piano position 4, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a6f71819-RB_P4_BALI_V7-1800x1286.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/a6f71819-RB_P4_BALI_V7.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/00744484-RB_P4_pos_V7-2400x1714.webp\"}},\"RB_S1_BALI\":{\"price\":\"12 445 \\u20ac\",\"name\":\"Tina, Escalier Square position 1, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0e424fc5-RB_S1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0e424fc5-RB_S1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/613ad24c-RB_S1_pos_V7-2400x1714.webp\"}},\"RB_S2_BALI\":{\"price\":\"12 445 \\u20ac\",\"name\":\"Tina, Escalier Square position 2, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e575f4c6-RB_S2_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e575f4c6-RB_S2_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/dcf0be82-RB_S2_pos_V7-2400x1714.webp\"}},\"RB_S3_BALI\":{\"price\":\"12 445 \\u20ac\",\"name\":\"Tina, Escalier Square position 3, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0ab79ff8-RB_S3_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/0ab79ff8-RB_S3_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/01666707-RB_S3_pos_V7-2400x1714.webp\"}},\"RB_S4_BALI\":{\"price\":\"12 445 \\u20ac\",\"name\":\"Tina, Escalier Square position 4, liner Pierre de Bali\",\"img_base\":\"Base_RB_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8ec5edf8-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e86b8481-RB_S4_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e86b8481-RB_S4_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/7c15615f-RB_S4_pos_V7-2400x1714.webp\"}},\"RBMini_E1_TOSCANE\":{\"price\":\"7 975 \\u20ac\",\"name\":\"Mini Tina, Echelle position 1, liner Toscane\",\"img_base\":\"Base_RBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3425e962-RB_E1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3425e962-RB_E1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Eb1_TOSCANE\":{\"price\":\"9 595 \\u20ac\",\"name\":\"Mini Tina, Banc + \\u00e9chelle position 1, liner Toscane\",\"img_base\":\"Base_RBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/78aa5cb4-RB_EB1_TOSCANE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/78aa5cb4-RB_EB1_TOSCANE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Pi1_TOSCANE\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 1, liner Toscane\",\"img_base\":\"Base_RBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a9693d14-RB_P1_TOSCANE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a9693d14-RB_P1_TOSCANE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7-2400x1714.webp\"}},\"RBMini_Pi2_TOSCANE\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 2, liner Toscane\",\"img_base\":\"Base_RBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6f6c25ec-RB_P2_TOSCANE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6f6c25ec-RB_P2_TOSCANE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7-2400x1714.webp\"}},\"RBMini_Pi3_TOSCANE\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 3, liner Toscane\",\"img_base\":\"Base_RBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c104b47d-RB_P3_TOSCANE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/c104b47d-RB_P3_TOSCANE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7-2400x1714.webp\"}},\"RBMini_Pi4_TOSCANE\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 4, liner Toscane\",\"img_base\":\"Base_RBMini_TOSCANE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/a0479575-Base_TOSCANE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3cfd4c08-RB_P4_TOSCANE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3cfd4c08-RB_P4_TOSCANE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7-2400x1714.webp\"}},\"RBMini_E1_GRIS\":{\"price\":\"7 975 \\u20ac\",\"name\":\"Mini Tina, Echelle position 1, liner Gris\",\"img_base\":\"Base_RBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c02cf8b2-RB_E1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/c02cf8b2-RB_E1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Eb1_GRIS\":{\"price\":\"9 595 \\u20ac\",\"name\":\"Mini Tina, Banc + \\u00e9chelle position 1, liner Gris\",\"img_base\":\"Base_RBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/18d50588-RB_EB1_GRIS_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/18d50588-RB_EB1_GRIS_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Pi1_GRIS\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 1, liner Gris\",\"img_base\":\"Base_RBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e19f8b37-RB_P1_GRIS-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e19f8b37-RB_P1_GRIS-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7-2400x1714.webp\"}},\"RBMini_Pi2_GRIS\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 2, liner Gris\",\"img_base\":\"Base_RBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/27245b36-RB_P2_GRIS_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/27245b36-RB_P2_GRIS_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7-2400x1714.webp\"}},\"RBMini_Pi3_GRIS\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 3, liner Gris\",\"img_base\":\"Base_RBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fab282b3-RB_P3_GRIS_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/fab282b3-RB_P3_GRIS_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7-2400x1714.webp\"}},\"RBMini_Pi4_GRIS\":{\"price\":\"12 015 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 4, liner Gris\",\"img_base\":\"Base_RBMini_GRIS\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/6b846d6c-Base_GRIS_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/87c184eb-RB_P4_GRIS_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/87c184eb-RB_P4_GRIS_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7-2400x1714.webp\"}},\"RBMini_E1_ARDOISE\":{\"price\":\"8 211 \\u20ac\",\"name\":\"Mini Tina, Echelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3665828f-RB_E1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3665828f-RB_E1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Eb1_ARDOISE\":{\"price\":\"9 831 \\u20ac\",\"name\":\"Mini Tina, Banc + \\u00e9chelle position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7aea3759-RB_EB1_ARDOISE_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/7aea3759-RB_EB1_ARDOISE_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Pi1_ARDOISE\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 1, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b7313a10-RB_P1_ARDOISE-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b7313a10-RB_P1_ARDOISE-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7-2400x1714.webp\"}},\"RBMini_Pi2_ARDOISE\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 2, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4294c22f-RB_P2_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/4294c22f-RB_P2_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7-2400x1714.webp\"}},\"RBMini_Pi3_ARDOISE\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 3, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ecfc53be-RB_P3_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/ecfc53be-RB_P3_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7-2400x1714.webp\"}},\"RBMini_Pi4_ARDOISE\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 4, liner Marbr\\u00e9 Ardoise\",\"img_base\":\"Base_RBMini_ARDOISE\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/8dbf72b6-Base_ARDOISE_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1105abcb-RB_P4_ARDOISE_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/1105abcb-RB_P4_ARDOISE_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7-2400x1714.webp\"}},\"RBMini_E1_ARGENT\":{\"price\":\"8 211 \\u20ac\",\"name\":\"Mini Tina, Echelle position 1, liner Gris Argent\",\"img_base\":\"Base_RBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3cf0bbac-RB_E1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/3cf0bbac-RB_E1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Eb1_ARGENT\":{\"price\":\"9 831 \\u20ac\",\"name\":\"Mini Tina, Banc + \\u00e9chelle position 1, liner Gris Argent\",\"img_base\":\"Base_RBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/da55338d-RB_EB1_ARGENT_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/da55338d-RB_EB1_ARGENT_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Pi1_ARGENT\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 1, liner Gris Argent\",\"img_base\":\"Base_RBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/214e1bf9-RB_P1_ARGENT-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/214e1bf9-RB_P1_ARGENT-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7-2400x1714.webp\"}},\"RBMini_Pi2_ARGENT\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 2, liner Gris Argent\",\"img_base\":\"Base_RBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/90378e53-RB_P2_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/90378e53-RB_P2_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7-2400x1714.webp\"}},\"RBMini_Pi3_ARGENT\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 3, liner Gris Argent\",\"img_base\":\"Base_RBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/29cc55bb-RB_P3_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/29cc55bb-RB_P3_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7-2400x1714.webp\"}},\"RBMini_Pi4_ARGENT\":{\"price\":\"12 251 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 4, liner Gris Argent\",\"img_base\":\"Base_RBMini_ARGENT\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/84cec0b0-Base_ARGENT_V3.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b2cd5aa1-RB_P4_ARGENT_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/b2cd5aa1-RB_P4_ARGENT_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7-2400x1714.webp\"}},\"RBMini_E1_BALI\":{\"price\":\"8 368 \\u20ac\",\"name\":\"Mini Tina, Echelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_RBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b05c2ec3-RB_E1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/b05c2ec3-RB_E1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Eb1_BALI\":{\"price\":\"9 988 \\u20ac\",\"name\":\"Mini Tina, Banc + \\u00e9chelle position 1, liner Pierre de Bali\",\"img_base\":\"Base_RBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/68a5d3f9-RB_EB1_BALI_V9.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/68a5d3f9-RB_EB1_BALI_V9.webp\"},\"pos_others_url\":{\"container\":\".webp\",\"modal\":\".webp\"}},\"RBMini_Pi1_BALI\":{\"price\":\"12 408 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 1, liner Pierre de Bali\",\"img_base\":\"Base_RBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d41d90-RB_P1_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/85d41d90-RB_P1_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/9aac373b-RB_P1_pos_V7-2400x1714.webp\"}},\"RBMini_Pi2_BALI\":{\"price\":\"12 408 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 2, liner Pierre de Bali\",\"img_base\":\"Base_RBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3d06a533-RB_P2_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/3d06a533-RB_P2_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/27665bf5-RB_P2_pos_V7-2400x1714.webp\"}},\"RBMini_Pi3_BALI\":{\"price\":\"12 408 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 3, liner Pierre de Bali\",\"img_base\":\"Base_RBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e0907cb6-RB_P3_BALI_V2-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/e0907cb6-RB_P3_BALI_V2-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/faf08270-RB_P3_pos_V7-2400x1714.webp\"}},\"RBMini_Pi4_BALI\":{\"price\":\"12 408 \\u20ac\",\"name\":\"Mini Tina, Banc + marches Piano position 4, liner Pierre de Bali\",\"img_base\":\"Base_RBMini_BALI\",\"liner_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/71a69369-Base_BALI_V3-2400x1714.png.webp\"},\"pos_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63fdd6d4-RB_P4_BALI-1800x1286.png.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/webp-express\\\/webp-images\\\/uploads\\\/2025\\\/12\\\/63fdd6d4-RB_P4_BALI-2400x1714.png.webp\"},\"pos_others_url\":{\"container\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7.webp\",\"modal\":\"https:\\\/\\\/www.waterair.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/87838428-RB_P4_pos_V7-2400x1714.webp\"}}};\n<\/script>\n\t<\/div>\n\n<div  class=\"block-content-media  content-block   \">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                            <h2 data-wa=\"fade-up\" class=\"content-block__title h2 mb-3 \">Alege\u021bi forma piscinei<\/h2>\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p><!-- wp:heading --><\/p>\n<p><strong>Gr\u0103dina dumneavoastr\u0103 este unic\u0103, piscina, de asemenea!<\/strong>Piscinele Waterair sunt disponibile \u00een numeroase dimensiuni \u0219i forme pentru a se potrivi terenului, dorin\u021belor \u0219i bugetului dvs. Testa\u021bi diferitele noastre configura\u021bii &#8211; <a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/piscine\/dreptunghi\">dreptunghiular\u0103<\/a>, <a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/piscine\/bob-de-fasole\">bob de fasole<\/a> sau<a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/piscine\/ovale\"> oval\u0103<\/a> &#8211; \u0219i <strong>imagina\u021bi-v\u0103 piscina ideal\u0103<\/strong>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  \">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1340\" height=\"1260\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-mini-olivia-1-1340x1260.jpg\" class=\"attachment-card_large_2x size-card_large_2x\" alt=\"Petite piscine Olivia mini avec terrasse bois\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-mini-olivia-1-1340x1260.jpg 1340w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-mini-olivia-1-670x630.jpg 670w\" sizes=\"auto, (max-width: 1340px) 100vw, 1340px\" \/>                                                                                    <\/span>\n                                                                                                                <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                            <title>Petite piscine Olivia mini avec terrasse bois<\/title>\n                                            <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                            <!--<image-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tx=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\ty=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\twidth=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\theight=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\txlink:href=\"--><? \/\/= $media['image']['sizes']['card_large_2x'] \n                                                                                                        ?>\n                                            <!--\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tclip-path=\"url(#content-block__mask---><? \/\/= $blockId \n                                                                                                                                ?>\n                                            <!--)\"-->\n                                            <!--\t\t\t\t\t\t\t\t\/>-->\n                                            <!--\t\t\t\t\t\t\t\t<clipPath id=\"content-block__mask---><? \/\/= $blockId \n                                                                                                                        ?>\n                                            <!--\" class=\"content-block__mask\">-->\n                                            <!--\t\t\t\t\t\t\t\t\t<path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>-->\n                                            <!--\t\t\t\t\t\t\t\t<\/clipPath>-->\n\n                                        <\/svg>\n                                    \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <h2>Configura\u021bi amplasamentul sc\u0103rii<\/h2>\n<p>Indiferent dac\u0103 scara este integrat\u0103 sau pozi\u021bionat\u0103 \u00een exteriorul bazinului, pute\u021bi alege <strong>amplasamentul <a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/echipamente\/scari\">sc\u0103rii<\/a> dup\u0103 cum dori\u021bi<\/strong>. Cu Piscines Waterair, alege\u021bi unghiul din care v\u0103 dori\u021bi s\u0103 privi\u021bi. Cu fa\u021ba spre apus sau spre teras\u0103, imagina\u021bi-v\u0103 spa\u021biul de destindere \u0219i <strong>spune\u021bi-v\u0103 c\u0103 totul este posibil<\/strong>!<\/p>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-3  \">\n                                <div class=\"content-block__media   \">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1340\" height=\"1260\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/escalier-integre-square-1340x1260.jpg\" class=\"attachment-card_large_2x size-card_large_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/escalier-integre-square-1340x1260.jpg 1340w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/escalier-integre-square-670x630.jpg 670w\" sizes=\"auto, (max-width: 1340px) 100vw, 1340px\" \/>                                                                                    <\/span>\n                                                                                                                <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                            <title><\/title>\n                                            <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                            <!--<image-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tx=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\ty=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\twidth=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\theight=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\txlink:href=\"--><? \/\/= $media['image']['sizes']['card_large_2x'] \n                                                                                                        ?>\n                                            <!--\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tclip-path=\"url(#content-block__mask---><? \/\/= $blockId \n                                                                                                                                ?>\n                                            <!--)\"-->\n                                            <!--\t\t\t\t\t\t\t\t\/>-->\n                                            <!--\t\t\t\t\t\t\t\t<clipPath id=\"content-block__mask---><? \/\/= $blockId \n                                                                                                                        ?>\n                                            <!--\" class=\"content-block__mask\">-->\n                                            <!--\t\t\t\t\t\t\t\t\t<path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>-->\n                                            <!--\t\t\t\t\t\t\t\t<\/clipPath>-->\n\n                                        <\/svg>\n                                    \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<div  class=\"block-content-media  content-block   has-no-title\">\n            <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col\">\n                    <div class=\"row flex-column flex-md-row \">\n                        <div class=\"content-block__col col-lg-6 col-xl-7 d-flex flex-column align-items-md-start order-lg-2\">\n                                                                                                                                                <div data-wa=\"fade-up\" data-wa-delay=\"400\" class=\"content-block__description text--sm text-weight--300 mb-0\">\n                                    <p><!-- wp:heading --><\/p>\n<h2>Configura\u021bi liner-ul piscinei<\/h2>\n<p><!-- \/wp:heading --><\/p>\n<p>Nuan\u021ba liner-ului este cea care va da <strong>culoarea apei din piscin\u0103 \u0219i ambian\u021ba dorit\u0103<\/strong>:<\/p>\n<ul>\n<li><a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/echipamente\/acoperire-liner-de-piscina\/liner-toscane\"><strong>Toscan :<\/strong><\/a> o ap\u0103 de culoare turcoaz, \u00een nuan\u021bele M\u0103rii Caraibilor<\/li>\n<li><a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/echipamente\/acoperire-liner-de-piscina\/liner-bleu-azur\"><strong>Azur :<\/strong><\/a> deschis la culoare \u0219i u\u0219or alb\u0103strui, pentru reflexe intense<\/li>\n<li><a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/echipamente\/acoperire-liner-de-piscina\/liner-gri\"><strong>Gri : <\/strong><\/a> o culoare modern\u0103 \u0219i contemporan\u0103 ce confer\u0103 discre\u021bie \u0219i elegan\u021b\u0103 piscinei<\/li>\n<li><a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/echipamente\/acoperire-liner-de-piscina\/liner-gri-argintiu\"><strong>Gri argintiu : <\/strong><\/a> un gri luminos pentru efecte sc\u00e2nteietoare<\/li>\n<li><a href=\"https:\/\/www.waterair.com\/ro\/piscine-si-echipamente\/echipamente\/acoperire-liner-de-piscina\/liner-marmorat-ardezie\"><strong>Marmorat tip ardezie : <\/strong><\/a>o ad\u00e2ncime intens\u0103 \u0219i un efect de oglind\u0103 pentru o piscin\u0103 rafinat\u0103<\/li>\n<\/ul>\n                                <\/div>\n                                                                                        <div data-wa=\"fade-up\" data-wa-delay=\"500\">\n                                                                    <\/div>\n                                                    <\/div>\n                                                                                <div class=\"content-block__col content-block__col--media col-lg-6 col-xl-5 order-lg-1  \">\n                                <div class=\"content-block__media is-left  \">\n                                    \n                                                                            <span data-wa=\"image\">\n                                                                                            <img loading=\"lazy\" decoding=\"async\" width=\"1340\" height=\"1260\" src=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/liner-piscine-gris-1-1340x1260.jpg\" class=\"attachment-card_large_2x size-card_large_2x\" alt=\"\" srcset=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/liner-piscine-gris-1-1340x1260.jpg 1340w, https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/liner-piscine-gris-1-670x630.jpg 670w\" sizes=\"auto, (max-width: 1340px) 100vw, 1340px\" \/>                                                                                    <\/span>\n                                                                                                                <svg class=\"content-block__svg\" viewBox=\"0 0 1000 1000\" aria-labelledby=\"title\">\n                                            <title><\/title>\n                                            <path class=\"content-block__blob\" fill=\"currentColor\" opacity=\".2\" data-blob='{\"minRadius\": \"470\"}'><\/path>\n                                            <!--<image-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tx=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\ty=\"0\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\twidth=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\theight=\"100%\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\txlink:href=\"--><? \/\/= $media['image']['sizes']['card_large_2x'] \n                                                                                                        ?>\n                                            <!--\"-->\n                                            <!--\t\t\t\t\t\t\t\t\t\tclip-path=\"url(#content-block__mask---><? \/\/= $blockId \n                                                                                                                                ?>\n                                            <!--)\"-->\n                                            <!--\t\t\t\t\t\t\t\t\/>-->\n                                            <!--\t\t\t\t\t\t\t\t<clipPath id=\"content-block__mask---><? \/\/= $blockId \n                                                                                                                        ?>\n                                            <!--\" class=\"content-block__mask\">-->\n                                            <!--\t\t\t\t\t\t\t\t\t<path class=\"content-block__blob\" data-blob='{\"minRadius\": \"440\",\"maxRadius\": \"490\"}'><\/path>-->\n                                            <!--\t\t\t\t\t\t\t\t<\/clipPath>-->\n\n                                        <\/svg>\n                                    \n                                <\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>Cere\u021bi un deviz gratuit \u0219i personalizat<\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_DEVI\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"a12b41798d\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/ro\/wp-json\/wp\/v2\/pages\/112906\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Nume                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Prenume                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Cod po\u0219tal                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off709650\"\n                         required='required'                                                                        maxlength=\"6\"\n                        pattern=\"^[0-9]{6}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Ora\u0219                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off535334\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u0102\u00c2\u00ce\u0218\u021a\u015e\u0162\u0103\u00e2\u00ee\u0219\u021b\u015f\u0163()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Num\u0103r \u0219i adres\u0103                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off546856\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u0102\u00c2\u00ce\u0218\u021a\u015e\u0162\u0103\u00e2\u00ee\u0219\u021b\u015f\u0163()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"ro\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Telefon                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"The telephone number must be at least 6 characters long.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 \">Cum dori\u021bi s\u0103 primi\u021bi catalogul? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format \">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Prin po\u0219t\u0103, la domiciliu<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>Prin e-mail, \u00een format digital<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Adresa pentru proiectul meu<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            Adresa pentru proiectul meu este identic\u0103 cu adresa personal\u0103        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">Da<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Nu<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Cod po\u0219tal                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off494425\"\n                                                                                                maxlength=\"6\"\n                        pattern=\"^[0-9]{6}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Ora\u0219                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off530582\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z \u0102\u00c2\u00ce\u0218\u021a\u015e\u0162\u0103\u00e2\u00ee\u0219\u021b\u015f\u0163()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Num\u0103r \u0219i adres\u0103                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off127337\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u0102\u00c2\u00ce\u0218\u021a\u015e\u0162\u0103\u00e2\u00ee\u0219\u021b\u015f\u0163()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"ro\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"ROUMANIE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Nume                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Prenume                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Cod po\u0219tal                    <\/label>\n        <input\n            autocomplete=\"off673093\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off115285\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Num\u0103r \u0219i adres\u0103                    <\/label>\n        <input\n            autocomplete=\"off330376\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off832125\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Ora\u0219                    <\/label>\n        <input\n            autocomplete=\"off331887\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off514337\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Telefon                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"The telephone number must be at least 6 characters long.\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Cod client Waterair                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Da<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Nu<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Autorizez societatea Waterair s\u0103-mi trimit\u0103 pre\u021burile, catalogul digital \u0219i promo\u021biile :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">prin e-mail<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">prin SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Detaliile dvs. sunt transferate la distribuitorul exclusiv Piscine Waterair din \u021bara dvs.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Am primit recomandare de la un prieten<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"ro\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"1\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Trimite\u021bi cererea<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">C\u00e2mpurile marcate cu * sunt obligatorii<br \/>\r\nDatele dvs. personale vor fi colectate de grupul Waterair \u00een urma transmiterii acestei solicit\u0103ri. Pentru mai multe informa\u021bii, consulta\u021bi politica noastr\u0103 de confiden\u021bialitate, disponibil\u0103 \u00een subsolul website-ului nostru.<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\n<div class=\"container block--core-paragraph\"><div class=\"row\"><div class=\"col-12 \">\n<p><\/p>\n<\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii. Alege\u021bi scara \u0219i pozi\u021bia acesteia, alege\u021bi liner-ul, personaliza\u021bi-v\u0103 piscina \u0219i face\u021bi-v\u0103 o idee despre modul \u00een care va ar\u0103ta.<\/p>\n","protected":false},"author":10,"featured_media":100988,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-112906","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Configura\u021bi-v\u0103 piscina | Piscine Waterair<\/title>\n<meta name=\"description\" content=\"Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Configura\u021bi-v\u0103 piscina\" \/>\n<meta property=\"og:description\" content=\"Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina\" \/>\n<meta property=\"og:site_name\" content=\"Piscine Waterair\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina\",\"url\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina\",\"name\":\"Configura\u021bi-v\u0103 piscina | Piscine Waterair\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg\",\"datePublished\":\"2022-01-21T09:50:12+00:00\",\"description\":\"Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg\",\"width\":1920,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Acas\u0103\",\"item\":\"https:\/\/www.waterair.com\/ro\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Configura\u021bi-v\u0103 piscina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/ro\/#website\",\"url\":\"https:\/\/www.waterair.com\/ro\/\",\"name\":\"Piscine Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Configura\u021bi-v\u0103 piscina | Piscine Waterair","description":"Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina","og_locale":"ro_RO","og_type":"article","og_title":"Configura\u021bi-v\u0103 piscina","og_description":"Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii.","og_url":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina","og_site_name":"Piscine Waterair","og_image":[{"width":1920,"height":400,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"1 minut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina","url":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina","name":"Configura\u021bi-v\u0103 piscina | Piscine Waterair","isPartOf":{"@id":"https:\/\/www.waterair.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg","datePublished":"2022-01-21T09:50:12+00:00","description":"Cu ajutorul dispozitivului nostru de configurare, descoperi\u021bi modelele de piscin\u0103 cu forme rectangulare, ovale, sau bob de fasole \u0219i simula\u021bi diferite configura\u021bii.","breadcrumb":{"@id":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/ro\/configurati-va-piscina"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/12\/piscine-rectangle-emilie-2-jour-1.jpg","width":1920,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/ro\/configurati-va-piscina#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Acas\u0103","item":"https:\/\/www.waterair.com\/ro"},{"@type":"ListItem","position":2,"name":"Configura\u021bi-v\u0103 piscina"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/ro\/#website","url":"https:\/\/www.waterair.com\/ro\/","name":"Piscine Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/pages\/112906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/comments?post=112906"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/pages\/112906\/revisions"}],"predecessor-version":[{"id":112926,"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/pages\/112906\/revisions\/112926"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/media\/100988"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/ro\/wp-json\/wp\/v2\/media?parent=112906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}