{"id":60781,"date":"2021-11-03T19:43:56","date_gmt":"2021-11-03T18:43:56","guid":{"rendered":"https:\/\/waterair-preprod2.adipso.fr\/lokalny-partner"},"modified":"2022-11-04T14:16:19","modified_gmt":"2022-11-04T13:16:19","slug":"lokalny-partner","status":"publish","type":"page","link":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner","title":{"rendered":"Partner v bl\u00edzkosti"},"content":{"rendered":"<div data-wa=\"fade-up\"  class=\"block-text-map  dots-absolute bg-primary content-block\">\n            <div class=\"container pt-10 pb-10\">\n            <div class=\"row pt-0 pb-0 pt-sm-6 pb-sm-6\">\n                <div class=\"col-12 col-md-5\">\n                                            <h2 class=\"block-text-map__title h3 c-white\">\n                            AMAX Group s.r.o.                         <\/h2>\n                                                                                    <div class=\"block-text-map__description c-white mt-2\">\n                            <p><a style=\"color: white;\" href=\"mailto:waterair@amaxgroup.sk\">waterair@amaxgroup.sk<\/a><\/p>\n                        <\/div>\n                    \n                                            <div class=\"block-text-map__phones mt-3\">\n                                                            <div class=\"block-text-map__phone d-flex align-items-center spaced-2 \">\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\">\n    <path fill=\"#00B5ED\" d=\"M10.28241,13.7183981 C8.37355624,11.8094127 7.94254698,9.90042724 7.8453113,9.13559167 C7.81814068,8.92411264 7.89091142,8.71203056 8.04219632,8.56179258 L9.58693349,7.01763855 C9.81416626,6.79053045 9.85449124,6.43658973 9.68416918,6.16418137 L7.22465797,2.34483118 C7.03622634,2.04318964 6.6493253,1.93432422 6.33126199,2.09344925 L2.38287242,3.95312382 C2.12566638,4.07978307 1.97438137,4.35307767 2.00358427,4.63830338 C2.21046871,6.60384113 3.06731511,11.4356157 7.81531305,16.1842859 C12.563311,20.9329561 17.3940627,21.7895168 19.3604993,21.9964155 C19.6457054,22.0256204 19.9189811,21.874325 20.0456316,21.6171012 L21.905178,17.6684393 C22.0636965,17.3510403 21.9555592,16.9651498 21.6551926,16.776361 L17.8361058,14.3173699 C17.5638714,14.1468581 17.2099712,14.1868981 16.9827075,14.4139226 L15.4386599,15.9587663 C15.2884323,16.1100616 15.0763649,16.1828374 14.8649004,16.1556649 C14.1001176,16.0584225 12.1912638,15.6273835 10.28241,13.7183981 Z\"\/>\n    <path fill=\"#00B5ED\" d=\"M17.8623112,12.6897667 C17.4814474,12.6897667 17.1726964,12.3809943 17.1726964,12.0001043 C17.169466,9.14476846 14.8557243,6.83086711 12.0005853,6.82763656 C11.6197216,6.82763656 11.3109705,6.51886421 11.3109705,6.1379742 C11.3109705,5.75708419 11.6197216,5.44831183 12.0005853,5.44831183 C15.6171366,5.45230273 18.5479353,8.38330362 18.551926,12.0001043 C18.551926,12.3809943 18.2431749,12.6897667 17.8623112,12.6897667 Z\"\/>\n    <path fill=\"#00B5ED\" d=\"M21.3103852,12.6897667 C20.9295215,12.6897667 20.6207704,12.3809943 20.6207704,12.0001043 C20.6154497,7.24118502 16.7591764,3.38464579 12.0005853,3.37932473 C11.6197216,3.37932473 11.3109705,3.07055237 11.3109705,2.68966237 C11.3109705,2.30877236 11.6197216,2 12.0005853,2 C17.5205888,2.0060814 21.993919,6.47972018 22,12.0001043 C22,12.1830141 21.9273444,12.3584325 21.7980165,12.4877693 C21.6686886,12.617106 21.4932824,12.6897667 21.3103852,12.6897667 Z\"\/>\n<\/svg>\n                                    <a href=\"tel:0907965140\" class=\"h7 c-white\">0907965140<\/a>\n                                <\/div>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"block-text-map__map block-text-map__map--iframe\">\n                            <iframe src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d2660.076683973089!2d17.16285311550704!3d48.18587397922733!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x476c8f7cb871909d%3A0xb369c96005c46474!2sStar%C3%A1%20Vajnorsk%C3%A1%204%2C%20831%2004%20Bratislava%2C%20Slovaquie!5e0!3m2!1sfr!2sfr!4v1667567760083!5m2!1sfr!2sfr\" width=\"600\" height=\"450\" style=\"border:0;\" allowfullscreen=\"\" loading=\"lazy\" referrerpolicy=\"no-referrer-when-downgrade\"><\/iframe>                    <\/div>\n            <\/div>\n\n\n    <div id=\"block-mini-form\" class=\"block-mini-form content-block bg-primary c-white pt-10 pb-10\" >\n        <div class=\"container\">\n                            <div class=\"row\">\n                    <div class=\"col-12 col-lg-8 offset-lg-2\">\n                        <h2 data-wa=\"fade-up\" class=\"block-mini-form__title text-center h3 c-white\">\n                            <p>Vy\u017eiadajte si bezplatn\u00fa cenov\u00fa a personalizovan\u00fa ponuku<\/p>\n                        <\/h2>\n                    <\/div>\n                <\/div>\n                                    <div data-wa=\"fade-up\" data-wa-delay=\"200\">\n                <div data-wa=\"fade-up\" data-code-action=\"DMD_DEVI\" data-source-form-coupon=\"catalogue-mini-form\">\n    <form id=\"catalogue-mini-form\" action=\"#catalogue-mini-form\" method=\"post\" class=\"adipso-form js-validation-form c-white pt-3\" enctype=\"multipart\/form-data\">\n\t\n\t<input type=\"hidden\" id=\"adipso_form_nonce\" name=\"adipso_form_nonce\" value=\"8b0be60f03\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/sk\/wp-json\/wp\/v2\/pages\/60781\" \/>\t<input type=\"hidden\" name=\"action\" value=\"adipso-form-catalogue-mini-form\" \/>\n\n\t\t\t<div class=\"adipso-form__pot\">\n\t\t\t<label for=\"username\"><\/label><input type=\"text\" id=\"username\" name=\"username\" autocomplete=\"off\" tabindex=\"-1\" \/><label for=\"email\"><\/label><input type=\"email\" id=\"email\" name=\"email\" autocomplete=\"off\" tabindex=\"-1\" value=\"leave@thisemail.com\" \/>\t\t<\/div>\n\t\n\t\n\t<div class=\"adipso-form__fields\">\n\t\t<div class=\"adipso-form__layout adipso-form__layout-container personal_address_wrapper row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text adipso-form__field--required adipso-form__field-text--required col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_name\" class=\"adipso-form__field-label adipso-form__field-text-label adipso-form__field-label--required adipso-form__field-text-label--required\">\n            Priezvisko                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_name\"\n            name=\"catalogue-mini-form[name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Meno                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_firstname\"\n            name=\"catalogue-mini-form[firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-cap-address adipso-form__field--required adipso-form__field-cap-address--required align-items-center d-flex flex-column flex-sm-row\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city adipso-form__field-postal-code-city--required adipso-form__field-cap-address-postal-code-city--required\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code adipso-form__field-postal-code--required adipso-form__field-cap-address-postal-code--required\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field adipso-form__field-postal-code-field--required adipso-form__field-cap-address-postal-code-field--required\">\n                <label for=\"catalogue-mini-form_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Po\u0161tov\u00e9 smerovacie \u010d\u00edslo                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_postal_code\"\n                        name=\"catalogue-mini-form[address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off604287\"\n                         required='required'                                                                        maxlength=\"6\"\n                        pattern=\"^[0-9 ]{6}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city adipso-form__field-city--required adipso-form__field-cap-address-city--required\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field adipso-form__field-city-field--required adipso-form__field-cap-address-city-field--required\">\n                <label for=\"catalogue-mini-form_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    Mesto                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_city\"\n                        name=\"catalogue-mini-form[address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off110641\"\n                         required='required'                                                                        maxlength=\"100\"\n                        pattern=\"^[a-zA-Z0-9 \u00c1\u00c4\u010c\u010e\u00c9\u00cd\u0139\u013d\u0147\u00d3\u00d4\u0154\u0160\u0164\u00da\u00dd\u017d\u00e1\u00e4\u010d\u010f\u00e9\u00ed\u013a\u013e\u0148\u00f3\u00f4\u0155\u0161\u0165\u00fa\u00fd\u017e()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines adipso-form__field-lines--required adipso-form__field-cap-address-lines--required\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field adipso-form__field-line-field--required adipso-form__field-cap-address-line-field--required\">\n                <label for=\"catalogue-mini-form_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label adipso-form__field-label--required adipso-form__field-cap-address-label--required\">\n                    \u010c\u00edslo a adresa                                            <span class=\"required\">*<\/span>\n                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input adipso-form__field-input--required adipso-form__field-cap-address-input--required\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_address_line_1\"\n                        name=\"catalogue-mini-form[address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off251038\"\n                         required='required'                                                                        pattern=\"^[a-zA-Z0-9 \u00c1\u00c4\u010c\u010e\u00c9\u00cd\u0139\u013d\u0147\u00d3\u00d4\u0154\u0160\u0164\u00da\u00dd\u017d\u00e1\u00e4\u010d\u010f\u00e9\u00ed\u013a\u013e\u0148\u00f3\u00f4\u0155\u0161\u0165\u00fa\u00fd\u017e()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete adipso-form__field-autocomplete--required adipso-form__field-cap-address-autocomplete--required\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][country_code]\" value=\"SVK\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[address][language]\" value=\"sk\" autocomplete=\"off\" \/>\n<\/div>\n<div class=\"adipso-form__field adipso-form__field-tel adipso-form__field--required adipso-form__field-tel--required col col--large\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label adipso-form__field-label--required adipso-form__field-tel-label--required\">\n            Telef\u00f3n                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_phone\"\n            name=\"catalogue-mini-form[phone]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Telef\u00f3nne \u010d\u00edslo mus\u00ed ma\u0165 aspo\u0148 6 znakov\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-email adipso-form__field--required adipso-form__field-email--required col col--large\">\n\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_email\" class=\"adipso-form__field-label adipso-form__field-email-label adipso-form__field-label--required adipso-form__field-email-label--required\">\n            E-mail                            <span class=\"required\">*<\/span>\n                    <\/label>\n        <input\n            type=\"email\"\n            id=\"catalogue-mini-form_email\"\n            name=\"catalogue-mini-form[email]\"\n            placeholder=\"\"\n            value=\"\"\n             required='required'                                    maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title p mb-5 is-hide\">Ako by ste chceli dost\u00e1va\u0165 svoj katal\u00f3g? * *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios adipso-form__field--required adipso-form__field-radios--required col field-format is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices adipso-form__field-choices--required adipso-form__field-radios-choices--required\">\n                            <label for=\"catalogue-mini-form_catalogue_format_paper\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_paper\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"paper\"\n                                    \/>\n                <span class=\"input-label\"><span class=\"icon-format paper\"><\/span>Po\u0161tou ku mne domov<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_catalogue_format_digital\" class=\"adipso-form__field-choice adipso-form__field-radios-choice adipso-form__field-choice--required adipso-form__field-radios-choice--required ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_catalogue_format_digital\"\n                    name=\"catalogue-mini-form[catalogue_format]\"\n                    value=\"digital\"\n                     checked='checked'                \/>\n                <span class=\"input-label\"><span class=\"icon-format digital\"><\/span>E-mailom v digit\u00e1lnom form\u00e1te<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mw-710\">Adresa m\u00f4jho projektu<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 js-display-field js-display-field--project_address\">\n\n            <p class=\"adipso-form__field-instructions adipso-form__field-radios-instructions\">\n            Adresa m\u00f4jho projektu je identick\u00e1 s moj\u00edm bydliskom        <\/p>\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_second_address_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_non\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"non\"\n                     checked='checked'                \/>\n                <span class=\"input-label\">\u00c1no<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_second_address_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_second_address_oui\"\n                    name=\"catalogue-mini-form[second_address]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">Nie<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container project_address_wrapper is-hide mt-4 mw-710\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-cap-address align-items-center d-flex flex-column flex-sm-row adipso-form__field--required\">\n    <div class=\"row adipso-form__field-postal-code-city adipso-form__field-cap-address-postal-code-city\">\n        <div class=\"col mt-4 adipso-form__field-postal-code adipso-form__field-cap-address-postal-code\">\n            <div class=\"input-wrapper adipso-form__field-postal-code-field adipso-form__field-cap-address-postal-code-field\">\n                <label for=\"catalogue-mini-form_project_address_postal_code\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Po\u0161tov\u00e9 smerovacie \u010d\u00edslo                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_postal_code\"\n                        name=\"catalogue-mini-form[project_address][postal_code]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off922937\"\n                                                                                                maxlength=\"6\"\n                        pattern=\"^[0-9 ]{6}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"postal_code\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n        <div class=\"col mt-4 adipso-form__field-city adipso-form__field-cap-address-city\">\n            <div class=\"input-wrapper adipso-form__field-city-field adipso-form__field-cap-address-city-field\">\n                <label for=\"catalogue-mini-form_project_address_city\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    Mesto                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_city\"\n                        name=\"catalogue-mini-form[project_address][city]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off788146\"\n                                                                                                maxlength=\"100\"\n                        pattern=\"^[a-zA-Z0-9 \u00c1\u00c4\u010c\u010e\u00c9\u00cd\u0139\u013d\u0147\u00d3\u00d4\u0154\u0160\u0164\u00da\u00dd\u017d\u00e1\u00e4\u010d\u010f\u00e9\u00ed\u013a\u013e\u0148\u00f3\u00f4\u0155\u0161\u0165\u00fa\u00fd\u017e()\\-\/\\.,&#039;]{1,100}$\"                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"city\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <div class=\"row adipso-form__field-lines adipso-form__field-cap-address-lines\">\n        <div class=\"col col--large mt-4\">\n            <div class=\"input-wrapper adipso-form__field-line-field adipso-form__field-cap-address-line-field\">\n                <label for=\"catalogue-mini-form_project_address_line_1\" class=\"adipso-form__field-label adipso-form__field-cap-address-label\">\n                    \u010c\u00edslo a adresa                                    <\/label>\n                <div class=\"adipso-form__field-input adipso-form__field-cap-address-input\">\n                    <input\n                        type=\"text\"\n                        id=\"catalogue-mini-form_project_address_line_1\"\n                        name=\"catalogue-mini-form[project_address][line_1]\"\n                        placeholder=\"\"\n                        value=\"\"\n                        autocomplete=\"off761677\"\n                                                                                                pattern=\"^[a-zA-Z0-9 \u00c1\u00c4\u010c\u010e\u00c9\u00cd\u0139\u013d\u0147\u00d3\u00d4\u0154\u0160\u0164\u00da\u00dd\u017d\u00e1\u00e4\u010d\u010f\u00e9\u00ed\u013a\u013e\u0148\u00f3\u00f4\u0155\u0161\u0165\u00fa\u00fd\u017e()\\-\/\\.,&#039;]{1,100}$\"                        maxlength=\"100\"\n                        data-form-name=\"catalogue-mini-form\"\n                        data-field-name=\"project_address\"\n                        data-input-name=\"line_1\"\n                    \/>\n                    <div class=\"adipso-form__field-autocomplete adipso-form__field-cap-address-autocomplete\"><\/div>\n\n                                    <\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][city_id]\" value=\"\" autocomplete=\"off\" \/>\n\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][quality_code]\" value=\"NA\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][country_code]\" value=\"SVK\" autocomplete=\"off\" \/>\n    <input type=\"hidden\" name=\"catalogue-mini-form[project_address][language]\" value=\"sk\" autocomplete=\"off\" \/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[project_country]\"\n\tvalue=\"SLOVAQUIE\"\n\/>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container sponsor2_wrapper is-hide mt-4\">\n\t<div class=\"adipso-form__layout adipso-form__layout-container row form-row\">\n\t<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_name\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Priezvisko                    <\/label>\n        <input\n            autocomplete=\"family-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_name\"\n            name=\"catalogue-mini-form[sponsor_name]\"\n            placeholder=\"\"\n            autocomplete=\"family-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_firstname\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Meno                    <\/label>\n        <input\n            autocomplete=\"given-name\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_firstname\"\n            name=\"catalogue-mini-form[sponsor_firstname]\"\n            placeholder=\"\"\n            autocomplete=\"given-name\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_zip_code\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Po\u0161tov\u00e9 smerovacie \u010d\u00edslo                    <\/label>\n        <input\n            autocomplete=\"off473877\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_zip_code\"\n            name=\"catalogue-mini-form[sponsor_zip_code]\"\n            placeholder=\"\"\n            autocomplete=\"off837319\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_street_address\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            \u010c\u00edslo a adresa                    <\/label>\n        <input\n            autocomplete=\"off714031\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_street_address\"\n            name=\"catalogue-mini-form[sponsor_street_address]\"\n            placeholder=\"\"\n            autocomplete=\"off113693\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_city\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Mesto                    <\/label>\n        <input\n            autocomplete=\"off679963\"            type=\"text\"\n            id=\"catalogue-mini-form_sponsor_city\"\n            name=\"catalogue-mini-form[sponsor_city]\"\n            placeholder=\"\"\n            autocomplete=\"off984107\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-tel col adipso-form__field--required\">\n\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_phone\" class=\"adipso-form__field-label adipso-form__field-tel-label\">\n            Telef\u00f3n                    <\/label>\n        <input\n            type=\"tel\"\n            id=\"catalogue-mini-form_sponsor_phone\"\n            name=\"catalogue-mini-form[sponsor_phone]\"\n            placeholder=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n            pattern=\"[0-9\\(\\)\\s+\\-]{6,}\"    \t\tdata-invalid-message=\"Telef\u00f3nne \u010d\u00edslo mus\u00ed ma\u0165 aspo\u0148 6 znakov\"\n        \/>\n\n            <\/div>\n\n    <\/div>\n<div class=\"adipso-form__field adipso-form__field-text col col--large adipso-form__field--required\">\n    <div class=\"input-wrapper\">\n        <label for=\"catalogue-mini-form_sponsor_client_id\" class=\"adipso-form__field-label adipso-form__field-text-label\">\n            Zadajte Va\u0161e z\u00e1kazn\u00edcke \u010d\u00edslo                    <\/label>\n        <input\n                        type=\"text\"\n            id=\"catalogue-mini-form_sponsor_client_id\"\n            name=\"catalogue-mini-form[sponsor_client_id]\"\n            placeholder=\"\"\n            autocomplete=\"\"\n            value=\"\"\n                                                maxlength=\"\"\n                    \/>\n\n            <\/div>\n\n    <\/div>\n<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Voulez-vous monter votre piscine vous m\u00eame ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_do_it_yourself_oui\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_oui\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"oui\"\n                                    \/>\n                <span class=\"input-label\">\u00c1no<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_non\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_non\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"non\"\n                                    \/>\n                <span class=\"input-label\">Nie<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_do_it_yourself_peut_etre\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_do_it_yourself_peut_etre\"\n                    name=\"catalogue-mini-form[do_it_yourself]\"\n                    value=\"peut_etre\"\n                                    \/>\n                <span class=\"input-label\">Peut-\u00eatre<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"form-title h7 mt-6 mb-5 mw-710 is-hide\">Quand pr\u00e9voyez-vous de d\u00e9marrer ce projet ? *<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-3 mw-710\">\n\t<div class=\"input-radio-wrapper adipso-form__field adipso-form__field-radios col pl-0 pr-0 is-hide\">\n\n    \n    \n    <div class=\"adipso-form__field-choices adipso-form__field-radios-choices\">\n                            <label for=\"catalogue-mini-form_time_limit_maintenant\" class=\"adipso-form__field-choice adipso-form__field-radios-choice \">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_maintenant\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"maintenant\"\n                                    \/>\n                <span class=\"input-label\">Imm\u00e9diatement<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_3_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_3_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_3_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 3 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_dans_6_mois\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_dans_6_mois\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"dans_6_mois\"\n                                    \/>\n                <span class=\"input-label\">Dans les 6 prochains mois<\/span>\n            <\/label>\n                                <label for=\"catalogue-mini-form_time_limit_plus_tard\" class=\"adipso-form__field-choice adipso-form__field-radios-choice ml-3\">\n                <input\n                    type=\"radio\"\n                    id=\"catalogue-mini-form_time_limit_plus_tard\"\n                    name=\"catalogue-mini-form[time_limit]\"\n                    value=\"plus_tard\"\n                                    \/>\n                <span class=\"input-label\">Plus tard<\/span>\n            <\/label>\n                                <\/div>\n\n    <\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container mw-710 mt-6\">\n\t<div class=\"adipso-form__layout adipso-form__layout-html \">\n\t<div class=\"adipso-form__layout-label adipso-form__layout-html-label\">\n\t\t\t<\/div>\n\n\t\t\t<small class=\"adipso-form__layout-instructions adipso-form__layout-html-instructions\">\n\t\t\t<div class=\"p\">Opr\u00e1v\u0148ujem spolo\u010dnos\u0165 Waterair, aby mi posielala ceny, digit\u00e1lny katal\u00f3g a propaga\u010dn\u00e9 akcie :<\/div>\t\t<\/small>\n\t<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales e-mail<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">E-mailom<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Offres commerciales sms<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_commercial_sms_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[commercial_sms][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">SMS<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes adipso-form__field--required adipso-form__field-checkboxes--required col\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label adipso-form__field-label--required adipso-form__field-checkboxes-label--required\"><\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices adipso-form__field-choices--required adipso-form__field-checkboxes-choices--required\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice adipso-form__field-choice--required adipso-form__field-checkboxes-choice--required\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_dealer_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[dealer][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Va\u0161e kontaktn\u00e9 \u00fadaje s\u00fa zaslan\u00e9 n\u00e1\u0161mu v\u00fdhradn\u00e9mu predajcovi Piscines Waterair vo va\u0161ej krajine.<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<div class=\"adipso-form__layout adipso-form__layout-container row mt-2 js-sponsor-container is-hide\">\n\t<div class=\"input-checkbox-wrapper adipso-form__field adipso-form__field-checkboxes col js-display-field js-display-field--sponsor2 js-sponsor-container\">\n\t<div class=\"adipso-form__field-label adipso-form__field-checkboxes-label\">Parrainage<\/div>\n\n\t<div class=\"adipso-form__field-choices adipso-form__field-checkboxes-choices\">\n\t\t\t\t\t<label class=\"adipso-form__field-choice adipso-form__field-checkboxes-choice\">\n\t\t\t\t<input\n\t\t\t\t\ttype=\"checkbox\"\n\t\t\t\t\tid=\"catalogue-mini-form_sponsor_oui\"\n\t\t\t\t\tname=\"catalogue-mini-form[sponsor][]\"\n\t\t\t\t\tvalue=\"oui\"\n\t\t\t\t\t\t\t\t\t\/>\n                <span class=\"input-label\">Poslal me je sponzor<\/span>\n\t\t\t<\/label>\n\t\t\t<\/div>\n\n\t\n\t<\/div>\n<\/div>\n<\/div>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[lang]\"\n\tvalue=\"sk\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[origin]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_origin_notation]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_code]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_finesis_profile_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[scoring_total_score]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[code_action]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[source_form_coupon]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[analytics_type]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[hash_email_sha256]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[commentaire]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[catalogue_num_enable]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[campaign]\"\n\tvalue=\"\"\n\/>\n<input\n\ttype=\"hidden\"\n\tname=\"catalogue-mini-form[cookie_consent_waterair]\"\n\tvalue=\"\"\n\/>\n\t<\/div>\n\n\t<div class=\"adipso-form__submit text-center mt-6\">\n\t\t\t\t<button class=\"btn btn--secondary\" type=\"submit\">Odosla\u0165 \u017eiados\u0165<\/button>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"form-note mt-6\">\n\t\t\t<span style=\"font-size:13px;\">Polia ozna\u010den\u00e9 * s\u00fa povinn\u00e9<br \/>\r\nVa\u0161e osobn\u00e9 \u00fadaje Skupina Waterair zhroma\u017e\u010fuje v r\u00e1mci va\u0161ej \u017eiadosti. Pre \u010fal\u0161ie inform\u00e1cie si, pros\u00edm, pre\u010d\u00edtajte na\u0161u politiku zachov\u00e1vania d\u00f4vernosti dostupn\u00fa v spodnej \u010dasti na\u0161ich internetov\u00fdch str\u00e1nok.<\/span>\t\t<\/div>\n\t\n\t\n\t<\/form>\n<\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":62811,"parent":36865,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"footnotes":""},"class_list":["post-60781","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.4 (Yoast SEO v27.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Predaj baz\u00e9na, v\u00fdrobca baz\u00e9nov Waterair: predaj baz\u00e9nov vo Franc\u00fazsku<\/title>\n<meta name=\"description\" content=\"H\u013ead\u00e1te \u0161pecialistu v oblasti predaja baz\u00e9nov? Waterair, l\u00edder v oblasti v\u00fdroby baz\u00e9nov\u00fdch s\u00faprav je v\u00e1m odteraz k dispoz\u00edcii po celom Franc\u00fazsku!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partner v bl\u00edzkosti\" \/>\n<meta property=\"og:description\" content=\"H\u013ead\u00e1te \u0161pecialistu v oblasti predaja baz\u00e9nov? Waterair, l\u00edder v oblasti v\u00fdroby baz\u00e9nov\u00fdch s\u00faprav je v\u00e1m odteraz k dispoz\u00edcii po celom Franc\u00fazsku!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner\" \/>\n<meta property=\"og:site_name\" content=\"Baz\u00e9ny Waterair\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-04T13:16:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner\",\"url\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner\",\"name\":\"Predaj baz\u00e9na, v\u00fdrobca baz\u00e9nov Waterair: predaj baz\u00e9nov vo Franc\u00fazsku\",\"isPartOf\":{\"@id\":\"https:\/\/www.waterair.com\/sk\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg\",\"datePublished\":\"2021-11-03T18:43:56+00:00\",\"dateModified\":\"2022-11-04T13:16:19+00:00\",\"description\":\"H\u013ead\u00e1te \u0161pecialistu v oblasti predaja baz\u00e9nov? Waterair, l\u00edder v oblasti v\u00fdroby baz\u00e9nov\u00fdch s\u00faprav je v\u00e1m odteraz k dispoz\u00edcii po celom Franc\u00fazsku!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"sk-SK\",\"@id\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#primaryimage\",\"url\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg\",\"contentUrl\":\"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Domov\",\"item\":\"https:\/\/www.waterair.com\/sk\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baz\u00e9ny\u00a0Waterair, eur\u00f3psky l\u00edder v oblasti baz\u00e9nov\u00fdch s\u00faprav u\u017e od roku 1972\",\"item\":\"https:\/\/www.waterair.com\/sk\/skupina\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Partner v bl\u00edzkosti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.waterair.com\/sk\/#website\",\"url\":\"https:\/\/www.waterair.com\/sk\/\",\"name\":\"Baz\u00e9ny Waterair\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.waterair.com\/sk\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Predaj baz\u00e9na, v\u00fdrobca baz\u00e9nov Waterair: predaj baz\u00e9nov vo Franc\u00fazsku","description":"H\u013ead\u00e1te \u0161pecialistu v oblasti predaja baz\u00e9nov? Waterair, l\u00edder v oblasti v\u00fdroby baz\u00e9nov\u00fdch s\u00faprav je v\u00e1m odteraz k dispoz\u00edcii po celom Franc\u00fazsku!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner","og_locale":"sk_SK","og_type":"article","og_title":"Partner v bl\u00edzkosti","og_description":"H\u013ead\u00e1te \u0161pecialistu v oblasti predaja baz\u00e9nov? Waterair, l\u00edder v oblasti v\u00fdroby baz\u00e9nov\u00fdch s\u00faprav je v\u00e1m odteraz k dispoz\u00edcii po celom Franc\u00fazsku!","og_url":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner","og_site_name":"Baz\u00e9ny Waterair","article_modified_time":"2022-11-04T13:16:19+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner","url":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner","name":"Predaj baz\u00e9na, v\u00fdrobca baz\u00e9nov Waterair: predaj baz\u00e9nov vo Franc\u00fazsku","isPartOf":{"@id":"https:\/\/www.waterair.com\/sk\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#primaryimage"},"image":{"@id":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#primaryimage"},"thumbnailUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg","datePublished":"2021-11-03T18:43:56+00:00","dateModified":"2022-11-04T13:16:19+00:00","description":"H\u013ead\u00e1te \u0161pecialistu v oblasti predaja baz\u00e9nov? Waterair, l\u00edder v oblasti v\u00fdroby baz\u00e9nov\u00fdch s\u00faprav je v\u00e1m odteraz k dispoz\u00edcii po celom Franc\u00fazsku!","breadcrumb":{"@id":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner"]}]},{"@type":"ImageObject","inLanguage":"sk-SK","@id":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#primaryimage","url":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg","contentUrl":"https:\/\/www.waterair.com\/wp-content\/uploads\/2021\/11\/piscine-miroir-waterair.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/www.waterair.com\/sk\/skupina\/lokalny-partner#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Domov","item":"https:\/\/www.waterair.com\/sk"},{"@type":"ListItem","position":2,"name":"Baz\u00e9ny\u00a0Waterair, eur\u00f3psky l\u00edder v oblasti baz\u00e9nov\u00fdch s\u00faprav u\u017e od roku 1972","item":"https:\/\/www.waterair.com\/sk\/skupina"},{"@type":"ListItem","position":3,"name":"Partner v bl\u00edzkosti"}]},{"@type":"WebSite","@id":"https:\/\/www.waterair.com\/sk\/#website","url":"https:\/\/www.waterair.com\/sk\/","name":"Baz\u00e9ny Waterair","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.waterair.com\/sk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"}]}},"_links":{"self":[{"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/pages\/60781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/comments?post=60781"}],"version-history":[{"count":5,"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/pages\/60781\/revisions"}],"predecessor-version":[{"id":252740,"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/pages\/60781\/revisions\/252740"}],"up":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/pages\/36865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/media\/62811"}],"wp:attachment":[{"href":"https:\/\/www.waterair.com\/sk\/wp-json\/wp\/v2\/media?parent=60781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}